{"id":2304,"date":"2020-09-17T15:25:01","date_gmt":"2020-09-17T13:25:01","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2304"},"modified":"2020-09-17T15:29:04","modified_gmt":"2020-09-17T13:29:04","slug":"contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/","title":{"rendered":"Contributi alle donne sottoposte a terapia oncologica per l&#8217;acquisto della parrucca. Attuazione dell&#8217;art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020."},"content":{"rendered":"<p>Possono accedere al contributo per l&#8217;acquisto delle parrucche tutte le donne residenti nel Lazio, affette da alopecia conseguita a terapia oncologica.<\/p>\n<div class=\"campoOggetto128\">\n<p>La domanda di contributo va presentata alla ASL di Viterbo entro il <strong>31 Ottobre 2020<\/strong> seguendo le modalit\u00e0 indicate nell&#8217;avviso allegato.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"campoOggetto48\"><\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2312\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/AVVISO-ASL-VT-X-PAR.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/AVVISO-ASL-VT-X-PAR.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO ASL VT X PAR<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Possono accedere al contributo per l&#8217;acquisto delle parrucche tutte le donne residenti nel Lazio, affette da alopecia conseguita a terapia oncologica. La domanda di contributo va presentata alla ASL di [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contributi alle donne sottoposte a terapia oncologica per l&#039;acquisto della parrucca. Attuazione dell&#039;art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020. - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contributi alle donne sottoposte a terapia oncologica per l&#039;acquisto della parrucca. Attuazione dell&#039;art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020. - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Possono accedere al contributo per l&#8217;acquisto delle parrucche tutte le donne residenti nel Lazio, affette da alopecia conseguita a terapia oncologica. La domanda di contributo va presentata alla ASL di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-17T13:25:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-17T13:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/asl1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Contributi alle donne sottoposte a terapia oncologica per l&#8217;acquisto della parrucca. Attuazione dell&#8217;art. 7, commi 77-81 della legge regionale n 28\\\/2019. Legge stabilit\u00e0 regionale 2020.\",\"datePublished\":\"2020-09-17T13:25:01+00:00\",\"dateModified\":\"2020-09-17T13:29:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/\"},\"wordCount\":63,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/09\\\/asl1.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/\",\"name\":\"Contributi alle donne sottoposte a terapia oncologica per l'acquisto della parrucca. Attuazione dell'art. 7, commi 77-81 della legge regionale n 28\\\/2019. Legge stabilit\u00e0 regionale 2020. - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/09\\\/asl1.jpg\",\"datePublished\":\"2020-09-17T13:25:01+00:00\",\"dateModified\":\"2020-09-17T13:29:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/09\\\/asl1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/09\\\/asl1.jpg\",\"width\":1000,\"height\":500,\"caption\":\"ASL Viterbo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/09\\\/17\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contributi alle donne sottoposte a terapia oncologica per l&#8217;acquisto della parrucca. Attuazione dell&#8217;art. 7, commi 77-81 della legge regionale n 28\\\/2019. Legge stabilit\u00e0 regionale 2020.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contributi alle donne sottoposte a terapia oncologica per l'acquisto della parrucca. Attuazione dell'art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020. - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/","og_locale":"it_IT","og_type":"article","og_title":"Contributi alle donne sottoposte a terapia oncologica per l'acquisto della parrucca. Attuazione dell'art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020. - Soriano nel Cimino","og_description":"Possono accedere al contributo per l&#8217;acquisto delle parrucche tutte le donne residenti nel Lazio, affette da alopecia conseguita a terapia oncologica. La domanda di contributo va presentata alla ASL di [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-09-17T13:25:01+00:00","article_modified_time":"2020-09-17T13:29:04+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/asl1.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Contributi alle donne sottoposte a terapia oncologica per l&#8217;acquisto della parrucca. Attuazione dell&#8217;art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020.","datePublished":"2020-09-17T13:25:01+00:00","dateModified":"2020-09-17T13:29:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/"},"wordCount":63,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/asl1.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/","name":"Contributi alle donne sottoposte a terapia oncologica per l'acquisto della parrucca. Attuazione dell'art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020. - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/asl1.jpg","datePublished":"2020-09-17T13:25:01+00:00","dateModified":"2020-09-17T13:29:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/asl1.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/09\/asl1.jpg","width":1000,"height":500,"caption":"ASL Viterbo"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/09\/17\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-attuazione-dellart-7-commi-77-81-della-legge-regionale-n-28-2019-legge-stabilita-regionale-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Contributi alle donne sottoposte a terapia oncologica per l&#8217;acquisto della parrucca. Attuazione dell&#8217;art. 7, commi 77-81 della legge regionale n 28\/2019. Legge stabilit\u00e0 regionale 2020."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2304"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2304\/revisions"}],"predecessor-version":[{"id":2313,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2304\/revisions\/2313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2305"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}