{"id":2459,"date":"2021-01-15T18:13:41","date_gmt":"2021-01-15T17:13:41","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2459"},"modified":"2021-01-15T18:13:41","modified_gmt":"2021-01-15T17:13:41","slug":"emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/","title":{"rendered":"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021"},"content":{"rendered":"<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef1edfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef1edfc\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86e3caf\" data-id=\"86e3caf\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-aa311e0 elementor-widget elementor-widget-text-editor\" data-id=\"aa311e0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>Il presidente del Consiglio\u00a0 ha firmato il nuovo DPCM\u00a0 con le nuove restrizioni anti contagio da Covid 19 che saranno in vigore<b>\u00a0da domani al 5 marzo:<\/b>\u00a0<i>\u00abAi sensi dell\u2019articolo 1 del decreto-legge n. 2 del 2021, dal 16 gennaio 2021 al 15 febbraio 2021 \u00e8 vietato ogni spostamento in entrata e in uscita tra i territori di diverse regioni o province autonome, salvi gli spostamenti motivati da comprovate esigenze lavorative o situazioni di necessit\u00e0 ovvero per motivi di salute. \u00c8 comunque<br \/>\nconsentito il rientro alla propria residenza, domicilio o abitazione\u00bb<\/i>.<\/p>\n<p>Di seguito le nuove regole.<\/p>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-aa08b24 elementor-widget elementor-widget-read-more\" data-id=\"aa08b24\" data-element_type=\"widget\" data-widget_type=\"read-more.default\">\n<div class=\"elementor-widget-container\">\n<div id=\"more-2027\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c67bee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c67bee\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47bdc3a\" data-id=\"47bdc3a\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-d98e8a5 elementor-widget elementor-widget-text-editor\" data-id=\"d98e8a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><b>Scuola, musei e attivit\u00e0 culturali<\/b><\/p>\n<p><b><\/b>&nbsp;<\/p>\n<p>Da luned\u00ec, lezioni in presenza per\u00a0<i>\u00abalmeno il 50% fino a un massimo di 75%\u00bb<\/i>\u00a0degli studenti delle scuole secondarie di primo e secondo grado. \u00abLe istituzioni scolastiche secondarie di secondo grado adottano forme flessibili nell\u2019organizzazione dell\u2019attivit\u00e0 didattica ai sensi degli articoli 4 e 5 del decreto del Presidente della Repubblica 8 marzo 1999, n. 275, in modo che a decorrere dal 18 gennaio 2021, almeno al 50 per cento e fino a un massimo del 75 per cento della popolazione studentesca delle predette istituzioni sia garantita l\u2019attivit\u00e0 didattica in presenza \u2013 si legge nel testo dle decreto -. La restante part dell\u2019attivit\u00e0 didattica \u00e8 svolta tramite il ricorso alla didattica a distanza\u00bb.<br \/>\nIl servizio di apertura al pubblico dei musei e degli altri istituti e luoghi della cultura \u00ab\u00e8 assicurato, dal luned\u00ec al venerd\u00ec\u00bb nelle zone gialle \u00abcon esclusione dei giorni festivi\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Bar e ristoranti<\/b><\/p>\n<p><b>Per i bar l\u2019asporto \u00e8 consentito esclusivamente fino alle ore 18:00<\/b>.<br \/>\nLo prevede il nuovo dpcm in vigore da domani. \u00ab<b>Le attivit\u00e0 dei servizi di ristorazione<\/b>\u00a0(fra cui bar, pub, ristoranti, gelaterie, pasticcerie)\u00a0\u00a0<b>sono consentite dalle ore 5:00 fino alle ore 18:00<\/b>; il consumo al tavolo \u00e8 consentito per un massimo di quattro persone per tavolo, salvo che<br \/>\nsiano tutti conviventi;\u00a0<b>dopo le ore 18,00 \u00e8 vietato il consumo di cibi e bevande nei luoghi pubblici e aperti al pubblico<\/b>; resta\u00a0<b>consentita senza limiti di orario la ristorazione negli alberghi e in altre strutture ricettive limitatamente ai propri clienti, che siano ivi alloggiati<\/b>; resta sempre\u00a0<b>consentita la ristorazione con consegna a domicilio<\/b>\u00a0nel rispetto delle norme igienico-sanitarie sia per l\u2019attivit\u00e0 di confezionamento che di trasporto, nonch\u00e9\u00a0<b>fino alle ore 22:00 la ristorazione con asporto, con divieto di consumazione sul posto o nelle adiacenze<\/b>; per i soggetti che svolgono come attivit\u00e0 prevalente una di quelle identificate dai codici ATECO 56.3 e 47.25 l\u2019asporto \u00e8 consentito esclusivamente fino alle ore 18:00\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Concorsi<\/b><\/p>\n<p><i>\u00ab\u00c8 sospeso lo svolgimento delle prove preselettive e scritte delle procedure concorsuali pubbliche e private e di quelle di abilitazione all\u2019esercizio delle professioni, a esclusione dei casi in cui la valutazione dei candidati sia effettuata esclusivamente su basi curriculari ovvero in modalit\u00e0 telematica, nonch\u00e9 ad esclusione dei concorsi per il personale del servizio sanitario nazionale, ivi compresi, ove richiesti, gli esami di Stato e di abilitazione all\u2019esercizio della professione di medico chirurgo e di quelli per il personale della protezione civile\u00bb<\/i>. \u00abA decorrere dal 15 febbraio 2021 \u2013<br \/>\nsi legge \u2013 sono consentite le prove selettive dei concorsi banditi dalle pubbliche amministrazioni nei casi in cui \u00e8 prevista la partecipazione di un numero di candidati non superiore a trenta per ogni sessione o sede di prova, previa adozione di protocolli adottati dal Dipartimento della Funzione Pubblica e validati dal Comitato tecnico-scientifico di cui all\u2019articolo 2 dell\u2019ordinanza 3 febbraio 2020, n. 630, del Capo del Dipartimento della protezione civile.<br \/>\nResta ferma in ogni caso l\u2019osservanza delle disposizioni di cui alla direttiva del Ministro per<br \/>\nla pubblica amministrazione n. 1 del 25 febbraio2020 e degli ulteriori aggiornamenti, nonch\u00e9 la possibilit\u00e0 per le commissioni di procedere alla correzione delle prove scritte con collegamento da remoto\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Impianti sciistici<\/b><\/p>\n<p>Fino al 15 febbraio \u00absono chiusi gli impianti nei comprensori sciistici\u00bb. Gli impianti \u00abpossono essere utilizzati solo da parte di atleti professionisti e non professionisti, riconosciuti di interesse nazionale dal Comitato olimpico nazionale italiano (CONI), dal Comitato Italiano Paralimpico (CIP) e\/o dalle rispettive federazioni per permettere la preparazione finalizzata allo svolgimento di competizioni sportive nazionali e internazionali o lo svolgimento di tali competizioni, nonch\u00e9 per lo svolgimento delle prove di abilitazione all\u2019esercizio della professione di maestro di sci\u00bb.<\/p>\n<p>\u00abA partire dal 15 febbraio 2021, gli impianti sono aperti agli sciatori amatoriali solo subordinatamente all\u2019adozione di apposite linee guida da parte della Conferenza delle Regioni e delle Province autonome e validate dal Comitato tecnico-scientifico, rivolte a evitare aggregazioni di persone e, in genere, assembramenti\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Imminente l\u2019ordinanza del ministro della Salute Speranza<br \/>\n<\/b><\/p>\n<p>Il ministro della Salute Roberto Speranza\u00a0 firmer\u00e0 nelle prossime ore una nuova ordinanza che andr\u00e0 in vigore a partire da domenica 17 gennaio. Passeranno in zona rossa la provincia autonoma di Bolzano e le Regioni Lombardia e Sicilia. Passano in area arancione le Regioni Abruzzo, Friuli Venezia Giulia, Lazio, Liguria, Marche, Piemonte, Puglia, Umbria e Valle D\u2019Aosta. Restano in area arancione Calabria, Emilia-Romagna e Veneto.\u00a0 Il nuovo Dpcm infatti prevede che finiscano in arancione le Regioni con Rt sopra 1 (nel suo valore minimo) o anche quelle con Rt sotto 1 ma con classificazione complessiva di rischio alta. In questi parametri rientrano appunto 12 Regioni. Mentre si entra in zona rossa con un Rt sopra 1,25 (sempre considerando il valore inferiore della \u00abforchetta\u00bb), quindi Lombardia (Rt medio 1,4, valore inferiore 1,38) e Provincia di Bolzano (Rt medio 1,5, valore minimo 1,4) sembrano destinate alle misure pi\u00f9 stringenti. Anche l\u2019Umbria ha un Rt medio a 1,29, ma il valore inferiore \u00e8 1,21: per un soffio potrebbe evitare il rosso e finire in arancione.\u00a0 \u00abSi osserva un aumento complessivo del rischio di una epidemia non controllata e non gestibile nel Paese, dovuto a un aumento diffuso della probabilit\u00e0 di trasmissione diSars-Cov-2 in un contesto in cui l\u2019impatto sui servizi assistenziali rimane alto nella maggior parte delle Regioni e province autonome\u00bb, \u00e8 l\u2019allerta contenuta nella bozza del report di monitoraggio di Istituto superiore di sanit\u00e0 (Iss) e ministero della Salute sull\u2019andamento dell\u2019epidemia di Covid-19 in Italia. Il documento si riferisce al periodo 4-10 gennaio, con dati aggiornati al 13.<\/p>\n<h4><span class=\"Linklist-link Linklist-link--lev1\">Allegati :<br \/>\n<\/span><\/h4>\n<ul class=\"Linklist Linklist--padded u-layout-prose u-text-r-xs\">\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2021\/01\/Dpcm_14_gennaio_2021.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">DPCM 14 Gennaio 2021 [2 MB]<\/a><\/li>\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2021\/01\/allegati_dPCM_14_gennaio_2021_0.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Allegati al DPCM del 14\/01\/2021 [7 MB]<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente del Consiglio\u00a0 ha firmato il nuovo DPCM\u00a0 con le nuove restrizioni anti contagio da Covid 19 che saranno in vigore\u00a0da domani al 5 marzo:\u00a0\u00abAi sensi dell\u2019articolo 1 del [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021 - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021 - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Il presidente del Consiglio\u00a0 ha firmato il nuovo DPCM\u00a0 con le nuove restrizioni anti contagio da Covid 19 che saranno in vigore\u00a0da domani al 5 marzo:\u00a0\u00abAi sensi dell\u2019articolo 1 del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T17:13:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/01\/presidenza_consiglio_ministri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021\",\"datePublished\":\"2021-01-15T17:13:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/\"},\"wordCount\":991,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/01\\\/presidenza_consiglio_ministri.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/\",\"name\":\"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021 - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/01\\\/presidenza_consiglio_ministri.jpg\",\"datePublished\":\"2021-01-15T17:13:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/01\\\/presidenza_consiglio_ministri.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/01\\\/presidenza_consiglio_ministri.jpg\",\"width\":400,\"height\":220},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/01\\\/15\\\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021 - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021 - Soriano nel Cimino","og_description":"Il presidente del Consiglio\u00a0 ha firmato il nuovo DPCM\u00a0 con le nuove restrizioni anti contagio da Covid 19 che saranno in vigore\u00a0da domani al 5 marzo:\u00a0\u00abAi sensi dell\u2019articolo 1 del [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-01-15T17:13:41+00:00","og_image":[{"width":400,"height":220,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/01\/presidenza_consiglio_ministri.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021","datePublished":"2021-01-15T17:13:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/"},"wordCount":991,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/01\/presidenza_consiglio_ministri.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/","name":"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021 - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/01\/presidenza_consiglio_ministri.jpg","datePublished":"2021-01-15T17:13:41+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/01\/presidenza_consiglio_ministri.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/01\/presidenza_consiglio_ministri.jpg","width":400,"height":220},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/01\/15\/emergenza-covid-19-nuovo-dpcm-e-nuove-regole-in-vigore-dal-16-gennaio-al-5-marzo-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Emergenza Covid-19: Nuovo DPCM e nuove regole in vigore dal 16 Gennaio al 5 marzo 2021"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2459"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2459\/revisions"}],"predecessor-version":[{"id":2461,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2459\/revisions\/2461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2460"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}