{"id":2562,"date":"2021-04-30T17:50:29","date_gmt":"2021-04-30T15:50:29","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2562"},"modified":"2021-04-30T18:25:03","modified_gmt":"2021-04-30T16:25:03","slug":"azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/","title":{"rendered":"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo"},"content":{"rendered":"<p>Si comunica elenco degli ammessi alla prova orale, in seguito allo svolgimento della prova scritta nell\u2019ambito della procedura di cui in oggetto ed articolata in tre sessioni (le cui attivit\u00e0 sono state registrate e verbalizzate nei verbali in atti).<\/p>\n<p>I candidati di cui al suddetto elenco sono invitati a presentarsi\u00a0<strong>il 7 maggio alle ore 10.00 presso la Sala del Consiglio Comunale del Comune di Soriano nel Cimino in Piazza Umberto I^ nr.12,\u00a0<\/strong>muniti del documento di riconoscimento in corso di validit\u00e0 e l\u2019obbligo di attenersi alle prescrizioni prescritte per le operazioni concorsuali in base al vigente protocollo Anti Covid (ved. allegato elenco).<\/p>\n<p><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/www.aziendaspecialesam.it\/wp-content\/uploads\/2021\/04\/Ammessi-SAM_Cultura-e-turismo-1.pdf\" target=\"_blank\" rel=\"noopener\">Elenco candidati ammessi selezione N. 2 IMPIEGATI ADDETTI AI SERVIZI ALLA CULTURA E TURISMO<\/a><\/p>\n<p>Fonte: <a href=\"https:\/\/www.aziendaspecialesam.it\/comunicazione-elenco-candidati-alla-prova-orale-selezione-per-n-2-impiegati-addetti-ai-servizi-alla-cultura-e-turismo\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.aziendaspecialesam.it\/comunicazione-elenco-candidati-alla-prova-orale-selezione-per-n-2-impiegati-addetti-ai-servizi-alla-cultura-e-turismo\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica elenco degli ammessi alla prova orale, in seguito allo svolgimento della prova scritta nell\u2019ambito della procedura di cui in oggetto ed articolata in tre sessioni (le cui attivit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Si comunica elenco degli ammessi alla prova orale, in seguito allo svolgimento della prova scritta nell\u2019ambito della procedura di cui in oggetto ed articolata in tre sessioni (le cui attivit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-30T15:50:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T16:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/08\/logo512t-300x234-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"234\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo\",\"datePublished\":\"2021-04-30T15:50:29+00:00\",\"dateModified\":\"2021-04-30T16:25:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/\"},\"wordCount\":144,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/08\\\/logo512t-300x234-1.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/\",\"name\":\"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/08\\\/logo512t-300x234-1.png\",\"datePublished\":\"2021-04-30T15:50:29+00:00\",\"dateModified\":\"2021-04-30T16:25:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/08\\\/logo512t-300x234-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/08\\\/logo512t-300x234-1.png\",\"width\":300,\"height\":234},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/04\\\/30\\\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/","og_locale":"it_IT","og_type":"article","og_title":"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo - Soriano nel Cimino","og_description":"Si comunica elenco degli ammessi alla prova orale, in seguito allo svolgimento della prova scritta nell\u2019ambito della procedura di cui in oggetto ed articolata in tre sessioni (le cui attivit\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-04-30T15:50:29+00:00","article_modified_time":"2021-04-30T16:25:03+00:00","og_image":[{"width":300,"height":234,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/08\/logo512t-300x234-1.png","type":"image\/png"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo","datePublished":"2021-04-30T15:50:29+00:00","dateModified":"2021-04-30T16:25:03+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/"},"wordCount":144,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/08\/logo512t-300x234-1.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/","name":"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/08\/logo512t-300x234-1.png","datePublished":"2021-04-30T15:50:29+00:00","dateModified":"2021-04-30T16:25:03+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/08\/logo512t-300x234-1.png","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/08\/logo512t-300x234-1.png","width":300,"height":234},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/04\/30\/azienda-speciale-sam-soriano-ambiente-mobilita-comunicazione-elenco-candidati-alla-prova-orale-selezione-per-1-imp-bibliotecario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Azienda Speciale SAM Soriano Ambiente &amp; Mobilit\u00e0 \u2013 Comunicazione Elenco candidati alla prova orale selezione per 2 Impiegati addetti servizi Cultura e Turismo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2562\/revisions"}],"predecessor-version":[{"id":2567,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2562\/revisions\/2567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2253"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}