{"id":2627,"date":"2021-07-02T14:47:22","date_gmt":"2021-07-02T12:47:22","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2627"},"modified":"2021-07-02T14:47:22","modified_gmt":"2021-07-02T12:47:22","slug":"ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/","title":{"rendered":"Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo"},"content":{"rendered":"<header class=\"Header Headroom--fixed js-Headroom u-hiddenPrint Headroom Headroom--not-bottom Headroom--pinned Headroom--top\">\n<div class=\"Header-navbar \">\n<div class=\"u-layout-wide Grid Grid--alignMiddle u-layoutCenter\">\n<div class=\"Header-utils Grid-cell\">\n<div class=\"Header-social Headroom-hideme\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/header>\n<div id=\"main\" class=\"site-content\">\n<div class=\"u-layout-wide u-layoutCenter u-text-r-l u-padding-r-top u-margin-r-bottom u-layout-r-withGutter\">\n<section class=\"Grid Grid--withGutter\">\n<div class=\"Grid-cell u-md-size8of12 u-lg-size8of12\">\n<div class=\"Prose u-layout-prose\">\n<p>Fino al 30 settembre 2021,\u00a0 \u00a0la cittadinanza \u00e8 cortesemente invitata a osservare l\u2019ordinanza sindacale in allegato e adottare un corretto e razionale uso dell\u2019acqua potabile al fine di evitare inutili sprechi e abusi in genere: saranno consentiti i normali, ammessi, usi domestici e sanitari ovvero, tutte le attivit\u00e0 regolarmente autorizzate, che necessitino dell\u2019uso di acqua potabile ivi compresi i servizi pubblici di igiene urbana.<\/p>\n<p><strong>E\u2019 vietato<\/strong>\u00a0l\u2019utilizzo di acqua potabile nei seguenti casi:<\/p>\n<ol>\n<li>per irrigazione o simili di orti e giardini;<\/li>\n<li>per riempimento di ogni tipo di piscina mobile o da giardino;<\/li>\n<li>per lavaggio automobili\/cicli\/motocicli;<\/li>\n<li>per qualunque uso ludico o che non sia quello del servizio.<\/li>\n<\/ol>\n<p>Anche nei casi di accertati eccessivi consumi di acqua potabile per usi domestici il Comune si riserva di procedere alla rescissione del contratto di erogazione dell\u2019acqua. Gli agenti ed ufficiali della Polizia Locale e della Forza Pubblica, i funzionari dell\u2019Ufficio Tecnico, nonch\u00e9 il personale della soc. Talete S.p.A. quale gestore del Servizio idrico integrato eserciteranno, a tal fine, rigorosi e costanti controlli.<\/p>\n<div class=\"u-sizeFull u-md-size11of12 u-lg-size11of12\">\n<div class=\"u-margin-r-top\"><\/div>\n<p><strong><span class=\"Linklist-link Linklist-link--lev1\">Allegati (1)<\/span><\/strong><\/p>\n<ol class=\"Linklist Linklist--padded u-layout-prose u-text-r-xs\">\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2021\/07\/Ordinanza-Sindacale-110-2021.pdf\" target=\"_blank\" rel=\"noopener\">Ordinanza Sindacale 110-2021 [144 KB]<\/a><\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fino al 30 settembre 2021,\u00a0 \u00a0la cittadinanza \u00e8 cortesemente invitata a osservare l\u2019ordinanza sindacale in allegato e adottare un corretto e razionale uso dell\u2019acqua potabile al fine di evitare inutili [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2628,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Fino al 30 settembre 2021,\u00a0 \u00a0la cittadinanza \u00e8 cortesemente invitata a osservare l\u2019ordinanza sindacale in allegato e adottare un corretto e razionale uso dell\u2019acqua potabile al fine di evitare inutili [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-02T12:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/07\/acqua_sprecata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Ordinanza Sindacale 110\\\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo\",\"datePublished\":\"2021-07-02T12:47:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/\"},\"wordCount\":190,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/07\\\/acqua_sprecata.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/\",\"name\":\"Ordinanza Sindacale 110\\\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/07\\\/acqua_sprecata.jpg\",\"datePublished\":\"2021-07-02T12:47:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/07\\\/acqua_sprecata.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/07\\\/acqua_sprecata.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/07\\\/02\\\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza Sindacale 110\\\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo - Soriano nel Cimino","og_description":"Fino al 30 settembre 2021,\u00a0 \u00a0la cittadinanza \u00e8 cortesemente invitata a osservare l\u2019ordinanza sindacale in allegato e adottare un corretto e razionale uso dell\u2019acqua potabile al fine di evitare inutili [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-07-02T12:47:22+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/07\/acqua_sprecata.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo","datePublished":"2021-07-02T12:47:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/"},"wordCount":190,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/07\/acqua_sprecata.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/","name":"Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/07\/acqua_sprecata.jpg","datePublished":"2021-07-02T12:47:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/07\/acqua_sprecata.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/07\/acqua_sprecata.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/07\/02\/ordinanza-sindacale-110-2021-uso-razionale-dellacqua-durante-il-periodo-estivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Ordinanza Sindacale 110\/2021 : Uso razionale dell\u2019acqua durante il periodo estivo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2627"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2627\/revisions"}],"predecessor-version":[{"id":2629,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2627\/revisions\/2629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2628"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}