{"id":2679,"date":"2021-10-12T14:14:55","date_gmt":"2021-10-12T12:14:55","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2679"},"modified":"2021-10-12T14:14:55","modified_gmt":"2021-10-12T12:14:55","slug":"nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/","title":{"rendered":"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021"},"content":{"rendered":"<div class=\"Grid-cell u-md-size8of12 u-lg-size8of12\">\n<div class=\"Prose u-layout-prose\">\n<p>Per motivi di manutenzione alla rete fognaria nella zona in oggetto, con Ordinanza del Responsabile Area IV Tecnica viene istituito il divieto circolazione dalle ore 14:00 a termine dei lavori (circa ore 16:00) del giorno 13 Ottobre 2021 in Via Garibaldi, nel solo tratto compreso tra<br \/>\nPiazza V. Emanuele II e Via Antonio Trua.<\/p>\n<p>Sono inoltre prescritti in Ordinanza i segg. punti:<\/p>\n<ul>\n<li>dovr\u00e0 essere consentito il passaggio dei pedoni in condizioni di sicurezza il tutto in conformit\u00e0 della normativa vigente in materia, al fine della salvaguardia della loro incolumit\u00e0;<\/li>\n<li>che sia se possibile garantito il transito dei residenti nei tratti di strada non interessati dai lavori nonch\u00e9 l\u2019ingresso e l\u2019uscita dai passi carrabili\u00a0 autorizzati ivi esistenti;<\/li>\n<li>che venga collocata e mantenuta efficiente la prescritta segnaletica stradale, a cura e spese dell\u2019Impresa esecutrice dei lavori, apponendo almeno 48 ore prima la segnaletica concernente i divieti di sosta, integrata con pannelli indicanti la rimozione coatta, l\u2019orario e la data di inizio del<br \/>\ndivieto;<\/li>\n<li>che tutta la segnaletica stradale provvisoria collocata in ottemperanza al presente atto indichi chiaramente il riferimento al numero e data della presente ordinanza;<\/li>\n<li>che sia posta idonea segnaletica di preavviso della chiusura delle dette strade in maniera tale da informare gli utenti delle modifiche alla viabilit\u00e0 istituite, al fine di non creare intralcio o pericolo per la circolazione;<\/li>\n<li>che dove risulti necessario si ponga in opera opportuna segnaletica di percorsi alternativi;<\/li>\n<li>che del giorno e dell\u2019ora in cui \u00e8 avvenuta la collocazione della segnaletica dei divieti di sosta eventualmente previsti, sia data comunicazione all\u2019Ufficio Polizia Locale;<\/li>\n<li>la presente ordinanza avr\u00e0 efficacia previo rilascio delle prescritte autorizzazioni e del pagamento per l\u2019occupazione del suolo pubblico se dovuto;<\/li>\n<li>spetta a chi di dovere e per quanto di competenza osservare e far osservare quanto disposto dalla presente ordinanza.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span class=\"Linklist-link Linklist-link--lev1\">Allegati (1)<\/span><\/p>\n<div class=\"u-sizeFull u-md-size11of12 u-lg-size11of12\">\n<ul class=\"Linklist Linklist--padded u-layout-prose u-text-r-xs\">\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2021\/10\/memdoc_creapdf_52072177367639651409451683691032.pdf\" target=\"_blank\" rel=\"noopener\">Ordinanza Numero 165 del 11-10-2021 [146 KB]<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"Grid-cell u-sizeFull u-md-size4of12 u-lg-size4of12\">\n<div class=\"u-sizeFull u-md-size11of12 u-lg-size11of12 italiawp-sidebar\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per motivi di manutenzione alla rete fognaria nella zona in oggetto, con Ordinanza del Responsabile Area IV Tecnica viene istituito il divieto circolazione dalle ore 14:00 a termine dei lavori [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021 - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021 - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Per motivi di manutenzione alla rete fognaria nella zona in oggetto, con Ordinanza del Responsabile Area IV Tecnica viene istituito il divieto circolazione dalle ore 14:00 a termine dei lavori [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T12:14:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"307\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021\",\"datePublished\":\"2021-10-12T12:14:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/\"},\"wordCount\":335,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/\",\"name\":\"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021 - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"datePublished\":\"2021-10-12T12:14:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"width\":512,\"height\":307},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/10\\\/12\\\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021 - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021 - Soriano nel Cimino","og_description":"Per motivi di manutenzione alla rete fognaria nella zona in oggetto, con Ordinanza del Responsabile Area IV Tecnica viene istituito il divieto circolazione dalle ore 14:00 a termine dei lavori [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-10-12T12:14:55+00:00","og_image":[{"width":512,"height":307,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021","datePublished":"2021-10-12T12:14:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/"},"wordCount":335,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/","name":"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021 - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","datePublished":"2021-10-12T12:14:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","width":512,"height":307},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/10\/12\/nuova-ordinanza-per-disciplina-del-traffico-veicolare-su-via-garibaldi-tratto-compreso-tra-piazza-v-emanuele-ii-e-via-antonio-trua-dalle-ore-1400-a-fine-lavori-del-giorno-13-ottobre-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Nuova Ordinanza per disciplina del traffico veicolare su Via Garibaldi tratto compreso tra Piazza V. Emanuele II e Via Antonio Trua dalle ore 14:00 a fine lavori del giorno 13 ottobre 2021"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2679"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2679\/revisions"}],"predecessor-version":[{"id":2680,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2679\/revisions\/2680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2499"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}