{"id":2711,"date":"2021-11-03T17:26:31","date_gmt":"2021-11-03T16:26:31","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2711"},"modified":"2021-11-03T17:26:31","modified_gmt":"2021-11-03T16:26:31","slug":"4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/","title":{"rendered":"4 Novembre &#8211; Giorno dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate"},"content":{"rendered":"<p>La ricorrenza del 4 Novembre, in cui ricordiamo anche la vittoria della Prima Guerra Mondiale e della sua tragedia, \u00e8 una giornata di memoria collettiva, una giornata che ripercorre la storia, la storia fatta di fatiche, sacrifici e di persone che hanno dato la vita per la nostra Italia. \u00c8 nostro dovere ricordare i Caduti e, attraverso il loro sacrificio, capire il significato profondo dell&#8217;essere Italiani. Conoscere e ricordare la storia ci insegna a non ripetere gli errori, puntando su un futuro basato su valori preziosi, sacrificio, dovere integrit\u00e0, amore per il proprio paese. Il nostro pensiero va soprattutto ai nostri giovani, con cui insieme dobbiamo sentire forte la responsabilit\u00e0 di costruire un futuro migliore. Solo cos\u00ec onoreremo i nostri Caduti.<\/p>\n<p>Un particolare ringraziamento va rivolto alle Forze Armate, a partire dalle Forze dell&#8217;Ordine che operano sul nostro territorio, che svolgono un lavoro quotidiano e silenzioso per il bene di tutta la collettivit\u00e0.<\/p>\n<h2 style=\"text-align: center\">Domenica 7 Novembre<\/h2>\n<p>ore 11,00: Consiglio Comunale straordinario per la lettura della motivazione del conferimento della cittadinanza onoraria al Milite Ignoto.<br \/>\nore 11,3o: Deposizione di una corona d&#8217;alloro al Monumento ai Caduti presso il Piazzale della Repubblica a Soriano nel Cimino.<\/p>\n<p><strong>A seguire Breve Concerto della Banda Musicale di Soriano nel Cimino.<\/strong><\/p>\n<p>ore 12,15 Deposizione di una corona d&#8217;alloro al Monumento ai Caduti presso la Frazione di Chia.<\/p>\n<p><em>La cerimonia si terr\u00e0 nel rispetto delle norme anti-covid 19<\/em><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>La ricorrenza del 4 Novembre, in cui ricordiamo anche la vittoria della Prima Guerra Mondiale e della sua tragedia, \u00e8 una giornata di memoria collettiva, una giornata che ripercorre la [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 Novembre - Giorno dell&#039;Unit\u00e0 Nazionale e delle Forze Armate - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 Novembre - Giorno dell&#039;Unit\u00e0 Nazionale e delle Forze Armate - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"La ricorrenza del 4 Novembre, in cui ricordiamo anche la vittoria della Prima Guerra Mondiale e della sua tragedia, \u00e8 una giornata di memoria collettiva, una giornata che ripercorre la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-03T16:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/11\/4-novembre-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"4 Novembre &#8211; Giorno dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate\",\"datePublished\":\"2021-11-03T16:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/\"},\"wordCount\":233,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/11\\\/4-novembre-.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/\",\"name\":\"4 Novembre - Giorno dell'Unit\u00e0 Nazionale e delle Forze Armate - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/11\\\/4-novembre-.jpg\",\"datePublished\":\"2021-11-03T16:26:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/11\\\/4-novembre-.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/11\\\/4-novembre-.jpg\",\"width\":640,\"height\":446},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2021\\\/11\\\/03\\\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 Novembre &#8211; Giorno dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 Novembre - Giorno dell'Unit\u00e0 Nazionale e delle Forze Armate - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/","og_locale":"it_IT","og_type":"article","og_title":"4 Novembre - Giorno dell'Unit\u00e0 Nazionale e delle Forze Armate - Soriano nel Cimino","og_description":"La ricorrenza del 4 Novembre, in cui ricordiamo anche la vittoria della Prima Guerra Mondiale e della sua tragedia, \u00e8 una giornata di memoria collettiva, una giornata che ripercorre la [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-11-03T16:26:31+00:00","og_image":[{"width":640,"height":446,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/11\/4-novembre-.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"4 Novembre &#8211; Giorno dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate","datePublished":"2021-11-03T16:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/"},"wordCount":233,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/11\/4-novembre-.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/","name":"4 Novembre - Giorno dell'Unit\u00e0 Nazionale e delle Forze Armate - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/11\/4-novembre-.jpg","datePublished":"2021-11-03T16:26:31+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/11\/4-novembre-.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/11\/4-novembre-.jpg","width":640,"height":446},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2021\/11\/03\/4-novembre-giorno-dellunita-nazionale-e-delle-forze-armate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"4 Novembre &#8211; Giorno dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2711"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2711\/revisions"}],"predecessor-version":[{"id":2713,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2711\/revisions\/2713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2712"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}