{"id":2816,"date":"2022-02-10T19:11:25","date_gmt":"2022-02-10T18:11:25","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2816"},"modified":"2022-02-10T19:11:25","modified_gmt":"2022-02-10T18:11:25","slug":"selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/","title":{"rendered":"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande."},"content":{"rendered":"<p><strong>I colloqui sono stati sospesi e rinviati, a data da destinarsi, dopo la scadenza per la presentazione delle domande, fissata per il 9 marzo.<\/strong><\/p>\n<p>In pedissequa esecuzione del decreto monocratico adottato dal Presidente della Sezione Quarta Bis del Tribunale Amministrativo Regionale per il Lazio n.00816-2022, Reg. Ric n. 01190\/2022, pubblicato in data 9 febbraio 2022, \u00e8 disposta la proroga del termine di cui all\u2019articolo 2 del Bando integrativo del 25 gennaio 2022, fissandolo alle ore 14:00 del 9 Marzo 2022.<\/p>\n<p>Le candidature presentate successivamente alle ore 14:00 del 10 febbraio 2022 fino al predetto termine del 9 marzo 2022 sono ammesse con riserva.<br \/>\nIl termine di cui al paragrafo n. 11 delle Linee Guida per la compilazione e presentazione della domanda online con la piattaforma DOL, pubblicate sul sito a corredo del Bando 2021, riportato anche nella FAQ n. 26, \u00e8 conseguentemente differito alle ore 14:00 dell\u20198 Marzo 2022 ai fini dell\u2019eventuale annullamento della propria domanda e presentazione di una nuova.<\/p>\n<p>Ulteriori ed eventuali determinazioni saranno adottate dal Dipartimento ad esito della Camera di Consiglio fissata dal medesimo decreto monocratico del Tribunale Amministrativo Regionale per il Lazio.<\/p>\n<p><a class=\"oajrlxb2 g5ia77u1 qu0x051f esr5mh6w e9989ue4 r7d6kgcz rq0escxv nhd2j8a9 nc684nl6 p7hjln8o kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x jb3vyjys rz4wbd8a qt6c0cv9 a8nywdso i1ao9s8h esuyzwwr f1sip0of lzcic4wl gpro0wi8 py34i1dx\" role=\"link\" href=\"https:\/\/www.politichegiovanili.gov.it\/comunicazione\/news\/2022\/2\/proroga-bando-9-marzo-2022\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/www.politichegiovanili.gov.it\/comunicazione\/news\/2022\/2\/proroga-bando-9-marzo-2022<\/a><\/p>\n<div class=\"oajrlxb2 g5ia77u1 qu0x051f esr5mh6w e9989ue4 r7d6kgcz rq0escxv nhd2j8a9 nc684nl6 p7hjln8o kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x jb3vyjys rz4wbd8a qt6c0cv9 a8nywdso i1ao9s8h esuyzwwr f1sip0of lzcic4wl gpro0wi8 oo9gr5id lrazzd5p\" role=\"button\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I colloqui sono stati sospesi e rinviati, a data da destinarsi, dopo la scadenza per la presentazione delle domande, fissata per il 9 marzo. In pedissequa esecuzione del decreto monocratico [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2817,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande. - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande. - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"I colloqui sono stati sospesi e rinviati, a data da destinarsi, dopo la scadenza per la presentazione delle domande, fissata per il 9 marzo. In pedissequa esecuzione del decreto monocratico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-10T18:11:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2022\/02\/bando_proroga.png\" \/>\n\t<meta property=\"og:image:width\" content=\"772\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande.\",\"datePublished\":\"2022-02-10T18:11:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/\"},\"wordCount\":193,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2022\\\/02\\\/bando_proroga.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/\",\"name\":\"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande. - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2022\\\/02\\\/bando_proroga.png\",\"datePublished\":\"2022-02-10T18:11:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2022\\\/02\\\/bando_proroga.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2022\\\/02\\\/bando_proroga.png\",\"width\":772,\"height\":505},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/02\\\/10\\\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande. - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/","og_locale":"it_IT","og_type":"article","og_title":"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande. - Soriano nel Cimino","og_description":"I colloqui sono stati sospesi e rinviati, a data da destinarsi, dopo la scadenza per la presentazione delle domande, fissata per il 9 marzo. In pedissequa esecuzione del decreto monocratico [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-02-10T18:11:25+00:00","og_image":[{"width":772,"height":505,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2022\/02\/bando_proroga.png","type":"image\/png"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande.","datePublished":"2022-02-10T18:11:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/"},"wordCount":193,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2022\/02\/bando_proroga.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/","name":"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande. - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2022\/02\/bando_proroga.png","datePublished":"2022-02-10T18:11:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2022\/02\/bando_proroga.png","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2022\/02\/bando_proroga.png","width":772,"height":505},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/02\/10\/selezione-bando-servizio-civile-prorogata-alle-ore-1400-del-9-marzo-2022-la-scadenza-per-la-presentazione-delle-domande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"SELEZIONE BANDO SERVIZIO CIVILE: Prorogata alle ore 14:00 del 9 marzo 2022 la scadenza per la presentazione delle domande."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2816"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2816\/revisions"}],"predecessor-version":[{"id":2818,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2816\/revisions\/2818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2817"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}