{"id":2883,"date":"2022-06-16T12:30:54","date_gmt":"2022-06-16T10:30:54","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2883"},"modified":"2022-06-16T12:30:54","modified_gmt":"2022-06-16T10:30:54","slug":"contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/","title":{"rendered":"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020)."},"content":{"rendered":"<p>La Regione Lazio persegue la tutela della salute e del benessere delle persone, con particolare riferimento alle situazioni che possono incidere negativamente sul loro equilibrio fisico e psichico.<br \/>\nIn attuazione dell\u2019art. 7, commi 77 \u2013 81 della legge regionale n. 28\/2019 \u00e8 prevista l\u2019erogazione di un contributo destinato alle donne sottoposte a terapia oncologica per l\u2019acquisto di una parrucca.<\/p>\n<p>Per l\u2019erogazione del contributo in questione si potranno presentare le domande durante il corso dell\u2019anno solare con scadenza\u00a0<strong>30 giugno 2022<\/strong><\/p>\n<p>I destinatari del presente avviso sono tutte le donne residenti nel Lazio affette da alopecia conseguente a terapia oncologica.<\/p>\n<div class=\"u-sizeFull u-md-size11of12 u-lg-size11of12\">\n<p><span class=\"Linklist-link Linklist-link--lev1\">Allegati (3):<\/span><\/p>\n<ul class=\"Linklist Linklist--padded u-layout-prose u-text-r-xs\">\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2022\/06\/AVVISO-ASL-X-TERAP-ONCOL..pdf\" target=\"_blank\" rel=\"noopener\">AVVISO ASL X TERAP. ONCOLOGICA [957 KB]<\/a><\/li>\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2022\/06\/DOMANDA-ASL-X-CONTRIB-TER-ONC.pdf\" target=\"_blank\" rel=\"noopener\">Modulo di Domanda ASL [429 KB]<\/a><\/li>\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2022\/06\/Informativa-al-trattamento-dati-personali-asl-vt-al-06_2022.pdf\" target=\"_blank\" rel=\"noopener\">Informativa al trattamento dati personali asl vt al 06_2022 [653 KB]<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Lazio persegue la tutela della salute e del benessere delle persone, con particolare riferimento alle situazioni che possono incidere negativamente sul loro equilibrio fisico e psichico. In attuazione [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020). - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020). - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"La Regione Lazio persegue la tutela della salute e del benessere delle persone, con particolare riferimento alle situazioni che possono incidere negativamente sul loro equilibrio fisico e psichico. In attuazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-16T10:30:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/regione-lazio-e1592316014567.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\\\/2020).\",\"datePublished\":\"2022-06-16T10:30:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/\"},\"wordCount\":136,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/regione-lazio-e1592316014567.png\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/\",\"name\":\"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\\\/2020). - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/regione-lazio-e1592316014567.png\",\"datePublished\":\"2022-06-16T10:30:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/regione-lazio-e1592316014567.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/regione-lazio-e1592316014567.png\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/06\\\/16\\\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\\\/2020).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020). - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/","og_locale":"it_IT","og_type":"article","og_title":"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020). - Soriano nel Cimino","og_description":"La Regione Lazio persegue la tutela della salute e del benessere delle persone, con particolare riferimento alle situazioni che possono incidere negativamente sul loro equilibrio fisico e psichico. In attuazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-06-16T10:30:54+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/regione-lazio-e1592316014567.png","type":"image\/png"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020).","datePublished":"2022-06-16T10:30:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/"},"wordCount":136,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/regione-lazio-e1592316014567.png","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/","name":"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020). - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/regione-lazio-e1592316014567.png","datePublished":"2022-06-16T10:30:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/regione-lazio-e1592316014567.png","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/regione-lazio-e1592316014567.png","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/06\/16\/contributi-alle-donne-sottoposte-a-terapia-oncologica-per-lacquisto-della-parrucca-e-istituzione-della-banca-della-parrucca-dgr-493-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Contributi alle donne sottoposte a terapia oncologica per l\u2019acquisto della parrucca e istituzione della Banca della parrucca \u2013 (DGR 493\/2020)."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2883"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2883\/revisions"}],"predecessor-version":[{"id":2884,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2883\/revisions\/2884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2222"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}