{"id":2978,"date":"2022-09-15T12:20:00","date_gmt":"2022-09-15T10:20:00","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2978"},"modified":"2022-09-15T12:20:00","modified_gmt":"2022-09-15T10:20:00","slug":"ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/","title":{"rendered":"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022"},"content":{"rendered":"<p>Si comunica che a seguito intervento correttivo di Talete Spa e successive verifiche effettuate con analisi batteriologiche, \u00e8 stata ripristinata la potabilit\u00e0 dell\u2019acqua per il consumo umano precedentemente interdetta da precedente Ordinanza n. 147 del 13\/09\/2022.<\/p>\n<p>Con allegate Ordinanza Sindacale n. 152 del 15\/09\/2022 ed esito delle analisi batteriologiche, si dispone la revoca dell\u2019Ordinanza n. 147\/2022 in quanto i parametri batteriologici sono rientrati nella normalit\u00e0<\/p>\n<p><span class=\"Linklist-link Linklist-link--lev1\">Allegati (2):<\/span><\/p>\n<ul class=\"Linklist Linklist--padded u-layout-prose u-text-r-xs\">\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2022\/09\/Copia_DocPrincipale_richiesta_verifica_analitica_alla_asl_di_competenza.pdf\" target=\"_blank\" rel=\"noopener\">Verifica analisi batteriologica [176 KB]<\/a><\/li>\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2022\/09\/MemDoc_CreaPdf_144617599478609821039581909558255.pdf\" target=\"_blank\" rel=\"noopener\">Ordinanza Sindacale 152\/2022 [152 KB]<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che a seguito intervento correttivo di Talete Spa e successive verifiche effettuate con analisi batteriologiche, \u00e8 stata ripristinata la potabilit\u00e0 dell\u2019acqua per il consumo umano precedentemente interdetta da [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":1913,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022 - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022 - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Si comunica che a seguito intervento correttivo di Talete Spa e successive verifiche effettuate con analisi batteriologiche, \u00e8 stata ripristinata la potabilit\u00e0 dell\u2019acqua per il consumo umano precedentemente interdetta da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T10:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\\\/09\\\/2022\",\"datePublished\":\"2022-09-15T10:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/\"},\"wordCount\":88,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/\",\"name\":\"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\\\/09\\\/2022 - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"datePublished\":\"2022-09-15T10:20:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"width\":300,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/09\\\/15\\\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\\\/09\\\/2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022 - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/","og_locale":"it_IT","og_type":"article","og_title":"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022 - Soriano nel Cimino","og_description":"Si comunica che a seguito intervento correttivo di Talete Spa e successive verifiche effettuate con analisi batteriologiche, \u00e8 stata ripristinata la potabilit\u00e0 dell\u2019acqua per il consumo umano precedentemente interdetta da [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-09-15T10:20:00+00:00","og_image":[{"width":300,"height":225,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022","datePublished":"2022-09-15T10:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/"},"wordCount":88,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/","name":"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022 - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","datePublished":"2022-09-15T10:20:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","width":300,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/09\/15\/ripristino-potabilita-dellacqua-dellacquedotto-comunale-al-servizio-di-porzione-del-territorio-con-revoca-ordinanza-n-147-del-13-09-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Ripristino potabilit\u00e0 dell\u2019acqua dell\u2019acquedotto comunale al servizio di porzione del territorio, con revoca ordinanza n. 147 del 13\/09\/2022"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2978"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2978\/revisions"}],"predecessor-version":[{"id":2979,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2978\/revisions\/2979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}