{"id":3045,"date":"2022-11-29T19:07:20","date_gmt":"2022-11-29T18:07:20","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=3045"},"modified":"2022-11-29T19:07:20","modified_gmt":"2022-11-29T18:07:20","slug":"disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/","title":{"rendered":"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI"},"content":{"rendered":"<p>Si comunica alla Cittadinanza che il giorno 7 Dicembre, dalle ore 9,00 fino a termine dei lavori di scavo per distribuzione rete di fibra ottica, verr\u00e0 chiuso il transito per garantire le opere in piena sicurezza: maggiori informazioni nell\u2019allegata Ordinanza del Responsabile.<\/p>\n<div class=\"u-sizeFull u-md-size11of12 u-lg-size11of12\">\n<p><span class=\"Linklist-link Linklist-link--lev1\">Allegati (1):<\/span><\/p>\n<ul class=\"Linklist Linklist--padded u-layout-prose u-text-r-xs\">\n<li><a class=\"Linklist-link Linklist-link--lev2\" href=\"https:\/\/comune.sorianonelcimino.vt.it\/wp-content\/uploads\/2022\/11\/MemDoc_CreaPdf_77438221178546651617091682214705.pdf\" target=\"_blank\" rel=\"noopener\">Ordinanza Numero 206 del 29-11-2022 [125 KB]<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica alla Cittadinanza che il giorno 7 Dicembre, dalle ore 9,00 fino a termine dei lavori di scavo per distribuzione rete di fibra ottica, verr\u00e0 chiuso il transito per [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Si comunica alla Cittadinanza che il giorno 7 Dicembre, dalle ore 9,00 fino a termine dei lavori di scavo per distribuzione rete di fibra ottica, verr\u00e0 chiuso il transito per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T18:07:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"307\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI\",\"datePublished\":\"2022-11-29T18:07:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/\"},\"wordCount\":64,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/\",\"name\":\"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"datePublished\":\"2022-11-29T18:07:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2021\\\/02\\\/ordinanza_veicolare.jpg\",\"width\":512,\"height\":307},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2022\\\/11\\\/29\\\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/","og_locale":"it_IT","og_type":"article","og_title":"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI - Soriano nel Cimino","og_description":"Si comunica alla Cittadinanza che il giorno 7 Dicembre, dalle ore 9,00 fino a termine dei lavori di scavo per distribuzione rete di fibra ottica, verr\u00e0 chiuso il transito per [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-29T18:07:20+00:00","og_image":[{"width":512,"height":307,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI","datePublished":"2022-11-29T18:07:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/"},"wordCount":64,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/","name":"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","datePublished":"2022-11-29T18:07:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2021\/02\/ordinanza_veicolare.jpg","width":512,"height":307},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2022\/11\/29\/disciplina-del-traffico-veicolare-su-viale-v-emanuele-iii-il-7-dicembre-2022-dalle-ore-900-a-fine-lavori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"DISCIPLINA DEL TRAFFICO VEICOLARE SU VIALE V. EMANUELE III IL 7 DICEMBRE 2022 DALLE ORE 9:00 A FINE LAVORI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/3045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=3045"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/3045\/revisions"}],"predecessor-version":[{"id":3046,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/3045\/revisions\/3046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2499"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=3045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=3045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=3045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}