{"id":665,"date":"2016-10-24T13:00:33","date_gmt":"2016-10-24T11:00:33","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=665"},"modified":"2016-10-24T13:00:33","modified_gmt":"2016-10-24T11:00:33","slug":"proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/","title":{"rendered":"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini."},"content":{"rendered":"<p>Comune di Soriano nel Cimino<\/p>\n<div id=\"wrapper\">\n<div id=\"content\">\n<div class=\"NewsHome\">\n<p>Il MInistero della Salute proroga le ordinanze contingibili ed urgenti concernenti la tutela della incolumit\u00e0 pubblica dall&#8217;aggressione dei cani (ordinanza 13 luglio 2016) e \u00a0l&#8217;impegno di equidi al di fuori degli impianti e dei percorsi ufficialmente autorizzati (ordinanza 3 agosto 2016).<\/p>\n<p><a href=\"http:\/\/www.comune.sorianonelcimino.vt.it\/my\/documentazione\/Documenti\/files\/ordinanza cani.pdf\">Allegato<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comune di Soriano nel Cimino Il MInistero della Salute proroga le ordinanze contingibili ed urgenti concernenti la tutela della incolumit\u00e0 pubblica dall&#8217;aggressione dei cani (ordinanza 13 luglio 2016) e \u00a0l&#8217;impegno [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-665","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini. - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini. - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Comune di Soriano nel Cimino Il MInistero della Salute proroga le ordinanze contingibili ed urgenti concernenti la tutela della incolumit\u00e0 pubblica dall&#8217;aggressione dei cani (ordinanza 13 luglio 2016) e \u00a0l&#8217;impegno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-24T11:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini.\",\"datePublished\":\"2016-10-24T11:00:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/\"},\"wordCount\":58,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/\",\"name\":\"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini. - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"datePublished\":\"2016-10-24T11:00:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2016\\\/10\\\/24\\\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini. - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/","og_locale":"it_IT","og_type":"article","og_title":"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini. - Soriano nel Cimino","og_description":"Comune di Soriano nel Cimino Il MInistero della Salute proroga le ordinanze contingibili ed urgenti concernenti la tutela della incolumit\u00e0 pubblica dall&#8217;aggressione dei cani (ordinanza 13 luglio 2016) e \u00a0l&#8217;impegno [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-10-24T11:00:33+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini.","datePublished":"2016-10-24T11:00:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/"},"wordCount":58,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/","name":"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini. - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"datePublished":"2016-10-24T11:00:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2016\/10\/24\/proroga-ordinanze-del-ministero-della-salute-in-materia-di-aggressione-cani-e-impegno-di-equini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Proroga ordinanze del Ministero della Salute in materia di aggressione cani e impegno di equini."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=665"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/665\/revisions"}],"predecessor-version":[{"id":666,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/665\/revisions\/666"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}