{"id":906,"date":"2017-03-23T16:05:03","date_gmt":"2017-03-23T15:05:03","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=906"},"modified":"2017-03-23T16:05:03","modified_gmt":"2017-03-23T15:05:03","slug":"progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/","title":{"rendered":"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani"},"content":{"rendered":"<p>Manifestazione di interesse per la partecipazione alle attivit\u00e0 del progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Urbani.<\/p>\n<p>Il comune di Soriano nel Cimino parteciper\u00e0 come ente, ma il bando \u00e8 aperto anche ad imprese e professionisti qualificati.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_907\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2017\/03\/bando-lazio-innova.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2017\/03\/bando-lazio-innova.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>bando lazio innova<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Manifestazione di interesse per la partecipazione alle attivit\u00e0 del progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Urbani. Il comune di Soriano nel Cimino parteciper\u00e0 come [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-906","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Manifestazione di interesse per la partecipazione alle attivit\u00e0 del progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Urbani. Il comune di Soriano nel Cimino parteciper\u00e0 come [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-23T15:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani\",\"datePublished\":\"2017-03-23T15:05:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/\"},\"wordCount\":55,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/\",\"name\":\"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"datePublished\":\"2017-03-23T15:05:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2017\\\/03\\\/23\\\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/","og_locale":"it_IT","og_type":"article","og_title":"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani - Soriano nel Cimino","og_description":"Manifestazione di interesse per la partecipazione alle attivit\u00e0 del progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Urbani. Il comune di Soriano nel Cimino parteciper\u00e0 come [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-03-23T15:05:03+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani","datePublished":"2017-03-23T15:05:03+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/"},"wordCount":55,"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/","name":"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"datePublished":"2017-03-23T15:05:03+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2017\/03\/23\/progetto-di-scambio-con-la-cina-per-la-valorizzazione-dei-piccoli-centri-storici-urbani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Progetto di scambio con la Cina per la valorizzazione dei Piccoli Centri Storici Urbani"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=906"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/906\/revisions"}],"predecessor-version":[{"id":908,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/906\/revisions\/908"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}