{"id":512,"date":"2016-08-02T10:49:48","date_gmt":"2016-08-02T08:49:48","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?post_type=rdif&#038;p=512"},"modified":"2016-08-02T10:49:48","modified_gmt":"2016-08-02T08:49:48","slug":"plastica","status":"publish","type":"rdif","link":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/","title":{"rendered":"Plastica"},"content":{"rendered":"<div class=\"ccCenter\">\n   <span class=\"fa-stack fa-4x\"><i class=\"fa fa-circle fa-stack-2x ccAzure\"><\/i><i class=\"fa fa-shopping-bag fa-stack-1x fa-inverse\"><\/i><\/span>\n<\/div>\n<h3 class=\"ccAzure ccCenter\">Sacco azzurro<\/h3>\n<h4>\n    <i class=\"fa fa-thumbs-up fa-2x ccDarkGreen\"><\/i> <b>Cosa depositare<\/b><br \/>\n<\/h4>\n<p class=\"ccJustify\">Bottiglie, vasetti e barattoli di plastica, Flaconi di detergenti e detersivi, Sacchetti di plastica, Confezioni di alimenti in plastica, Film e Pellicole, Vasi per piante, Piatti e bicchieri di plastica, Cassette per frutta, Reti per frutta e verdura e polistirolo.<\/p>\n<h4>\n    <i class=\"fa fa-thumbs-down fa-2x ccRed\"><\/i> <b>Cosa NON depositare<\/b><br \/>\n<\/h4>\n<p class=\"ccJustify\">Posate di plastica, Contenitori per solventi e vernici, Giocattoli, Apparecchiature elettriche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sacco azzurro Cosa depositare Bottiglie, vasetti e barattoli di plastica, Flaconi di detergenti e detersivi, Sacchetti di plastica, Confezioni di alimenti in plastica, Film e Pellicole, Vasi per piante, Piatti [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":507,"menu_order":5,"template":"","meta":[],"class_list":["post-512","rdif","type-rdif","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plastica - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plastica - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Sacco azzurro Cosa depositare Bottiglie, vasetti e barattoli di plastica, Flaconi di detergenti e detersivi, Sacchetti di plastica, Confezioni di alimenti in plastica, Film e Pellicole, Vasi per piante, Piatti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/rdif\\\/info-utili\\\/plastica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/rdif\\\/info-utili\\\/plastica\\\/\",\"name\":\"Plastica - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"datePublished\":\"2016-08-02T08:49:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/rdif\\\/info-utili\\\/plastica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/rdif\\\/info-utili\\\/plastica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/rdif\\\/info-utili\\\/plastica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Info Utili\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/rdif\\\/info-utili\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plastica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plastica - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/","og_locale":"it_IT","og_type":"article","og_title":"Plastica - Soriano nel Cimino","og_description":"Sacco azzurro Cosa depositare Bottiglie, vasetti e barattoli di plastica, Flaconi di detergenti e detersivi, Sacchetti di plastica, Confezioni di alimenti in plastica, Film e Pellicole, Vasi per piante, Piatti [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/","name":"Plastica - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"datePublished":"2016-08-02T08:49:48+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/plastica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Info Utili","item":"https:\/\/comunicacity.net\/sorianonelcimino\/rdif\/info-utili\/"},{"@type":"ListItem","position":3,"name":"Plastica"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/rdif\/512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/rdif"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/rdif"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/rdif\/507"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}