{"id":1407,"date":"2016-03-30T16:25:01","date_gmt":"2016-03-30T14:25:01","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=1407"},"modified":"2016-03-30T16:25:01","modified_gmt":"2016-03-30T14:25:01","slug":"il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/","title":{"rendered":"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI"},"content":{"rendered":"<p><span style=\"color: #000000\"><span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-size: medium\">Gioved\u00ec 31 marzo prossimo, presso l&#8217;istituto Foscolo di Sparanise il regista Angelo Maiello presenter\u00e0 un interessante spettacolo dedicato al grande educatore don Lorenzo Milani, autore della celebre \u201cLettera a una professoressa\u201d.Il regista Maiello, spiega il preside Mesolella, racconter\u00e0 ai nostri alunni la storia di Don Milani con le parole di don Milani: nulla della sua narrazione infatti \u00e8 inventato ed ogni fras<\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-size: medium\">e del suo spettacolo \u00e8 stata pronunciata dallo stesso don Milani. Chi ha studiato don Milani sa bene che don Milani riesce a matterci con le spalle al muro, sa che \u00e8 proprio don Milani ad essere, nel panorama del cattolicesimo del Novecento, la testimonianza pi\u00f9 emblematica e significativa: quella di un uomo esemplare che ha vissuto la sua vita ed il suo apostolato per denunciare l&#8217;ingiustizia sociale che purtroppo \u00e8 ancora attuale. Poco o nulla \u00e8 cambiato da allora se anche oggi nelle nostre scuole anzicch\u00e9 incoraggiare gli alunni in difficolt\u00e0 socio culturali si fa di tutto per allontanarli dalla scuola e dai ragazzi\u201dper bene\u201d. Don Milani diceva che non si pu\u00f2 essere insegnanti dalla parte dei ricchi, dei bravi, dei borghesi, del partito Italiano Laureati, abbandonando tutti gli altri (che sono la maggior parte) nel risentimento e nella povert\u00e0 umana ed intellettuale. Don Milani ci parler\u00e0 di Barbiana, di quel luogo nascosto ed isolato, difficile e duro da sopportare. Solo un pazzo poteva restare l\u00ec, in quelle condizioni. Oppure un santo che accettava di essere solo contro tutti, alla ricerca della vertit\u00e0 con coerenza, fino in fondo, fino alla rottura, fino all&#8217;ultimo, fino alla morte, per difendere gli ultimi. In questo modo don Milani ha iniziato un viaggio che lo ha reso prete, maestro, educatore, scrittore, profeta ed intellettuale ma soprattutto ribelle\u201d.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 31 marzo prossimo, presso l&#8217;istituto Foscolo di Sparanise il regista Angelo Maiello presenter\u00e0 un interessante spettacolo dedicato al grande educatore don Lorenzo Milani, autore della celebre \u201cLettera a una [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":1408,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 31 marzo prossimo, presso l&#8217;istituto Foscolo di Sparanise il regista Angelo Maiello presenter\u00e0 un interessante spettacolo dedicato al grande educatore don Lorenzo Milani, autore della celebre \u201cLettera a una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-30T14:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2016\/03\/Don-Milani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"paolomesolella\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"paolomesolella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/\"},\"author\":{\"name\":\"paolomesolella\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\"},\"headline\":\"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI\",\"datePublished\":\"2016-03-30T14:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/\"},\"wordCount\":294,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2016\\\/03\\\/Don-Milani.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/\",\"name\":\"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2016\\\/03\\\/Don-Milani.jpg\",\"datePublished\":\"2016-03-30T14:25:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2016\\\/03\\\/Don-Milani.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2016\\\/03\\\/Don-Milani.jpg\",\"width\":533,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2016\\\/03\\\/30\\\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\",\"name\":\"paolomesolella\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"caption\":\"paolomesolella\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/paolomesolella\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/","og_locale":"it_IT","og_type":"article","og_title":"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI - Sparanise","og_description":"Gioved\u00ec 31 marzo prossimo, presso l&#8217;istituto Foscolo di Sparanise il regista Angelo Maiello presenter\u00e0 un interessante spettacolo dedicato al grande educatore don Lorenzo Milani, autore della celebre \u201cLettera a una [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/","og_site_name":"Sparanise","article_published_time":"2016-03-30T14:25:01+00:00","og_image":[{"width":533,"height":400,"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2016\/03\/Don-Milani.jpg","type":"image\/jpeg"}],"author":"paolomesolella","twitter_misc":{"Scritto da":"paolomesolella","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/"},"author":{"name":"paolomesolella","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c"},"headline":"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI","datePublished":"2016-03-30T14:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/"},"wordCount":294,"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2016\/03\/Don-Milani.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/","url":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/","name":"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2016\/03\/Don-Milani.jpg","datePublished":"2016-03-30T14:25:01+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/#primaryimage","url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2016\/03\/Don-Milani.jpg","contentUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2016\/03\/Don-Milani.jpg","width":533,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2016\/03\/30\/il-regista-angelo-maiello-spiega-agli-alunni-del-galilei-don-lorenzo-milani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"IL REGISTA ANGELO MAIELLO SPIEGA AGLI ALUNNI DEL GALILEI DON LORENZO MILANI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c","name":"paolomesolella","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","caption":"paolomesolella"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/paolomesolella\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/1407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=1407"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/1407\/revisions"}],"predecessor-version":[{"id":1409,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/1407\/revisions\/1409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media\/1408"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=1407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=1407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=1407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}