{"id":2714,"date":"2018-07-11T19:22:06","date_gmt":"2018-07-11T17:22:06","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=2714"},"modified":"2018-07-11T19:22:06","modified_gmt":"2018-07-11T17:22:06","slug":"conferimento-frazione-multimateriale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/","title":{"rendered":"conferimento frazione multimateriale"},"content":{"rendered":"<p>Si\u00a0 porta a conoscenza della cittadinanza che questo Ente ha accertato che numerosi concittadini non hanno ancora compreso compiutamente come si effettua il conferimento della frazione multimateriale.<\/p>\n<p>A tal fine si precisa che il mercoled\u00ec sera all&#8217;interno del sacco del multimateriale devono \u00a0essere conferiti: <strong><span style=\"color: #000000\">Imballaggi in plastica<\/span><\/strong>:bottiglie, flaconi per detersivi, piatti e bicchieri di palstica monouso, buste vaschette, pellicole, polistorolo da imballaggio, contenitori con sigle PET-PVC-PE-PP-PS.<\/p>\n<p><strong>Imballaggi in metallo<\/strong>:scatolame, lattine, fogli di alluminio, bombolette spray, tubetti, lattine, confezioni Tetra Pak.<\/p>\n<p>Il corretto conferimento dei rifiuti, al di l\u00e0 del rispetto dell&#8217;ambiente, comporta un duplice risparmio per l&#8217;Ente ed in generale per tutti i cittadini, aumentando la raccolta di multimateriale aumenta il ristoro al comune, di contro diminuisce il costo dell&#8217;indifferenziato.<\/p>\n<p>Con la consegna delle buste i rifiuti, se conferiti nelle buste nere non saranno pi\u00f9 ritirati .<\/p>\n<p>Tutte le violazioni saranno perseguite come per Legge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si\u00a0 porta a conoscenza della cittadinanza che questo Ente ha accertato che numerosi concittadini non hanno ancora compreso compiutamente come si effettua il conferimento della frazione multimateriale. A tal fine [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2714","post","type-post","status-publish","format-standard","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>conferimento frazione multimateriale - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"conferimento frazione multimateriale - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Si\u00a0 porta a conoscenza della cittadinanza che questo Ente ha accertato che numerosi concittadini non hanno ancora compreso compiutamente come si effettua il conferimento della frazione multimateriale. A tal fine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-11T17:22:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Giovanni Fusco\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Fusco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/\"},\"author\":{\"name\":\"Giovanni Fusco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\"},\"headline\":\"conferimento frazione multimateriale\",\"datePublished\":\"2018-07-11T17:22:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/\"},\"wordCount\":149,\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/\",\"name\":\"conferimento frazione multimateriale - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"datePublished\":\"2018-07-11T17:22:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2018\\\/07\\\/11\\\/conferimento-frazione-multimateriale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"conferimento frazione multimateriale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\",\"name\":\"Giovanni Fusco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"caption\":\"Giovanni Fusco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/giovannifusco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"conferimento frazione multimateriale - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/","og_locale":"it_IT","og_type":"article","og_title":"conferimento frazione multimateriale - Sparanise","og_description":"Si\u00a0 porta a conoscenza della cittadinanza che questo Ente ha accertato che numerosi concittadini non hanno ancora compreso compiutamente come si effettua il conferimento della frazione multimateriale. A tal fine [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/","og_site_name":"Sparanise","article_published_time":"2018-07-11T17:22:06+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png","height":600,"width":1200,"type":""}],"author":"Giovanni Fusco","twitter_misc":{"Scritto da":"Giovanni Fusco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/"},"author":{"name":"Giovanni Fusco","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4"},"headline":"conferimento frazione multimateriale","datePublished":"2018-07-11T17:22:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/"},"wordCount":149,"articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/","url":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/","name":"conferimento frazione multimateriale - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"datePublished":"2018-07-11T17:22:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2018\/07\/11\/conferimento-frazione-multimateriale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"conferimento frazione multimateriale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4","name":"Giovanni Fusco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","caption":"Giovanni Fusco"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/giovannifusco\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/2714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=2714"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/2714\/revisions"}],"predecessor-version":[{"id":2715,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/2714\/revisions\/2715"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=2714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=2714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=2714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}