{"id":294,"date":"2015-03-17T19:02:31","date_gmt":"2015-03-17T19:02:31","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=294"},"modified":"2015-03-17T19:02:31","modified_gmt":"2015-03-17T19:02:31","slug":"sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/","title":{"rendered":"Sanzione amministrativa di 8000 euro comminata dal garante per  violazione  contestata nel 2012"},"content":{"rendered":"<p style=\"text-align: justify\">Il comune di Sparanise dovr\u00e0 pagare una multa comminata\u00a0 dal garante\u00a0 per la protezione dei dati personali. I fatti: il comune pubblic\u00f2\u00a0 nel 2011 dati personali tramite il sito istituzionale sull&#8217;albo pretorio la determina destinata all&#8217;ufficio ragioneria per la liquidazione dei contributi Calenia recante l&#8217;elenco di tutti i beneficiari con l&#8217;indicazione del codice iban; inoltre\u00a0 \u00e8 stata contestato l&#8217;aver omesso il riscontro, ovvero risposta, alle molteplici richieste di chiarimento dell&#8217;autorit\u00e0 in oggetto.\u00a0 Per tali motivi le due mancanze sono state sanzionate con una multa di 8000 euro che bisogner\u00e0 pagare. Inoltre a questa cifra va aggiunto l&#8217;onorario dell&#8217;avvocato nominato quale difensore di fiducia, liquidato con determina n. 228 del 5\\9\\2013 di euro 3020,16. Potrete leggere, allegata alla presente, l&#8217;ordinanza di ingiunzione del garante pubblicata il 4\\12\\2014. L&#8217;amministrazione in carica \u00e8 intenzionata fortemente a\u00a0 provvedere\u00a0 al\u00a0 recupero dei soldi\u00a0 che si pagheranno con azione \u00a0 di responsabilit\u00e0\u00a0 per fatti avvenutii\u00a0 nel corso dell&#8217; amministrazione precedente. Soldi, morale della favola, che quest&#8217;anno potevano essere spesi per le famiglie di Sparanise&#8230;&#8230;.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_295\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/GARANTE-DELLA-PRIVACY-Ordinanza-di-ingiunzione-nei-confronti-di-Comune-di-Sparanise-4-dicembre-2014-3723498.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/GARANTE-DELLA-PRIVACY-Ordinanza-di-ingiunzione-nei-confronti-di-Comune-di-Sparanise-4-dicembre-2014-3723498.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>- GARANTE DELLA PRIVACY - Ordinanza di ingiunzione nei confronti di Comune di Sparanise - 4 dicembre 2014 [3723498]<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il comune di Sparanise dovr\u00e0 pagare una multa comminata\u00a0 dal garante\u00a0 per la protezione dei dati personali. I fatti: il comune pubblic\u00f2\u00a0 nel 2011 dati personali tramite il sito istituzionale [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":36,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012 - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012 - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Il comune di Sparanise dovr\u00e0 pagare una multa comminata\u00a0 dal garante\u00a0 per la protezione dei dati personali. I fatti: il comune pubblic\u00f2\u00a0 nel 2011 dati personali tramite il sito istituzionale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-17T19:02:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Ingresso-Casa-Comunale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"497\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antoniomerola\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antoniomerola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/\"},\"author\":{\"name\":\"antoniomerola\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\"},\"headline\":\"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012\",\"datePublished\":\"2015-03-17T19:02:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/\"},\"wordCount\":170,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Ingresso-Casa-Comunale.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/\",\"name\":\"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012 - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Ingresso-Casa-Comunale.jpg\",\"datePublished\":\"2015-03-17T19:02:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Ingresso-Casa-Comunale.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Ingresso-Casa-Comunale.jpg\",\"width\":497,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/03\\\/17\\\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\",\"name\":\"antoniomerola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"caption\":\"antoniomerola\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/antoniomerola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012 - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/","og_locale":"it_IT","og_type":"article","og_title":"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012 - Sparanise","og_description":"Il comune di Sparanise dovr\u00e0 pagare una multa comminata\u00a0 dal garante\u00a0 per la protezione dei dati personali. I fatti: il comune pubblic\u00f2\u00a0 nel 2011 dati personali tramite il sito istituzionale [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/","og_site_name":"Sparanise","article_published_time":"2015-03-17T19:02:31+00:00","og_image":[{"width":497,"height":400,"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Ingresso-Casa-Comunale.jpg","type":"image\/jpeg"}],"author":"antoniomerola","twitter_misc":{"Scritto da":"antoniomerola","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/"},"author":{"name":"antoniomerola","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8"},"headline":"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012","datePublished":"2015-03-17T19:02:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/"},"wordCount":170,"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Ingresso-Casa-Comunale.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/","url":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/","name":"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012 - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Ingresso-Casa-Comunale.jpg","datePublished":"2015-03-17T19:02:31+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/#primaryimage","url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Ingresso-Casa-Comunale.jpg","contentUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Ingresso-Casa-Comunale.jpg","width":497,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/03\/17\/sanzione-amministrativa-di-8000-euro-comminata-dal-garante-per-violazione-contestata-nel-2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Sanzione amministrativa di 8000 euro comminata dal garante per violazione contestata nel 2012"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8","name":"antoniomerola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","caption":"antoniomerola"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/antoniomerola\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=294"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/294\/revisions"}],"predecessor-version":[{"id":296,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/294\/revisions\/296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}