{"id":3078,"date":"2019-08-03T12:49:57","date_gmt":"2019-08-03T10:49:57","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=3078"},"modified":"2019-08-03T12:52:05","modified_gmt":"2019-08-03T10:52:05","slug":"rifacimento-manto-stradale-c-so-matteotti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/","title":{"rendered":"Rifacimento manto  stradale  C.so Matteotti."},"content":{"rendered":"<p>Si porta a conoscenza della cittadinanza che luned\u00ec 5 agosto 2019 inizieranno i lavori di rifacimento di c.so Matteotti e che termineranno, al massimo sabato 10 Agosto 2019, in merito la ditta ha riferito che i lavori potrebbero terminare anche prima.<\/p>\n<p>Il Comando di P.M. ha adottato il seguente dispositivo di traffico: DIVIETO DI SOSTA E TRANSITO DA LUNEDI&#8217; 5 agosto 2019 lungo tutto C.so Matteotti.<\/p>\n<p>Per lenire i disagi alla cittadinanza e permettere l&#8217;accesso in Piazza e zone limitrofe \u00e8 stato momentaneamente invertito il senso di marcia di via Ragozzino\u00a0 (primo tratto), ossia dall&#8217;intersezione con via Graziadei e fino all&#8217;intersezione con via C.so Del Popolo, con direzione via C.so Del Popolo.<\/p>\n<p>Si chiede la collaborazione dei residenti e della cittadinanza tutta al fine di consentire lo svolgimento dei lavori, in sicurezza e con celerit\u00e0,\u00a0e terminare\u00a0gli stessi, prima della scadenza del tempo previsto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si porta a conoscenza della cittadinanza che luned\u00ec 5 agosto 2019 inizieranno i lavori di rifacimento di c.so Matteotti e che termineranno, al massimo sabato 10 Agosto 2019, in merito [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3078","post","type-post","status-publish","format-standard","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rifacimento manto stradale C.so Matteotti. - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifacimento manto stradale C.so Matteotti. - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Si porta a conoscenza della cittadinanza che luned\u00ec 5 agosto 2019 inizieranno i lavori di rifacimento di c.so Matteotti e che termineranno, al massimo sabato 10 Agosto 2019, in merito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-03T10:49:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-03T10:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Giovanni Fusco\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Fusco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/\"},\"author\":{\"name\":\"Giovanni Fusco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\"},\"headline\":\"Rifacimento manto stradale C.so Matteotti.\",\"datePublished\":\"2019-08-03T10:49:57+00:00\",\"dateModified\":\"2019-08-03T10:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/\"},\"wordCount\":149,\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/\",\"name\":\"Rifacimento manto stradale C.so Matteotti. - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"datePublished\":\"2019-08-03T10:49:57+00:00\",\"dateModified\":\"2019-08-03T10:52:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/03\\\/rifacimento-manto-stradale-c-so-matteotti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rifacimento manto stradale C.so Matteotti.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\",\"name\":\"Giovanni Fusco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"caption\":\"Giovanni Fusco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/giovannifusco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rifacimento manto stradale C.so Matteotti. - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/","og_locale":"it_IT","og_type":"article","og_title":"Rifacimento manto stradale C.so Matteotti. - Sparanise","og_description":"Si porta a conoscenza della cittadinanza che luned\u00ec 5 agosto 2019 inizieranno i lavori di rifacimento di c.so Matteotti e che termineranno, al massimo sabato 10 Agosto 2019, in merito [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/","og_site_name":"Sparanise","article_published_time":"2019-08-03T10:49:57+00:00","article_modified_time":"2019-08-03T10:52:05+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png","height":600,"width":1200,"type":""}],"author":"Giovanni Fusco","twitter_misc":{"Scritto da":"Giovanni Fusco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/"},"author":{"name":"Giovanni Fusco","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4"},"headline":"Rifacimento manto stradale C.so Matteotti.","datePublished":"2019-08-03T10:49:57+00:00","dateModified":"2019-08-03T10:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/"},"wordCount":149,"articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/","url":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/","name":"Rifacimento manto stradale C.so Matteotti. - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"datePublished":"2019-08-03T10:49:57+00:00","dateModified":"2019-08-03T10:52:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/03\/rifacimento-manto-stradale-c-so-matteotti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Rifacimento manto stradale C.so Matteotti."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4","name":"Giovanni Fusco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","caption":"Giovanni Fusco"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/giovannifusco\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=3078"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3078\/revisions"}],"predecessor-version":[{"id":3081,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3078\/revisions\/3081"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=3078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=3078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=3078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}