{"id":3092,"date":"2019-08-12T18:03:32","date_gmt":"2019-08-12T16:03:32","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=3092"},"modified":"2019-08-12T18:03:32","modified_gmt":"2019-08-12T16:03:32","slug":"15-agosto-2019-conferimento-rifiuti-comunicazione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/","title":{"rendered":"15 AGOSTO 2019 CONFERIMENTO RIFIUTI &#8211; COMUNICAZIONE"},"content":{"rendered":"<p><span style=\"color: #000000\">Si porta a conoscenza della cittadinanza e dei commercianti tutti che Gioved\u00ec 15 agosto 2019 (Ferragosto) <strong>non verr\u00e0 effettuato il servizio di raccolta della frazione multimateriale<\/strong>.<\/span><\/p>\n<p><span style=\"color: #ff0000\"><span style=\"color: #000000\">Si raccomanda infine di non conferire<\/span> <strong>assolutamente<\/strong><span style=\"color: #000000\"> il multimateriale nel giorno di venerd\u00ec insieme all&#8217;indifferenziato; <\/span><\/span><\/p>\n<p><span style=\"color: #000000\">Il Comando Polizia Municipale effettuer\u00e0 verifiche su tutto il territorio comunale.<\/span><\/p>\n<p><span style=\"color: #000000\">Si confida nel consueto senso di civilt\u00e0 che contraddistingue la stragrande maggioranza dei cittadini.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si porta a conoscenza della cittadinanza e dei commercianti tutti che Gioved\u00ec 15 agosto 2019 (Ferragosto) non verr\u00e0 effettuato il servizio di raccolta della frazione multimateriale. Si raccomanda infine di [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":1854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15 AGOSTO 2019 CONFERIMENTO RIFIUTI - COMUNICAZIONE - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 AGOSTO 2019 CONFERIMENTO RIFIUTI - COMUNICAZIONE - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Si porta a conoscenza della cittadinanza e dei commercianti tutti che Gioved\u00ec 15 agosto 2019 (Ferragosto) non verr\u00e0 effettuato il servizio di raccolta della frazione multimateriale. Si raccomanda infine di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-12T16:03:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2017\/01\/servizioecologia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"251\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Fusco\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Fusco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/\"},\"author\":{\"name\":\"Giovanni Fusco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\"},\"headline\":\"15 AGOSTO 2019 CONFERIMENTO RIFIUTI &#8211; COMUNICAZIONE\",\"datePublished\":\"2019-08-12T16:03:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/\"},\"wordCount\":70,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2017\\\/01\\\/servizioecologia.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/\",\"name\":\"15 AGOSTO 2019 CONFERIMENTO RIFIUTI - COMUNICAZIONE - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2017\\\/01\\\/servizioecologia.jpg\",\"datePublished\":\"2019-08-12T16:03:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2017\\\/01\\\/servizioecologia.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2017\\\/01\\\/servizioecologia.jpg\",\"width\":251,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2019\\\/08\\\/12\\\/15-agosto-2019-conferimento-rifiuti-comunicazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 AGOSTO 2019 CONFERIMENTO RIFIUTI &#8211; COMUNICAZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/9f7d11500b44c208e363d3366506a8b4\",\"name\":\"Giovanni Fusco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g\",\"caption\":\"Giovanni Fusco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/giovannifusco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 AGOSTO 2019 CONFERIMENTO RIFIUTI - COMUNICAZIONE - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/","og_locale":"it_IT","og_type":"article","og_title":"15 AGOSTO 2019 CONFERIMENTO RIFIUTI - COMUNICAZIONE - Sparanise","og_description":"Si porta a conoscenza della cittadinanza e dei commercianti tutti che Gioved\u00ec 15 agosto 2019 (Ferragosto) non verr\u00e0 effettuato il servizio di raccolta della frazione multimateriale. Si raccomanda infine di [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/","og_site_name":"Sparanise","article_published_time":"2019-08-12T16:03:32+00:00","og_image":[{"width":251,"height":200,"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2017\/01\/servizioecologia.jpg","type":"image\/jpeg"}],"author":"Giovanni Fusco","twitter_misc":{"Scritto da":"Giovanni Fusco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/"},"author":{"name":"Giovanni Fusco","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4"},"headline":"15 AGOSTO 2019 CONFERIMENTO RIFIUTI &#8211; COMUNICAZIONE","datePublished":"2019-08-12T16:03:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/"},"wordCount":70,"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2017\/01\/servizioecologia.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/","url":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/","name":"15 AGOSTO 2019 CONFERIMENTO RIFIUTI - COMUNICAZIONE - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2017\/01\/servizioecologia.jpg","datePublished":"2019-08-12T16:03:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/#primaryimage","url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2017\/01\/servizioecologia.jpg","contentUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2017\/01\/servizioecologia.jpg","width":251,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2019\/08\/12\/15-agosto-2019-conferimento-rifiuti-comunicazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"15 AGOSTO 2019 CONFERIMENTO RIFIUTI &#8211; COMUNICAZIONE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/9f7d11500b44c208e363d3366506a8b4","name":"Giovanni Fusco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9eec5414d1be982a72c1b49b6134b44dff1a0ce682590ecd432c761c10b0862?s=96&d=mm&r=g","caption":"Giovanni Fusco"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/giovannifusco\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=3092"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3092\/revisions"}],"predecessor-version":[{"id":3093,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3092\/revisions\/3093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media\/1854"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=3092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=3092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=3092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}