{"id":3290,"date":"2020-05-05T10:51:09","date_gmt":"2020-05-05T08:51:09","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=3290"},"modified":"2020-05-05T10:51:09","modified_gmt":"2020-05-05T08:51:09","slug":"avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/","title":{"rendered":"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) &#8211; Avviso e questionario"},"content":{"rendered":"<p>Si allega l&#8217;avviso in oggetto ed il seguente link per la consultazione del <a href=\"http:\/\/ww2.gazzettaamministrativa.it\/opencms\/opencms\/_gazzetta_amministrativa\/amministrazione_trasparente\/_campania\/_sparanise\/190_pia_gov_ter\/2017\/Documenti_1496757365620\/\"><strong>Preliminare Piano Urbanistico Comunale (P.U.C.) approvato con delibera di Giunta Comunale n\u00b094 del 5.6.2017<\/strong><\/a><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3291\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/05\/Determina-Avviso-Osservazioni.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/05\/Determina-Avviso-Osservazioni.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Determina Avviso Osservazioni<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si allega l&#8217;avviso in oggetto ed il seguente link per la consultazione del Preliminare Piano Urbanistico Comunale (P.U.C.) approvato con delibera di Giunta Comunale n\u00b094 del 5.6.2017 \ud83d\udcce AllegatiDetermina Avviso [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3290","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) - Avviso e questionario - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) - Avviso e questionario - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Si allega l&#8217;avviso in oggetto ed il seguente link per la consultazione del Preliminare Piano Urbanistico Comunale (P.U.C.) approvato con delibera di Giunta Comunale n\u00b094 del 5.6.2017 \ud83d\udcce AllegatiDetermina Avviso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T08:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"robertozanna\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"robertozanna\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/\"},\"author\":{\"name\":\"robertozanna\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\"},\"headline\":\"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) &#8211; Avviso e questionario\",\"datePublished\":\"2020-05-05T08:51:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/\"},\"wordCount\":47,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/\",\"name\":\"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) - Avviso e questionario - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"datePublished\":\"2020-05-05T08:51:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/05\\\/05\\\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) &#8211; Avviso e questionario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\",\"name\":\"robertozanna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"caption\":\"robertozanna\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/robertozanna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) - Avviso e questionario - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/","og_locale":"it_IT","og_type":"article","og_title":"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) - Avviso e questionario - Sparanise","og_description":"Si allega l&#8217;avviso in oggetto ed il seguente link per la consultazione del Preliminare Piano Urbanistico Comunale (P.U.C.) approvato con delibera di Giunta Comunale n\u00b094 del 5.6.2017 \ud83d\udcce AllegatiDetermina Avviso [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/","og_site_name":"Sparanise","article_published_time":"2020-05-05T08:51:09+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"robertozanna","twitter_misc":{"Scritto da":"robertozanna"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/"},"author":{"name":"robertozanna","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6"},"headline":"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) &#8211; Avviso e questionario","datePublished":"2020-05-05T08:51:09+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/"},"wordCount":47,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/","url":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/","name":"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) - Avviso e questionario - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"datePublished":"2020-05-05T08:51:09+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2020\/05\/05\/avvio-della-fase-di-consultazione-conseguente-allapprovazione-del-preliminare-di-piano-urbanistico-comunale-puc-avviso-e-questionario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Avvio della fase di consultazione conseguente all\u2019approvazione del preliminare di Piano Urbanistico Comunale (PUC) &#8211; Avviso e questionario"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6","name":"robertozanna","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","caption":"robertozanna"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/robertozanna\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=3290"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3290\/revisions"}],"predecessor-version":[{"id":3292,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3290\/revisions\/3292"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=3290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=3290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=3290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}