{"id":3631,"date":"2020-12-22T17:23:48","date_gmt":"2020-12-22T15:23:48","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=3631"},"modified":"2020-12-22T17:23:48","modified_gmt":"2020-12-22T15:23:48","slug":"al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/","title":{"rendered":"Al Foscolo di Sparanise arriva &#8220;Relazioni internazionali per il Marketing&#8221; con potenziamento linguistico."},"content":{"rendered":"<p>(PM) Non solo il Liceo Classico ed il Liceo Linguistico con la presenza del docente madrelingua, all&#8217;Isiss Foscolo di Teano e Sparanise, quest&#8217;anno sono attese molte iscrizioni anche all\u2019indirizzo \u201cRelazioni Internazionali per il Marketing\u201d, un indirizzo al passo con i tempi, aperto all\u2019Europa, che prevede tra l\u2019altro, lo studio di tre lingue straniere (inglese, francese e spagnolo) ma anche Informatica e materie come \u201cRelazioni internazionali\u201d, \u201cTecnologie della comunicazione\u201d e \u201cGeopolitica\u201d. Un liceo che non dimentica\u00a0 la Matematica, il Diritto, l\u2019Economia, l\u2019Economia Aziendale, la Fisica, la Chimica, la Biologia e le Scienze della terra, ma \u00e8 aperto ad una visione internazionale. Dopo l\u2019Indirizzo Tuiristico e il Liceo Linguistico, quindi, ancora un indirizzo che guarda oltre i confini dell\u2019Italia, per far avere agli studenti le competenze necessarie per un profilo di carattere \u201cinternazionale\u201d. Sia l&#8217;indirizzo \u201cRelazioni internazionali per il Marketing\u201d che quello linguistico e Turistico infatti, quest&#8217;anno prevedono un potenziamento della formazione linguistica con la presenza del lettore madrelingua e lo studio di tre lingue; inglese,\u00a0 francese e spagnolo. E&#8217;\u00a0 cresciuta quindi\u00a0 l&#8217;offerta formativa all&#8217;Istituto \u201cFoscolo\u201d di Teano e Sparanise e\u00a0 dal prossimo anno scolastico nelle due sedi di Teano e Sparanise, oltre al Liceo Scientifico e Classico Biomedico, al Liceo delle Scienze Umane e al liceo delle Scienze Applicate, ci saranno anche\u00a0 il Liceo Linguistico, il Liceo delle Scienze Umane con indirizzo Economico Sociale e l\u2019indirizzo \u201cRelazioni Internazionali per il Marketing\u201d.\u00a0 Il Liceo Linguistico, l\u2019indirizzo Turismo e Relazioni internazionali per il Markerting,\u00a0 spiega il preside Paolo Mesolella,\u00a0 sono gi\u00e0 attivi da tre anni e ad essi \u00e8 possibile iscriversi dal 3 gennaio prossimo. Essi prevedono quali insegnamenti obbligatori di indirizzo, le lingue straniere, le Relazioni internazionali e la Geopolitica: Inglese, Francese, Spagnolo, Informatica, Diritto Internazionale, Geopolitica, Tecologia della Comunicazione, Matematica e Fisica, Biologia, Chimica e Scienze della Terra, Economia, Economia aziendale ed altre materie ancora per un totale di 32 ore settimanali. Gli studenti durante il percorso di studio\u00a0 acquisiranno conoscenze nelle lingue straniere corrispondenti al livello B2 del quadro comune europeo; e parteciperanno a viaggi di studio e a stage linguistici a Londra, Malta, Parigi e Spagna.\u00a0 \u201cLa presenza dell\u2019indirizzo \u201cRelazioni internazionali per il Marketing\u201d, insieme ai due indirizzi del Turismo e del Liceo Linguistico, nella nostra scuola, &#8211; spiega il preside del Foscolo, prof. Paolo Mesolella, assume una particolare importanza in un bacino di utenza che comprende i comuni di Teano,\u00a0 Raccomonfina, Pignataro Maggiore, Sparanise, Calvi Risorta, Francolise, Giano Vetusto, Camigliano, Pastorano e Vitulazio configurandosi come oggettivo ampliamento dell\u2019offerta formativa verso l\u2019internazionalizzazione e l\u2019informatizzazione dei servizi con particolare riferimento all\u2019e-commerce, alle lingue straniere, alla comunicazione, all\u2019informatica, alle tecniche di trasformazione, conservazione e commercializzazione dei prodotti, ai mercati dei prodotti assicurativi e finanziari. Un percorso, insomma, da Scuole 2.0.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(PM) Non solo il Liceo Classico ed il Liceo Linguistico con la presenza del docente madrelingua, all&#8217;Isiss Foscolo di Teano e Sparanise, quest&#8217;anno sono attese molte iscrizioni anche all\u2019indirizzo \u201cRelazioni [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":3632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-3631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al Foscolo di Sparanise arriva &quot;Relazioni internazionali per il Marketing&quot; con potenziamento linguistico. - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al Foscolo di Sparanise arriva &quot;Relazioni internazionali per il Marketing&quot; con potenziamento linguistico. - Sparanise\" \/>\n<meta property=\"og:description\" content=\"(PM) Non solo il Liceo Classico ed il Liceo Linguistico con la presenza del docente madrelingua, all&#8217;Isiss Foscolo di Teano e Sparanise, quest&#8217;anno sono attese molte iscrizioni anche all\u2019indirizzo \u201cRelazioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-22T15:23:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/12\/Relazioni-internazionali-per-il-Marketing.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"558\" \/>\n\t<meta property=\"og:image:height\" content=\"221\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"paolomesolella\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"paolomesolella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/\"},\"author\":{\"name\":\"paolomesolella\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\"},\"headline\":\"Al Foscolo di Sparanise arriva &#8220;Relazioni internazionali per il Marketing&#8221; con potenziamento linguistico.\",\"datePublished\":\"2020-12-22T15:23:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/\"},\"wordCount\":474,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2020\\\/12\\\/Relazioni-internazionali-per-il-Marketing.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/\",\"name\":\"Al Foscolo di Sparanise arriva \\\"Relazioni internazionali per il Marketing\\\" con potenziamento linguistico. - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2020\\\/12\\\/Relazioni-internazionali-per-il-Marketing.jpg\",\"datePublished\":\"2020-12-22T15:23:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2020\\\/12\\\/Relazioni-internazionali-per-il-Marketing.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2020\\\/12\\\/Relazioni-internazionali-per-il-Marketing.jpg\",\"width\":558,\"height\":221},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2020\\\/12\\\/22\\\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al Foscolo di Sparanise arriva &#8220;Relazioni internazionali per il Marketing&#8221; con potenziamento linguistico.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\",\"name\":\"paolomesolella\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"caption\":\"paolomesolella\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/paolomesolella\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al Foscolo di Sparanise arriva \"Relazioni internazionali per il Marketing\" con potenziamento linguistico. - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/","og_locale":"it_IT","og_type":"article","og_title":"Al Foscolo di Sparanise arriva \"Relazioni internazionali per il Marketing\" con potenziamento linguistico. - Sparanise","og_description":"(PM) Non solo il Liceo Classico ed il Liceo Linguistico con la presenza del docente madrelingua, all&#8217;Isiss Foscolo di Teano e Sparanise, quest&#8217;anno sono attese molte iscrizioni anche all\u2019indirizzo \u201cRelazioni [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/","og_site_name":"Sparanise","article_published_time":"2020-12-22T15:23:48+00:00","og_image":[{"width":558,"height":221,"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/12\/Relazioni-internazionali-per-il-Marketing.jpg","type":"image\/jpeg"}],"author":"paolomesolella","twitter_misc":{"Scritto da":"paolomesolella","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/"},"author":{"name":"paolomesolella","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c"},"headline":"Al Foscolo di Sparanise arriva &#8220;Relazioni internazionali per il Marketing&#8221; con potenziamento linguistico.","datePublished":"2020-12-22T15:23:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/"},"wordCount":474,"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/12\/Relazioni-internazionali-per-il-Marketing.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/","url":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/","name":"Al Foscolo di Sparanise arriva \"Relazioni internazionali per il Marketing\" con potenziamento linguistico. - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/12\/Relazioni-internazionali-per-il-Marketing.jpg","datePublished":"2020-12-22T15:23:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/#primaryimage","url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/12\/Relazioni-internazionali-per-il-Marketing.jpg","contentUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2020\/12\/Relazioni-internazionali-per-il-Marketing.jpg","width":558,"height":221},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2020\/12\/22\/al-foscolo-di-sparanise-arriva-relazioni-internazionali-per-il-marketing-con-potenziamento-linguistico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Al Foscolo di Sparanise arriva &#8220;Relazioni internazionali per il Marketing&#8221; con potenziamento linguistico."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c","name":"paolomesolella","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","caption":"paolomesolella"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/paolomesolella\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=3631"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3631\/revisions"}],"predecessor-version":[{"id":3633,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3631\/revisions\/3633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media\/3632"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=3631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=3631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=3631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}