{"id":3746,"date":"2021-03-11T14:48:48","date_gmt":"2021-03-11T12:48:48","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=3746"},"modified":"2021-03-11T14:48:48","modified_gmt":"2021-03-11T12:48:48","slug":"raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/","title":{"rendered":"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista"},"content":{"rendered":"<p>Si rende noto che fino al 31 Marzo, presso l&#8217;Ufficio Anagrafe del Comune di Sparanise, \u00e8 possibile firmare a favore del progetto di legge di iniziativa popolare contro la propaganda fascista e nazista, nei seguenti orari: Luned\u00ec dalle ore 9,00 alle ore 13,00 e Gioved\u00ec dalle ore 15,00 alle ore 17,30<\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3747\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/Locandina-A4-Legge-Antifascista-PDF-per-stampa.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/Locandina-A4-Legge-Antifascista-PDF-per-stampa.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Locandina A4 Legge Antifascista PDF per stampa<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si rende noto che fino al 31 Marzo, presso l&#8217;Ufficio Anagrafe del Comune di Sparanise, \u00e8 possibile firmare a favore del progetto di legge di iniziativa popolare contro la propaganda [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":3748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Si rende noto che fino al 31 Marzo, presso l&#8217;Ufficio Anagrafe del Comune di Sparanise, \u00e8 possibile firmare a favore del progetto di legge di iniziativa popolare contro la propaganda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-11T12:48:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/raccolta-firma.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"robertozanna\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"robertozanna\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/\"},\"author\":{\"name\":\"robertozanna\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\"},\"headline\":\"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista\",\"datePublished\":\"2021-03-11T12:48:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/\"},\"wordCount\":59,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/03\\\/raccolta-firma.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/\",\"name\":\"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/03\\\/raccolta-firma.png\",\"datePublished\":\"2021-03-11T12:48:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/03\\\/raccolta-firma.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/03\\\/raccolta-firma.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2021\\\/03\\\/11\\\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\",\"name\":\"robertozanna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"caption\":\"robertozanna\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/robertozanna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/","og_locale":"it_IT","og_type":"article","og_title":"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista - Sparanise","og_description":"Si rende noto che fino al 31 Marzo, presso l&#8217;Ufficio Anagrafe del Comune di Sparanise, \u00e8 possibile firmare a favore del progetto di legge di iniziativa popolare contro la propaganda [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/","og_site_name":"Sparanise","article_published_time":"2021-03-11T12:48:48+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/raccolta-firma.png","type":"image\/png"}],"author":"robertozanna","twitter_misc":{"Scritto da":"robertozanna"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/"},"author":{"name":"robertozanna","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6"},"headline":"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista","datePublished":"2021-03-11T12:48:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/"},"wordCount":59,"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/raccolta-firma.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/","url":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/","name":"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/raccolta-firma.png","datePublished":"2021-03-11T12:48:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/#primaryimage","url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/raccolta-firma.png","contentUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2021\/03\/raccolta-firma.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2021\/03\/11\/raccolta-firme-per-proposta-di-legge-popolare-contro-la-propaganda-fascista-e-nazista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Raccolta firme per proposta di legge popolare contro la propaganda fascista e nazista"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6","name":"robertozanna","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","caption":"robertozanna"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/robertozanna\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=3746"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3746\/revisions"}],"predecessor-version":[{"id":3749,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/3746\/revisions\/3749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media\/3748"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=3746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=3746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=3746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}