{"id":4062,"date":"2022-01-11T17:04:38","date_gmt":"2022-01-11T15:04:38","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=4062"},"modified":"2022-01-11T17:04:38","modified_gmt":"2022-01-11T15:04:38","slug":"comunicazione-revoca-ordinanza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/","title":{"rendered":"Comunicazione revoca Ordinanza"},"content":{"rendered":"<p>Come \u00e8 noto nella giornata di ieri ho provveduto alla chiusura delle scuole le cui motivazioni sono elencate nell\u2019ordinanza. E\u2019 pervenuta al protocollo del comune, in data odierna, comunicazione da parte della Prefettura indirizzata a tutti i Sindaci della Provincia con invito a revocare eventuali ordinanze di chiusura delle scuole .<\/p>\n<p>In ottemperanza a tale disposizione comunico che da qui a poco provveder\u00f2 alla revoca dell\u2019 ordinanza di cui in premessa e che , quindi,\u00a0 gioved\u00ec 13 corrente mese l\u2019attivit\u00e0 didattica riprender\u00e0 normalmente, fatta eccezione dei servizi per l\u2019infanzia (6\/36 mesi) che rimarr\u00e0 chiusa fino al 29\/01\/2022.<\/p>\n<p>Il Sindaco F.F.<\/p>\n<p>Vitaliano Ferrara<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come \u00e8 noto nella giornata di ieri ho provveduto alla chiusura delle scuole le cui motivazioni sono elencate nell\u2019ordinanza. E\u2019 pervenuta al protocollo del comune, in data odierna, comunicazione da [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-4062","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicazione revoca Ordinanza - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicazione revoca Ordinanza - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Come \u00e8 noto nella giornata di ieri ho provveduto alla chiusura delle scuole le cui motivazioni sono elencate nell\u2019ordinanza. E\u2019 pervenuta al protocollo del comune, in data odierna, comunicazione da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T15:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"robertozanna\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"robertozanna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/\"},\"author\":{\"name\":\"robertozanna\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\"},\"headline\":\"Comunicazione revoca Ordinanza\",\"datePublished\":\"2022-01-11T15:04:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/\"},\"wordCount\":103,\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/\",\"name\":\"Comunicazione revoca Ordinanza - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"datePublished\":\"2022-01-11T15:04:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2022\\\/01\\\/11\\\/comunicazione-revoca-ordinanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicazione revoca Ordinanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/11b0f80322dfce9f35cdf5a1aecd14d6\",\"name\":\"robertozanna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g\",\"caption\":\"robertozanna\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/robertozanna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicazione revoca Ordinanza - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/","og_locale":"it_IT","og_type":"article","og_title":"Comunicazione revoca Ordinanza - Sparanise","og_description":"Come \u00e8 noto nella giornata di ieri ho provveduto alla chiusura delle scuole le cui motivazioni sono elencate nell\u2019ordinanza. E\u2019 pervenuta al protocollo del comune, in data odierna, comunicazione da [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/","og_site_name":"Sparanise","article_published_time":"2022-01-11T15:04:38+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png","height":600,"width":1200,"type":""}],"author":"robertozanna","twitter_misc":{"Scritto da":"robertozanna","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/"},"author":{"name":"robertozanna","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6"},"headline":"Comunicazione revoca Ordinanza","datePublished":"2022-01-11T15:04:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/"},"wordCount":103,"articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/","url":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/","name":"Comunicazione revoca Ordinanza - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"datePublished":"2022-01-11T15:04:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2022\/01\/11\/comunicazione-revoca-ordinanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Comunicazione revoca Ordinanza"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/11b0f80322dfce9f35cdf5a1aecd14d6","name":"robertozanna","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3525d2f74225bf36043d6bf402050c2979f3303dca0bd2d7fe7a0f5727f49a84?s=96&d=mm&r=g","caption":"robertozanna"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/robertozanna\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/4062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=4062"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/4062\/revisions"}],"predecessor-version":[{"id":4063,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/4062\/revisions\/4063"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=4062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=4062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=4062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}