{"id":574,"date":"2015-05-07T14:37:22","date_gmt":"2015-05-07T14:37:22","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=574"},"modified":"2015-05-08T16:46:15","modified_gmt":"2015-05-08T16:46:15","slug":"isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/","title":{"rendered":"ISISS GALILEI &#8211; FOSCOLO Circolare n. 59 del 7 maggio 2015"},"content":{"rendered":"<p style=\"text-align: justify;\">Circolare n. 59 Ai docenti, ai genitori, agli studenti, all&#8217;albo on line, a ComunicaCity ODG<\/p>\n<ol>\n<li style=\"text-align: justify;\">12 maggio 2015 Somministrazione Prove Invalsi.<\/li>\n<li style=\"text-align: justify;\">Credenziali Rete Wi-fi di Istituto: consegna codice d\u2019accesso.<\/li>\n<li style=\"text-align: justify;\">Partecipazione allo spettacolo teatrale dell&#8217;associazione I Liberi di Teano.<\/li>\n<li style=\"text-align: justify;\">Il Foscolo alla premiazione del XII Premio don Peppe Diana a Pinetamare, venerd\u00ec 8 maggio<\/li>\n<li style=\"text-align: justify;\">Vincenzo Luca Coppola vince il Premio Marinelli della Societ\u00e0 Dante Alighieri<\/li>\n<li style=\"text-align: justify;\">Il 17 e 18 maggio la classe 5^A LS parteciper\u00e0 alle finali dell&#8217;High School Game a Civitavecchia<\/li>\n<li style=\"text-align: justify;\">15 e 19 maggio Orientamento Universitario E-Campus e Universit\u00e0 Suor Orsola Benincasa<\/li>\n<li style=\"text-align: justify;\">23 maggio 2015. Marcia per la Pace con Agnese Ginocchio, Premio Borsellino<\/li>\n<li style=\"text-align: justify;\">Consegna notizie e foto sui progetti Pon, di Istituto, di classe e i premi, entro sabato 16 maggio<\/li>\n<\/ol>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_575\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/05\/Circolare-n.-59-Teano-Proove-Invalsi.doc\" onclick=\"window.open('https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/05\/Circolare-n.-59-Teano-Proove-Invalsi.doc', '_system'); return false;\"><i class='icon attachment'><\/i>Circolare n. 59  Teano  Proove Invalsi<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Circolare n. 59 Ai docenti, ai genitori, agli studenti, all&#8217;albo on line, a ComunicaCity ODG 12 maggio 2015 Somministrazione Prove Invalsi. Credenziali Rete Wi-fi di Istituto: consegna codice d\u2019accesso. Partecipazione [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-574","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ISISS GALILEI - FOSCOLO Circolare n. 59 del 7 maggio 2015 - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ISISS GALILEI - FOSCOLO Circolare n. 59 del 7 maggio 2015 - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Circolare n. 59 Ai docenti, ai genitori, agli studenti, all&#8217;albo on line, a ComunicaCity ODG 12 maggio 2015 Somministrazione Prove Invalsi. Credenziali Rete Wi-fi di Istituto: consegna codice d\u2019accesso. Partecipazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-07T14:37:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-08T16:46:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"paolomesolella\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"paolomesolella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/\"},\"author\":{\"name\":\"paolomesolella\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\"},\"headline\":\"ISISS GALILEI &#8211; FOSCOLO Circolare n. 59 del 7 maggio 2015\",\"datePublished\":\"2015-05-07T14:37:22+00:00\",\"dateModified\":\"2015-05-08T16:46:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/\"},\"wordCount\":121,\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/\",\"name\":\"ISISS GALILEI - FOSCOLO Circolare n. 59 del 7 maggio 2015 - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"datePublished\":\"2015-05-07T14:37:22+00:00\",\"dateModified\":\"2015-05-08T16:46:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/07\\\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ISISS GALILEI &#8211; FOSCOLO Circolare n. 59 del 7 maggio 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/083c03a9239de65458d244a851b4206c\",\"name\":\"paolomesolella\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g\",\"caption\":\"paolomesolella\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/paolomesolella\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ISISS GALILEI - FOSCOLO Circolare n. 59 del 7 maggio 2015 - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/","og_locale":"it_IT","og_type":"article","og_title":"ISISS GALILEI - FOSCOLO Circolare n. 59 del 7 maggio 2015 - Sparanise","og_description":"Circolare n. 59 Ai docenti, ai genitori, agli studenti, all&#8217;albo on line, a ComunicaCity ODG 12 maggio 2015 Somministrazione Prove Invalsi. Credenziali Rete Wi-fi di Istituto: consegna codice d\u2019accesso. Partecipazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/","og_site_name":"Sparanise","article_published_time":"2015-05-07T14:37:22+00:00","article_modified_time":"2015-05-08T16:46:15+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png","height":600,"width":1200,"type":""}],"author":"paolomesolella","twitter_misc":{"Scritto da":"paolomesolella","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/"},"author":{"name":"paolomesolella","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c"},"headline":"ISISS GALILEI &#8211; FOSCOLO Circolare n. 59 del 7 maggio 2015","datePublished":"2015-05-07T14:37:22+00:00","dateModified":"2015-05-08T16:46:15+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/"},"wordCount":121,"articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/","url":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/","name":"ISISS GALILEI - FOSCOLO Circolare n. 59 del 7 maggio 2015 - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"datePublished":"2015-05-07T14:37:22+00:00","dateModified":"2015-05-08T16:46:15+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/07\/isiss-galilei-foscolo-circolare-n-59-del-7-maggio-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"ISISS GALILEI &#8211; FOSCOLO Circolare n. 59 del 7 maggio 2015"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/083c03a9239de65458d244a851b4206c","name":"paolomesolella","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69936852c9725ed948cb0f6c2c2daed14b5100416770d894f57fc7e5c6de8dec?s=96&d=mm&r=g","caption":"paolomesolella"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/paolomesolella\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=574"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/574\/revisions"}],"predecessor-version":[{"id":586,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/574\/revisions\/586"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}