{"id":616,"date":"2015-05-17T13:03:35","date_gmt":"2015-05-17T13:03:35","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=616"},"modified":"2015-05-17T13:03:35","modified_gmt":"2015-05-17T13:03:35","slug":"elezione-vice-presidente-consiglio-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/","title":{"rendered":"Elezione vice presidente consiglio comunale"},"content":{"rendered":"<p>Nella riunione di consiglio comunale del 14\\5\\15 \u00e8 stata eletta, come da regolamento , alla carica di vice presidente dell&#8217;assemblea l&#8217;avv. Assunata Zona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella riunione di consiglio comunale del 14\\5\\15 \u00e8 stata eletta, come da regolamento , alla carica di vice presidente dell&#8217;assemblea l&#8217;avv. Assunata Zona.<\/p>\n","protected":false},"author":39,"featured_media":215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezione vice presidente consiglio comunale - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezione vice presidente consiglio comunale - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Nella riunione di consiglio comunale del 14515 \u00e8 stata eletta, come da regolamento , alla carica di vice presidente dell&#8217;assemblea l&#8217;avv. Assunata Zona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-17T13:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/LOGO-COMUNE-DI-SPARANISE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antoniomerola\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antoniomerola\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/\"},\"author\":{\"name\":\"antoniomerola\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\"},\"headline\":\"Elezione vice presidente consiglio comunale\",\"datePublished\":\"2015-05-17T13:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/\"},\"wordCount\":25,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/03\\\/LOGO-COMUNE-DI-SPARANISE.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/\",\"name\":\"Elezione vice presidente consiglio comunale - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/03\\\/LOGO-COMUNE-DI-SPARANISE.jpg\",\"datePublished\":\"2015-05-17T13:03:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/03\\\/LOGO-COMUNE-DI-SPARANISE.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/03\\\/LOGO-COMUNE-DI-SPARANISE.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/05\\\/17\\\/elezione-vice-presidente-consiglio-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezione vice presidente consiglio comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\",\"name\":\"antoniomerola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"caption\":\"antoniomerola\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/antoniomerola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezione vice presidente consiglio comunale - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Elezione vice presidente consiglio comunale - Sparanise","og_description":"Nella riunione di consiglio comunale del 14515 \u00e8 stata eletta, come da regolamento , alla carica di vice presidente dell&#8217;assemblea l&#8217;avv. Assunata Zona.","og_url":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/","og_site_name":"Sparanise","article_published_time":"2015-05-17T13:03:35+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/LOGO-COMUNE-DI-SPARANISE.jpg","type":"image\/jpeg"}],"author":"antoniomerola","twitter_misc":{"Scritto da":"antoniomerola"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/"},"author":{"name":"antoniomerola","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8"},"headline":"Elezione vice presidente consiglio comunale","datePublished":"2015-05-17T13:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/"},"wordCount":25,"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/LOGO-COMUNE-DI-SPARANISE.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/","url":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/","name":"Elezione vice presidente consiglio comunale - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/LOGO-COMUNE-DI-SPARANISE.jpg","datePublished":"2015-05-17T13:03:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/#primaryimage","url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/LOGO-COMUNE-DI-SPARANISE.jpg","contentUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/03\/LOGO-COMUNE-DI-SPARANISE.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/05\/17\/elezione-vice-presidente-consiglio-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Elezione vice presidente consiglio comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8","name":"antoniomerola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","caption":"antoniomerola"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/antoniomerola\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=616"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/616\/revisions"}],"predecessor-version":[{"id":617,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/616\/revisions\/617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media\/215"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}