{"id":773,"date":"2015-06-29T10:23:08","date_gmt":"2015-06-29T10:23:08","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?p=773"},"modified":"2015-06-29T10:23:08","modified_gmt":"2015-06-29T10:23:08","slug":"carenza-idrica-7","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/","title":{"rendered":"Carenza idrica"},"content":{"rendered":"<p style=\"text-align: justify\">Causa guasto all&#8217;impianto idrico regionale sulla provinciale per Calvi Risorta si avr\u00e0 carenza idrica nei prossimi giorni. Per eventuali esigenze i cittadini sono pregati di rivolgersi ai vigili. \u00a0Sul luogo del guasto gi\u00e0 si sta provvedendo alla riparazione. Ulteriori novit\u00e0 saranno comunicate con lo stesso mezzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Causa guasto all&#8217;impianto idrico regionale sulla provinciale per Calvi Risorta si avr\u00e0 carenza idrica nei prossimi giorni. Per eventuali esigenze i cittadini sono pregati di rivolgersi ai vigili. \u00a0Sul luogo [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":35,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carenza idrica - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carenza idrica - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Causa guasto all&#8217;impianto idrico regionale sulla provinciale per Calvi Risorta si avr\u00e0 carenza idrica nei prossimi giorni. Per eventuali esigenze i cittadini sono pregati di rivolgersi ai vigili. \u00a0Sul luogo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-29T10:23:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Fontana-Beatrice.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antoniomerola\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antoniomerola\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/\"},\"author\":{\"name\":\"antoniomerola\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\"},\"headline\":\"Carenza idrica\",\"datePublished\":\"2015-06-29T10:23:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/\"},\"wordCount\":48,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Fontana-Beatrice.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/\",\"name\":\"Carenza idrica - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Fontana-Beatrice.jpg\",\"datePublished\":\"2015-06-29T10:23:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Fontana-Beatrice.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2015\\\/02\\\/Sparanise-Fontana-Beatrice.jpg\",\"width\":398,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/2015\\\/06\\\/29\\\/carenza-idrica-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carenza idrica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#\\\/schema\\\/person\\\/491a00563a4847abff6244c645c7a2f8\",\"name\":\"antoniomerola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g\",\"caption\":\"antoniomerola\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/author\\\/antoniomerola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carenza idrica - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/","og_locale":"it_IT","og_type":"article","og_title":"Carenza idrica - Sparanise","og_description":"Causa guasto all&#8217;impianto idrico regionale sulla provinciale per Calvi Risorta si avr\u00e0 carenza idrica nei prossimi giorni. Per eventuali esigenze i cittadini sono pregati di rivolgersi ai vigili. \u00a0Sul luogo [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/","og_site_name":"Sparanise","article_published_time":"2015-06-29T10:23:08+00:00","og_image":[{"width":398,"height":400,"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Fontana-Beatrice.jpg","type":"image\/jpeg"}],"author":"antoniomerola","twitter_misc":{"Scritto da":"antoniomerola"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/"},"author":{"name":"antoniomerola","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8"},"headline":"Carenza idrica","datePublished":"2015-06-29T10:23:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/"},"wordCount":48,"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Fontana-Beatrice.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/","url":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/","name":"Carenza idrica - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Fontana-Beatrice.jpg","datePublished":"2015-06-29T10:23:08+00:00","author":{"@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/#primaryimage","url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Fontana-Beatrice.jpg","contentUrl":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/Sparanise-Fontana-Beatrice.jpg","width":398,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/2015\/06\/29\/carenza-idrica-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Carenza idrica"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sparanise\/#\/schema\/person\/491a00563a4847abff6244c645c7a2f8","name":"antoniomerola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd68312eba96dcaf81b102671f65a81a43422a59e9774694b88d1e8e6fd85269?s=96&d=mm&r=g","caption":"antoniomerola"},"url":"https:\/\/comunicacity.net\/sparanise\/author\/antoniomerola\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/comments?post=773"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/773\/revisions"}],"predecessor-version":[{"id":774,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/posts\/773\/revisions\/774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media\/35"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/categories?post=773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/tags?post=773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}