{"id":1621,"date":"2016-08-01T12:51:36","date_gmt":"2016-08-01T10:51:36","guid":{"rendered":"https:\/\/comunicacity.net\/sparanise\/?post_type=rdif&#038;p=1621"},"modified":"2016-08-01T12:51:53","modified_gmt":"2016-08-01T10:51:53","slug":"oli-vegetali-esauriti","status":"publish","type":"rdif","link":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/","title":{"rendered":"Oli vegetali esauriti"},"content":{"rendered":"<div class=\"ccCenter\">\n   <span class=\"fa-stack fa-4x\"><i class=\"fa fa-circle fa-stack-2x ccGreen\"><\/i><i class=\"fa fa-tint fa-stack-1x fa-inverse\"><\/i><\/span>\n<\/div>\n<h3 class=\"ccGreen ccCenter\">Contenitore a campana<\/h3>\n<h4>\n    <i class=\"fa fa-thumbs-up fa-2x ccDarkGreen\"><\/i> <b>Cosa depositare<\/b><br \/>\n<\/h4>\n<p class=\"ccJustify\">Oli vegetali esauriti.<\/p>\n<p class=\"ccJustify\">L&#8217;olio va sversato nelle due campane ubicate in <b>viale delle Medaglie d&#8217;Oro<\/b> (nei pressi del palazzetto dell Sport) e in <b>via le Castagne<\/b> (nei pressi dell&#8217;ufficio postale).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contenitore a campana Cosa depositare Oli vegetali esauriti. L&#8217;olio va sversato nelle due campane ubicate in viale delle Medaglie d&#8217;Oro (nei pressi del palazzetto dell Sport) e in via le [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":1613,"menu_order":4,"template":"","meta":[],"class_list":["post-1621","rdif","type-rdif","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oli vegetali esauriti - Sparanise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oli vegetali esauriti - Sparanise\" \/>\n<meta property=\"og:description\" content=\"Contenitore a campana Cosa depositare Oli vegetali esauriti. L&#8217;olio va sversato nelle due campane ubicate in viale delle Medaglie d&#8217;Oro (nei pressi del palazzetto dell Sport) e in via le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/\" \/>\n<meta property=\"og:site_name\" content=\"Sparanise\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-01T10:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/sparanise.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/rdif\\\/info-utili\\\/oli-vegetali-esauriti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/rdif\\\/info-utili\\\/oli-vegetali-esauriti\\\/\",\"name\":\"Oli vegetali esauriti - Sparanise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\"},\"datePublished\":\"2016-08-01T10:51:36+00:00\",\"dateModified\":\"2016-08-01T10:51:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/rdif\\\/info-utili\\\/oli-vegetali-esauriti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/rdif\\\/info-utili\\\/oli-vegetali-esauriti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/rdif\\\/info-utili\\\/oli-vegetali-esauriti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Info Utili\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/rdif\\\/info-utili\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oli vegetali esauriti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/\",\"name\":\"Sparanise\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sparanise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oli vegetali esauriti - Sparanise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/","og_locale":"it_IT","og_type":"article","og_title":"Oli vegetali esauriti - Sparanise","og_description":"Contenitore a campana Cosa depositare Oli vegetali esauriti. L&#8217;olio va sversato nelle due campane ubicate in viale delle Medaglie d&#8217;Oro (nei pressi del palazzetto dell Sport) e in via le [&hellip;]","og_url":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/","og_site_name":"Sparanise","article_modified_time":"2016-08-01T10:51:53+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sparanise\/wp-content\/uploads\/sites\/23\/2015\/02\/sparanise.jpg","height":50,"width":50,"type":""}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/","url":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/","name":"Oli vegetali esauriti - Sparanise","isPartOf":{"@id":"https:\/\/comunicacity.net\/sparanise\/#website"},"datePublished":"2016-08-01T10:51:36+00:00","dateModified":"2016-08-01T10:51:53+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/oli-vegetali-esauriti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sparanise\/"},{"@type":"ListItem","position":2,"name":"Info Utili","item":"https:\/\/comunicacity.net\/sparanise\/rdif\/info-utili\/"},{"@type":"ListItem","position":3,"name":"Oli vegetali esauriti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sparanise\/#website","url":"https:\/\/comunicacity.net\/sparanise\/","name":"Sparanise","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sparanise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/rdif\/1621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/rdif"}],"about":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/types\/rdif"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/rdif\/1613"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sparanise\/wp-json\/wp\/v2\/media?parent=1621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}