{"id":10110,"date":"2023-02-23T14:18:40","date_gmt":"2023-02-23T13:18:40","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10110"},"modified":"2023-02-23T14:18:40","modified_gmt":"2023-02-23T13:18:40","slug":"sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/","title":{"rendered":"&#8220;Sogno Festival&#8221;: fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori"},"content":{"rendered":"<p>In occasione della fase conclusiva del Carnevale prende avvio a Tivoli alle Scuderie Estensi, \u2018<strong>Sogno Festival<\/strong>\u2019, Festival multidisciplinare e multimediale dedicato alla fiaba, all\u2019insegna della contaminazione tra le arti (teatro, letteratura, cinema, musica).<\/p>\n<p>\u2018Sogno Festival\u2019 \u00e8 promosso da Associazione Ariadne \u2013 Compagnia Teatro A e si avvale del contributo della Regione Lazio, previsto dal bando di Lazio Crea a sostegno delle attivit\u00e0 di valorizzazione e promozione del territorio regionale. Ha il patrocinio della Reale Ambasciata di Danimarca (Roma) e del Comune di Tivoli.<\/p>\n<p>Il Festival \u00e8 realizzato in collaborazione con Associazione MTKproject A.P.S., Associazione Danz\u2019Arte, Casa editrice \u201cAlbero delle Matite\u201d.<\/p>\n<p>La direzione artistica \u00e8 affidata alla regista\u00a0<strong>Valeria Freiberg.<\/strong><\/p>\n<p>Il programma della rassegna prevede spettacoli, laboratori creativi, mostre, incontri, presentazioni di libri ed installazioni audiovisive: l\u2019azione creativa punta alla commistione tra linguaggi artistici ma anche tra arte e tecnologia.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Questi gli appuntamenti a Tivoli alle Scuderie Estensi:<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<strong>Lo specchio magico<\/strong>\u201d. Ogni favola che si rispetti ha uno specchio da interrogare e per guardare il mondo con occhi diversi. E allora spazio a spettacoli, performane, incontri con gli artisti, uscendo dagli schemi. Spazio viene dedicato alle ricerche nell&#8217;ambito di soundrama, dramma plastico, video installazioni.<\/p>\n<p>Gli spettacoli sono \u201c<em>La Regina delle Nevi<\/em>\u201d e \u201c<em>La principessa sul pisello<\/em>\u201d (21 febbraio), \u201c<em>Grimmrock<\/em>\u201d ed \u201c<em>Il tenace soldatino di stagno<\/em>\u201d (22 febbraio), \u201c<em>Diario dei cattivi consigli<\/em>\u201d e \u201c<em>Il guardiano dei porci<\/em>\u201d (23 febbraio), \u201c<em>La Sirenetta<\/em>\u201d (24 febbraio) e \u201c<em>I vestiti nuovi dell\u2019Imperatore<\/em>\u201d (25 febbraio).<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<strong>La casa di Andersen<\/strong>\u201d: con questa iniziativa si vuole rendere omaggio al grande scrittore danese Hans Christian Andersen (1805-1875), a 190 anni dal suo soggiorno a Roma; si dice che, proprio a Tivoli, nelle Grotte di Villa Gregoriana, Andersen trov\u00f2 ispirazione per la favola de La Sirenetta.<\/p>\n<p>\u201cLa casa di Andersen\u201d, a Sogno Festival, ospiter\u00e0 laboratori e mostre-percorso emozionali e creativi nelle favole dello scrittore danese, con allestimenti video, musicali, illustrativi, ma anche l\u2019angolo dei libri realizzato in collaborazione con la Biblioteca Comunale \u201cM.C.Fornari\u201d, per coinvolgere i pi\u00f9 piccoli.<\/p>\n<p>In evidenza l\u2019affascinante mostra permanente \u201c<em>Il canto delle sirene<\/em>\u201d della biologa-artista Marina Longo, con suggestive ceramiche d\u2019arte dedicate ad Andersen ed alla Sirenetta che ci conduce ai miti del Mediterraneo.<\/p>\n<p>Inoltre, \u201cLa casa di Andersen\u201d apre\u00a0le sue porte agli incontri destinati a docenti, insegnanti di teatro e bibliotecari: il 21 febbraio \u00e8 stata la volta del\u00a0<em>\u201cIl Teatro\u00a0 per scoprire se stessi\u201d,<\/em>\u00a0condotto dall\u2019attrice e pedagoga teatrale Cristina Colonnetti; il 24 febbraio alle ore 18 si terr\u00e0 l\u2019incontro \u201c<em>Come parlare ai ragazzi dell\u2019attualit\u00e0: viaggio nella letteratura da Andersen agli autori contemporanei<\/em>\u201d, curato dall\u2019editrice Carlotta Rindone (casa editrice \u201cAlbero delle Matite\u201d)\u00a0 e dall\u2019autrice Catia Proietti.<\/p>\n<p><strong>Fiabe \u201cper le vie di Ole Lukoie<\/strong>\u201d: sabato 25 febbraio e domenica 26 febbraio sono previsti \u201cIl ballo delle Fiabe\u201d presso le Scuderie e \u201cFiabe di H.C.Andersen per le strade di Ole Lukoje\u201d -incontri letterari e letture ad alta voce lungo le strade e i locali del centro storico di Tivoli. Il personaggio di Andersen, Ole Lukoie (Ole Chiudigliocchi), esce dai libri di fiabe per raggiungere e vitalizzare il centro storico di Tivoli.<\/p>\n<p><strong>Concorso Corti Teatrali scritti dai ragazzi\u00a0<\/strong>(Tivoli). In occasione del Sogno Festival si d\u00e0 l\u2019avvio al concorso a cui potranno partecipare classi e singoli allievi degli Istituti scolastici secondari di primo e secondo grado del Comune di Tivoli e di tutta la Regione Lazio. I 5 migliori corti teatrali, 24 Febbraio, in presenza del pubblico, saranno letti presso le Scuderie Estenso da attori professionisti in forma di lettura drammatizzata. Il corto vincitore verr\u00e0 messo in scena il 10 giugno, sempre a Tivoli, nell\u2019ambito della rassegna teatrale RoccaFest, realizzata anch\u2019essa dall\u2019Associazione Ariadne.<\/p>\n<p>Il programma dettagliato delle iniziative del Sogno Festival ed il bando con le modalit\u00e0 di partecipazione al \u201cConcorso Corti Teatrali scritti dai ragazzi\u201d si possono trovare sul sito\u00a0<a href=\"http:\/\/www.compagniateatroa.it\/\">www.compagniateatroa.it<\/a>.<\/p>\n<p>&#8220;Ci siamo ispirati \u2013 osserva Valeria Freiberg &#8211; alle parole del filosofo tedesco Arthur Schopenhauer: \u2018<em>La vita e i sogni sono pagine di uno stesso libro\u2019<\/em>. L\u2019invito che rivolgiamo a grandi e piccoli \u00e8 di non rinunciare a sognare\u201d.<\/p>\n<p>E-mail\u00a0<a href=\"mailto:ateatro.assariadne@gmail.com\">ateatro.assariadne@gmail.com<\/a><\/p>\n<p>WhatsApp: +39-3714125639<\/p>\n<p>Informazioni su\u00a0<a href=\"http:\/\/www.compagniateatroa.it\/\">www.compagniateatroa.it<\/a><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_10111\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/Cs-SognoFestival-generale.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/Cs-SognoFestival-generale.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>COMUNICATO STAMPA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione della fase conclusiva del Carnevale prende avvio a Tivoli alle Scuderie Estensi, \u2018Sogno Festival\u2019, Festival multidisciplinare e multimediale dedicato alla fiaba, all\u2019insegna della contaminazione tra le arti (teatro, [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Sogno Festival&quot;: fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Sogno Festival&quot;: fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori - Tivoli\" \/>\n<meta property=\"og:description\" content=\"In occasione della fase conclusiva del Carnevale prende avvio a Tivoli alle Scuderie Estensi, \u2018Sogno Festival\u2019, Festival multidisciplinare e multimediale dedicato alla fiaba, all\u2019insegna della contaminazione tra le arti (teatro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-23T13:18:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/SognoFestival-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1448\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;Sogno Festival&#8221;: fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori\",\"datePublished\":\"2023-02-23T13:18:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/\"},\"wordCount\":695,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/02\\\/SognoFestival-1.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/\",\"name\":\"\\\"Sogno Festival\\\": fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/02\\\/SognoFestival-1.jpg\",\"datePublished\":\"2023-02-23T13:18:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/02\\\/SognoFestival-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/02\\\/SognoFestival-1.jpg\",\"width\":1448,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/02\\\/23\\\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Sogno Festival&#8221;: fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Sogno Festival\": fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/","og_locale":"it_IT","og_type":"article","og_title":"\"Sogno Festival\": fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori - Tivoli","og_description":"In occasione della fase conclusiva del Carnevale prende avvio a Tivoli alle Scuderie Estensi, \u2018Sogno Festival\u2019, Festival multidisciplinare e multimediale dedicato alla fiaba, all\u2019insegna della contaminazione tra le arti (teatro, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-02-23T13:18:40+00:00","og_image":[{"width":1448,"height":2048,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/SognoFestival-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;Sogno Festival&#8221;: fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori","datePublished":"2023-02-23T13:18:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/"},"wordCount":695,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/SognoFestival-1.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/","name":"\"Sogno Festival\": fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/SognoFestival-1.jpg","datePublished":"2023-02-23T13:18:40+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/SognoFestival-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/02\/SognoFestival-1.jpg","width":1448,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/02\/23\/sogno-festival-fino-al-26-febbraio-alle-scuderie-estensi-teatro-mostre-e-laboratori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;Sogno Festival&#8221;: fino al 26 febbraio alle Scuderie Estensi teatro, mostre e laboratori"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10110"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10110\/revisions"}],"predecessor-version":[{"id":10114,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10110\/revisions\/10114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10113"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}