{"id":10208,"date":"2023-03-13T14:53:54","date_gmt":"2023-03-13T13:53:54","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10208"},"modified":"2023-03-13T14:53:54","modified_gmt":"2023-03-13T13:53:54","slug":"viabilita-19-marzo-fiera-di-san-giuseppe-2023","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/","title":{"rendered":"Viabilit\u00e0 19 marzo &#8211; Fiera di San Giuseppe 2023"},"content":{"rendered":"<p>Domenica 19 marzo 2023 avr\u00e0 luogo la tradizionale Fiera di San Giuseppe 2023 con numerosi banchi di vendita ed esposizione di prodotti tipici posizionati nelle seguenti vie: PIAZZA DOMENICO TANI, VIA COLSERENO, PIAZZA SAN VINCENZO, LARGO G. BAJA, VIA DEL GOVERNO, PIAZZA DEL COMUNE, PIAZZA DEL GOVERNO, GIARDINO VIA SANTA SINFERUSA (piazzetta fronte Scuola del Ges\u00f9), PIAZZA SABUCCI, VICOLO DEL MELANGOLO, VIA LIONE, VIA MUNAZIO PLANCO, VICOLO TODINI, VIA PARMEGIANI, VIA DI PONTE GREGORIANO, PIAZZA DELLE ERBE, PIAZZA RIVAROLA, VIA PALATINA, PIAZZA PALATINA, PIAZZA DEL PLEBISCITO, VIA SANTE VIOLA, VIA I. MISSONI.<\/p>\n<p>Considerato che, come nelle precedenti edizioni, sar\u00e0 prevedibile una notevole affluenza di persone, con conseguente incremento del traffico veicolare in tutte le strade attigue a quelle interessate dalla fiera, si ordina la modifica dell&#8217;attuale\u00a0regolamentazione stradale nelle\u00a0<strong>zone elencate nell&#8217;ordinanza, in allegato<\/strong>.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_10209\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/fiera.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/fiera.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ORD N 84<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 19 marzo 2023 avr\u00e0 luogo la tradizionale Fiera di San Giuseppe 2023 con numerosi banchi di vendita ed esposizione di prodotti tipici posizionati nelle seguenti vie: PIAZZA DOMENICO TANI, [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10208","post","type-post","status-publish","format-standard","hentry","category-attivita-produttive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viabilit\u00e0 19 marzo - Fiera di San Giuseppe 2023 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viabilit\u00e0 19 marzo - Fiera di San Giuseppe 2023 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Domenica 19 marzo 2023 avr\u00e0 luogo la tradizionale Fiera di San Giuseppe 2023 con numerosi banchi di vendita ed esposizione di prodotti tipici posizionati nelle seguenti vie: PIAZZA DOMENICO TANI, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-13T13:53:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/attivita-produttive.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Viabilit\u00e0 19 marzo &#8211; Fiera di San Giuseppe 2023\",\"datePublished\":\"2023-03-13T13:53:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/\"},\"wordCount\":138,\"articleSection\":[\"Attivit\u00e0 Produttive\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/\",\"name\":\"Viabilit\u00e0 19 marzo - Fiera di San Giuseppe 2023 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-03-13T13:53:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/13\\\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viabilit\u00e0 19 marzo &#8211; Fiera di San Giuseppe 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viabilit\u00e0 19 marzo - Fiera di San Giuseppe 2023 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Viabilit\u00e0 19 marzo - Fiera di San Giuseppe 2023 - Tivoli","og_description":"Domenica 19 marzo 2023 avr\u00e0 luogo la tradizionale Fiera di San Giuseppe 2023 con numerosi banchi di vendita ed esposizione di prodotti tipici posizionati nelle seguenti vie: PIAZZA DOMENICO TANI, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-03-13T13:53:54+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/attivita-produttive.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Viabilit\u00e0 19 marzo &#8211; Fiera di San Giuseppe 2023","datePublished":"2023-03-13T13:53:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/"},"wordCount":138,"articleSection":["Attivit\u00e0 Produttive"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/","name":"Viabilit\u00e0 19 marzo - Fiera di San Giuseppe 2023 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-03-13T13:53:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/13\/viabilita-19-marzo-fiera-di-san-giuseppe-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Viabilit\u00e0 19 marzo &#8211; Fiera di San Giuseppe 2023"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10208"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10208\/revisions"}],"predecessor-version":[{"id":10210,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10208\/revisions\/10210"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}