{"id":10233,"date":"2023-03-17T09:52:48","date_gmt":"2023-03-17T08:52:48","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10233"},"modified":"2023-03-17T09:52:48","modified_gmt":"2023-03-17T08:52:48","slug":"domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/","title":{"rendered":"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene"},"content":{"rendered":"<p>Domenica 19 marzo, durante la Fiera di San Giuseppe e in occasione della terza domenica del mese, si svolger\u00e0 l&#8217;<strong>Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene<\/strong>\u00a0nel cuore della citt\u00e0 di Tivoli in via 2 giugno,\u00a0angolo Piazza Santa Croce, dalle 9,30 alle 19.<\/p>\n<p>Tivoli, la citt\u00e0 della bellezza per le sue VILLAE, per il paesaggio della Villa Gregoriana, per il suo borgo medievale, offre un archeomercato che rispecchia le antiche origini della citt\u00e0 e soprattutto segue i principi della chiocciola, con cibo &#8220;buono, pulito e giusto e sano\u201d.<\/p>\n<p>L&#8217;Archeomercato della Terra non \u00e8 solo\u00a0un &#8220;mercato&#8221; ma una comunit\u00e0 di Terra Madre pronta a trasformare la spesa in un&#8217;esperienza di riconnessione con il ritmo della natura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 19 marzo, durante la Fiera di San Giuseppe e in occasione della terza domenica del mese, si svolger\u00e0 l&#8217;Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene\u00a0nel cuore della [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell&#039;Aniene - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell&#039;Aniene - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Domenica 19 marzo, durante la Fiera di San Giuseppe e in occasione della terza domenica del mese, si svolger\u00e0 l&#8217;Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene\u00a0nel cuore della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T08:52:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/slow-food-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene\",\"datePublished\":\"2023-03-17T08:52:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/\"},\"wordCount\":125,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/03\\\/slow-food-1.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/\",\"name\":\"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell'Aniene - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/03\\\/slow-food-1.jpg\",\"datePublished\":\"2023-03-17T08:52:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/03\\\/slow-food-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/03\\\/slow-food-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/03\\\/17\\\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell'Aniene - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/","og_locale":"it_IT","og_type":"article","og_title":"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell'Aniene - Tivoli","og_description":"Domenica 19 marzo, durante la Fiera di San Giuseppe e in occasione della terza domenica del mese, si svolger\u00e0 l&#8217;Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene\u00a0nel cuore della [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-03-17T08:52:48+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/slow-food-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene","datePublished":"2023-03-17T08:52:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/"},"wordCount":125,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/slow-food-1.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/","name":"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell'Aniene - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/slow-food-1.jpg","datePublished":"2023-03-17T08:52:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/slow-food-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/03\/slow-food-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/03\/17\/domenica-19-marzo-archeomercato-della-terra-di-slowfood-tivoli-e-valle-dellaniene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Domenica 19 marzo Archeomercato della Terra di SlowFood Tivoli e Valle dell&#8217;Aniene"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10233"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10233\/revisions"}],"predecessor-version":[{"id":10235,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10233\/revisions\/10235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10234"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}