{"id":10324,"date":"2023-04-03T11:41:10","date_gmt":"2023-04-03T09:41:10","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10324"},"modified":"2023-04-03T15:08:36","modified_gmt":"2023-04-03T13:08:36","slug":"3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/","title":{"rendered":"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini"},"content":{"rendered":"<p>Mercoled\u00ec 5 aprile ha inizio ufficialmente il Natale di Tivoli, manifestazione che quest&#8217;anno si protrarr\u00e0 fino al 4 giugno. I festeggiamenti del\u00a0<strong>3238\u00b0 compleanno della citt\u00e0<\/strong>, la cui fondazione viene fatta risalire al 5 aprile 1215 a.C., si aprono con un\u00a0<strong>evento inaugurale presso il Museo della Citt\u00e0<\/strong>, in piazza Campitelli e con il conferimento del prestigioso\u00a0<strong>Premio &#8220;Francesco Bulgarini sulla storia di Tivoli&#8221;\u00a0<\/strong>agli alunni <strong>\u00a0<\/strong>presso le Scuderie Estensi.<\/p>\n<p>Protagonisti della mattinata saranno gli allievi delle scuole: la classe II sezione A, indirizzo Aureus (Arte, Tutela, Restauro, Educazione all\u2019uso del Patrimonio Artistico) dell\u2019I.I.S. Publio Elio Adriano di Tivoli presenter\u00e0 un contributo didattico, incentrato su tematiche legate alle origini ed ai miti di Tivoli. Il lavoro degli studenti \u00e8 il prodotto di informazione, studio ed elaborazione di conoscenze approfondite nell\u2019anno scolastico 2021-2022, con la Soprintendenza Archeologia Belle Arti e Paesaggio per l\u2019Area Metropolitana di Roma e per la Provincia di Rieti e la Prof. Maria Rita Lattanzi di Storia dell\u2019Arte.<\/p>\n<p>Le presentazioni curate dagli allievi saranno distribuite nelle quattro aule didattiche del Museo della Citt\u00e0, per ospitare gli studenti di alcune scuole secondarie di primo grado di Tivoli, a partire\u00a0<strong>dalle ore 9.00 fino alle ore 12.00<\/strong>. Gli argomenti trattati saranno: 1. Le origini di Tivoli, 2. Il Mito di Ercole, 3. Il Mito di Anio, 4. La Gens di Tivoli.<\/p>\n<p>Dopo l&#8217;esposizione dei lavori dei ragazzi, sempre in piazza Campitelli\u00a0<strong>Slow Food Tivoli e Valle dell\u2019Aniene<\/strong> condurr\u00e0 i presenti alla scoperta del territorio\u00a0con un approfondimento sui prodotti tipici e sull\u2019educazione alla biodiversit\u00e0.<\/p>\n<p>I festeggiamenti proseguiranno\u00a0poi nel pomeriggio.\u00a0Alle ore 17 presso le Scuderie Estensi, in piazza Garibaldi, si terr\u00e0 la cerimonia conclusiva del\u00a0<strong>Premio &#8220;Francesco Bulgarini sulla storia di Tivoli&#8221;<\/strong>, anno scolastico 2022\/2023, al quale hanno partecipato 486 alunni, di 24 classi quinte di otto scuole primarie statali e parificate del Comune di Tivoli, suddivise in 15 plessi.<\/p>\n<p>La famiglia Bulgarini ha voluto riportare in auge, a partire dall\u2019anno scolastico 2019-20, questo storico progetto educativo e formativo, ritenendo di fondamentale rilevanza il coinvolgimento delle nuove generazioni tiburtine e delle loro famiglie, in modo da alimentare nuovamente la conoscenza, l\u2019orgoglio e la passione per la citt\u00e0 e la sua storia. La consulenza scientifica \u00e8 stata assunta dalla <strong>Societ\u00e0 Tiburtina di Storia e d\u2019Arte<\/strong>.<\/p>\n<p>Ai vincitori (massimo due per ogni classe partecipante al Premio) verranno assegnate medaglie artistiche, coniate per l\u2019occasione, in argento o bronzo con diploma.<\/p>\n<p>A tutti gli alunni delle classi partecipanti sar\u00e0 conferito il diploma nominativo di \u00ab<strong>Sostenitore del patrimonio storico, artistico e naturale di Tivoli<\/strong>\u00bb.<\/p>\n<p><a href=\"https:\/\/comune.tivoli.rm.it\/novita\/notizie\/3238deg-natale-di-tivoli-il-programma-degli-eventi\"><strong>LEGGI IL PROGRAMMA DEL\u00a03238\u00b0 NATALE DI TIVOLI<\/strong><\/a><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_10327\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/DOC-20230401-WA0005.-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/DOC-20230401-WA0005.-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>CERIMONIA INAUGURALE - programma<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 5 aprile ha inizio ufficialmente il Natale di Tivoli, manifestazione che quest&#8217;anno si protrarr\u00e0 fino al 4 giugno. I festeggiamenti del\u00a03238\u00b0 compleanno della citt\u00e0, la cui fondazione viene fatta [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Mercoled\u00ec 5 aprile ha inizio ufficialmente il Natale di Tivoli, manifestazione che quest&#8217;anno si protrarr\u00e0 fino al 4 giugno. I festeggiamenti del\u00a03238\u00b0 compleanno della citt\u00e0, la cui fondazione viene fatta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-03T09:41:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-03T13:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/premio-bulgarini2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"905\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini\",\"datePublished\":\"2023-04-03T09:41:10+00:00\",\"dateModified\":\"2023-04-03T13:08:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/\"},\"wordCount\":433,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/premio-bulgarini2.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/\",\"name\":\"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/premio-bulgarini2.jpg\",\"datePublished\":\"2023-04-03T09:41:10+00:00\",\"dateModified\":\"2023-04-03T13:08:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/premio-bulgarini2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/premio-bulgarini2.jpg\",\"width\":905,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/03\\\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/","og_locale":"it_IT","og_type":"article","og_title":"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini - Tivoli","og_description":"Mercoled\u00ec 5 aprile ha inizio ufficialmente il Natale di Tivoli, manifestazione che quest&#8217;anno si protrarr\u00e0 fino al 4 giugno. I festeggiamenti del\u00a03238\u00b0 compleanno della citt\u00e0, la cui fondazione viene fatta [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-04-03T09:41:10+00:00","article_modified_time":"2023-04-03T13:08:36+00:00","og_image":[{"width":905,"height":1280,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/premio-bulgarini2.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini","datePublished":"2023-04-03T09:41:10+00:00","dateModified":"2023-04-03T13:08:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/"},"wordCount":433,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/premio-bulgarini2.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/","name":"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/premio-bulgarini2.jpg","datePublished":"2023-04-03T09:41:10+00:00","dateModified":"2023-04-03T13:08:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/premio-bulgarini2.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/premio-bulgarini2.jpg","width":905,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/03\/3238-natale-di-tivoli-mercoledi-5-aprile-cerimonia-inaugurale-e-premio-bulgarini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"3238\u00b0 Natale di Tivoli: mercoled\u00ec 5 aprile cerimonia inaugurale e Premio Bulgarini"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10324"}],"version-history":[{"count":6,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10324\/revisions"}],"predecessor-version":[{"id":10333,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10324\/revisions\/10333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10326"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}