{"id":10441,"date":"2023-04-21T13:16:12","date_gmt":"2023-04-21T11:16:12","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10441"},"modified":"2023-04-26T09:59:56","modified_gmt":"2023-04-26T07:59:56","slug":"tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/","title":{"rendered":"&#8220;TivoLibri&#8221;: a Tivoli arriva il &#8220;Maggio dei libri&#8221;. Un mese di appuntamenti per gli amanti della lettura"},"content":{"rendered":"<p>Al via\u00a0<strong>&#8220;TivoLibri&#8221;<\/strong>: un calendario ricco di appuntamenti\u00a0per tutti gli amanti della letteratura. Gli eventi,\u00a0programmati nell&#8217;ambito del 3238\u00b0 Natale della citt\u00e0, rientrano nell&#8217;ambito del\u00a0<a href=\"https:\/\/www.ilmaggiodeilibri.cepell.it\/\"><strong>&#8220;Maggio dei Libri&#8221;<\/strong><\/a>, campagna nazionale promossa dal Centro per il Libro e la Lettura del Ministero della Cultura alla quale, anche quest&#8217;anno, il Comune ha aderito con successo. L&#8217;obiettivo del &#8220;Maggio dei Libri&#8221; \u00e8 quello di portare\u00a0i libri e la lettura anche in contesti diversi da quelli tradizionali, per intercettare coloro che solitamente non leggono ma che possono essere incuriositi, se stimolati nel modo giusto.<\/p>\n<p>Dieci presentazioni di libri in tutto: si parte domenica 23 aprile con la presentazione, a cura di Marianna Scibetta, della trilogia di opere di Gianni Andrei &#8220;Sopravvivere al tempo&#8221;, per terminare sabato 27 maggio con la presentazione del libro\u00a0\u201cUndici Settembre 1973, il caso\u201d di Assunta Antonini su strada di Pomata.\u00a0Ritorna anche alla fine di maggio l&#8217;iniziativa\u00a0<a href=\"https:\/\/www.luig.it\/seminarlibri-2023\/\">SeminarLibri<\/a>\u00a0presso l&#8217;Antico Palazzo del Seminario con un omaggio a Italo Calvino nel centenario dalla sua scomparsa.<\/p>\n<p><strong>&#8220;Se leggi sei forte!&#8221;<\/strong>\u00a0\u00e8 il tema della tredicesima edizione del &#8220;Maggio dei Libri&#8221;. Quest\u2019anno, in continuit\u00e0 con l\u2019ultima edizione di Libriamoci, anche Il Maggio dei Libri celebra l\u2019importanza della lettura come strumento di forza e consapevolezza, capace di rendere autenticamente liberi. La forza delle parole, I libri, quelli forti\u2026 e Forti con le rime sono i tre filoni che caratterizzano il tema comune alle due campagne, ciascuno pensato per ospitare molteplici generi letterari e offrire diversi punti di vista sul valore sociale dei libri. Il tema istituzionale di questa tredicesima edizione \u00e8 &#8220;Se leggi sei forte!&#8221;, perch\u00e9\u00a0<strong>chi legge \u00e8 pi\u00f9 al sicuro, pi\u00f9 difeso e armato di idee<\/strong>, contro ingiustizie, sofferenze e ostacoli, sa come prendersi cura di s\u00e9 stesso e reagire di fronte alle avversit\u00e0.<\/p>\n<p>&#8220;Il nome dell&#8217;iniziativa &#8211; TivoLibri &#8211; intende connettere &#8220;Il Maggio dei Libri&#8221; con il nostro Natale di Tivoli &#8211; afferma\u00a0<strong>Antonio Capitano<\/strong>, responsabile dell&#8217;Ufficio Cultura del Comune di Tivoli -. TivoLibri \u00e8 la naturale continuazione della rassegna letteraria che si \u00e8 tenuta, con grande seguito, nel mese di gennaio e intende essere un contenitore di tutti gli eventi presenti e futuri relativi alla promozione della lettura e della forza del libro per il suo altissimo valore sociale. Ringrazio quanti hanno aderito all&#8217;iniziativa e quanti prenderanno parte agli eventi, con la speranza che questi possano essere per tutti occasione di arricchimento&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al via\u00a0&#8220;TivoLibri&#8221;: un calendario ricco di appuntamenti\u00a0per tutti gli amanti della letteratura. Gli eventi,\u00a0programmati nell&#8217;ambito del 3238\u00b0 Natale della citt\u00e0, rientrano nell&#8217;ambito del\u00a0&#8220;Maggio dei Libri&#8221;, campagna nazionale promossa dal Centro [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;TivoLibri&quot;: a Tivoli arriva il &quot;Maggio dei libri&quot;. Un mese di appuntamenti per gli amanti della lettura - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;TivoLibri&quot;: a Tivoli arriva il &quot;Maggio dei libri&quot;. Un mese di appuntamenti per gli amanti della lettura - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Al via\u00a0&#8220;TivoLibri&#8221;: un calendario ricco di appuntamenti\u00a0per tutti gli amanti della letteratura. Gli eventi,\u00a0programmati nell&#8217;ambito del 3238\u00b0 Natale della citt\u00e0, rientrano nell&#8217;ambito del\u00a0&#8220;Maggio dei Libri&#8221;, campagna nazionale promossa dal Centro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-21T11:16:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T07:59:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/manifesto-maggio-libri-corretto-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1119\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;TivoLibri&#8221;: a Tivoli arriva il &#8220;Maggio dei libri&#8221;. Un mese di appuntamenti per gli amanti della lettura\",\"datePublished\":\"2023-04-21T11:16:12+00:00\",\"dateModified\":\"2023-04-26T07:59:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/\"},\"wordCount\":405,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/manifesto-maggio-libri-corretto-1.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/\",\"name\":\"\\\"TivoLibri\\\": a Tivoli arriva il \\\"Maggio dei libri\\\". Un mese di appuntamenti per gli amanti della lettura - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/manifesto-maggio-libri-corretto-1.jpg\",\"datePublished\":\"2023-04-21T11:16:12+00:00\",\"dateModified\":\"2023-04-26T07:59:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/manifesto-maggio-libri-corretto-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/04\\\/manifesto-maggio-libri-corretto-1.jpg\",\"width\":1119,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/04\\\/21\\\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;TivoLibri&#8221;: a Tivoli arriva il &#8220;Maggio dei libri&#8221;. Un mese di appuntamenti per gli amanti della lettura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"TivoLibri\": a Tivoli arriva il \"Maggio dei libri\". Un mese di appuntamenti per gli amanti della lettura - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/","og_locale":"it_IT","og_type":"article","og_title":"\"TivoLibri\": a Tivoli arriva il \"Maggio dei libri\". Un mese di appuntamenti per gli amanti della lettura - Tivoli","og_description":"Al via\u00a0&#8220;TivoLibri&#8221;: un calendario ricco di appuntamenti\u00a0per tutti gli amanti della letteratura. Gli eventi,\u00a0programmati nell&#8217;ambito del 3238\u00b0 Natale della citt\u00e0, rientrano nell&#8217;ambito del\u00a0&#8220;Maggio dei Libri&#8221;, campagna nazionale promossa dal Centro [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-04-21T11:16:12+00:00","article_modified_time":"2023-04-26T07:59:56+00:00","og_image":[{"width":1119,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/manifesto-maggio-libri-corretto-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;TivoLibri&#8221;: a Tivoli arriva il &#8220;Maggio dei libri&#8221;. Un mese di appuntamenti per gli amanti della lettura","datePublished":"2023-04-21T11:16:12+00:00","dateModified":"2023-04-26T07:59:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/"},"wordCount":405,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/manifesto-maggio-libri-corretto-1.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/","name":"\"TivoLibri\": a Tivoli arriva il \"Maggio dei libri\". Un mese di appuntamenti per gli amanti della lettura - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/manifesto-maggio-libri-corretto-1.jpg","datePublished":"2023-04-21T11:16:12+00:00","dateModified":"2023-04-26T07:59:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/manifesto-maggio-libri-corretto-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/04\/manifesto-maggio-libri-corretto-1.jpg","width":1119,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/04\/21\/tivolibri-a-tivoli-arriva-il-maggio-dei-libri-un-mese-di-appuntamenti-per-gli-amanti-della-lettura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;TivoLibri&#8221;: a Tivoli arriva il &#8220;Maggio dei libri&#8221;. Un mese di appuntamenti per gli amanti della lettura"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10441"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10441\/revisions"}],"predecessor-version":[{"id":10444,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10441\/revisions\/10444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10461"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}