{"id":10478,"date":"2023-05-02T13:53:59","date_gmt":"2023-05-02T11:53:59","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10478"},"modified":"2023-05-02T13:53:59","modified_gmt":"2023-05-02T11:53:59","slug":"sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/","title":{"rendered":"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio"},"content":{"rendered":"<p>A seguito di chiarimento con ANAS e con la ditta esecutrice dei lavori in corso sulla via Tiburtina, si dispone la <strong>sospensione della ZTL 1 (varco 1-2-3) dalle ore 7 alle ore 14<\/strong> tutti i giorni fino a venerd\u00ec 5 maggio compreso. Pertanto i varchi torneranno attivi alle ore 17, salvo diversi avvisi. I lavori verranno costantemente monitorati e nel caso di eccessivo intasamento del traffico cittadino la ditta proceder\u00e0 alla momentanea sospensione dei lavori per agevolare il transito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A seguito di chiarimento con ANAS e con la ditta esecutrice dei lavori in corso sulla via Tiburtina, si dispone la sospensione della ZTL 1 (varco 1-2-3) dalle ore 7 [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-10478","post","type-post","status-publish","format-standard","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio - Tivoli\" \/>\n<meta property=\"og:description\" content=\"A seguito di chiarimento con ANAS e con la ditta esecutrice dei lavori in corso sulla via Tiburtina, si dispone la sospensione della ZTL 1 (varco 1-2-3) dalle ore 7 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-02T11:53:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio\",\"datePublished\":\"2023-05-02T11:53:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/\"},\"wordCount\":86,\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/\",\"name\":\"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-05-02T11:53:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/02\\\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/","og_locale":"it_IT","og_type":"article","og_title":"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio - Tivoli","og_description":"A seguito di chiarimento con ANAS e con la ditta esecutrice dei lavori in corso sulla via Tiburtina, si dispone la sospensione della ZTL 1 (varco 1-2-3) dalle ore 7 [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-02T11:53:59+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio","datePublished":"2023-05-02T11:53:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/"},"wordCount":86,"articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/","name":"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-05-02T11:53:59+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/02\/sospensione-della-ztl-1-dalle-ore-7-alle-ore-14-fino-a-venerdi-5-maggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Sospensione della ZTL 1 dalle ore 7 alle ore 14 fino a venerd\u00ec 5 maggio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10478"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10478\/revisions"}],"predecessor-version":[{"id":10479,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10478\/revisions\/10479"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}