{"id":10486,"date":"2023-05-03T14:27:12","date_gmt":"2023-05-03T12:27:12","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10486"},"modified":"2023-05-04T11:57:49","modified_gmt":"2023-05-04T09:57:49","slug":"tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/","title":{"rendered":"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato"},"content":{"rendered":"<p>l pugilato italiano ha la possibilit\u00e0 di avere tre campioni europei nell\u2019arco di una sera: venerd\u00ec 5 maggio, presso il Palasport di Tivoli, con il patrocinio del Comune di Tivoli, la Opi Since 82 presenter\u00e0 la\u00a0<strong>Tivoli Boxing Night<\/strong>, evento di pugilato professionistico che sar\u00e0\u00a0<strong>trasmesso in duplice diretta su DAZN in esclusiva italiana<\/strong>\u00a0e su\u00a0<strong>ESPN+<\/strong>\u00a0negli USA. Una card unica nel suo genere, con tre cinture europee in palio.<\/p>\n<p>Il\u00a0<strong>main event\u00a0<\/strong>della serata \u00e8 l\u2019atteso rematch tra Mauro Forte (17-0-2, 7KO) e Francesco Grandelli (16-1-2, 3KO) valido per il Titolo Europeo dei pesi piuma. Forte e Grandelli si sono gi\u00e0 sfidati nel n\\ovembre 2021, durante la Dazn Boxing Night di Roma, in dodici riprese spettacolari terminate con un pareggio per Split Draw, verdetto che consent\u00ec a Mauro Forte di mantenere la cintura di campione dell\u2019Unione Europea. Adesso in palio c\u2019\u00e8 la pregiata cintura europea, lasciata vacante dallo spagnolo Kiko Martinez, il cui valore dar\u00e0 uno stimolo e una determinazione in pi\u00f9 ai due pugili.<\/p>\n<p>Come co-main event della serata, i due titoli europei femminili: Stephanie Silva (7-0-0) difender\u00e0 la sua cintura di campionessa europea dei supermosca contro la francese Mailys Gangloff (8-3-0, 2KO), mentre Simona Salvatori (8-0-0, 2KO) sfider\u00e0 Johanna Wonyou (8-0-0, 2KO) per il vacante titolo europeo dei pesi gallo. Stephanie Silva \u00e8 alla seconda difesa della cintura continentale, dopo aver battuto la polacca Pekalska con una prestazione tecnicamente e mentalmente ineccepibile nella Roma Boxing Night al Pala Atlantico del 28 ottobre 2022. Per Simona Salvatori \u00e8 la chance iridata fondamentale per continuare a crescere, contro un\u2019avversaria imbattuta e capace.<br \/>\nNell\u2019undercard ci saranno quattro incontri, tutti dedicati ai prospect emergenti della scena pugilistica romana. Armando Casamonica (9-0-0, 1KO) combatter\u00e0 sulla distanza delle otto riprese nei pesi superleggeri dopo aver vinto il Trofeo delle Cinture della Federazione Pugilistica Italiana, Gloria Peritore (1-0) disputer\u00e0 il secondo match da professionista, Mario Manfredi inseguir\u00e0 la terza vittoria (2-0, 1KO) e Francesco Faraoni (1-0) ritorner\u00e0 sul ring dopo l\u2019esordio vincente di ottobre.<\/p>\n<p>\u201cTre titoli europei su sette incontri professionistici in una sola card: siamo felici di organizzare una manifestazione cos\u00ec prestigiosa per il movimento pugilistico italiano. La nostra missione \u00e8 far crescere nel migliore dei modi i nostri atleti, di aiutarli nel loro cammino sportivo garantendogli la giusta esposizione mediatica e matchmaking di rilievo. Basta leggere la fight card per capire che si tratta di incontri che nessun appassionato di boxe si perderebbe: crediamo possano essere di richiamo al botteghino per una piazza come Tivoli, di cui ringraziamo l\u2019amministrazione comunale, e come Roma, dove la nobile arte \u00e8 amata in maniera viscerale\u201d spiega Alessandro Cherchi di Opi Since 82.<\/p>\n<p>I biglietti sono in vendita su www.boxol.it al prezzo di 60,00\u20ac bordo ring, 35,00\u20ac tribuna e 25,00\u20ac gradinata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l pugilato italiano ha la possibilit\u00e0 di avere tre campioni europei nell\u2019arco di una sera: venerd\u00ec 5 maggio, presso il Palasport di Tivoli, con il patrocinio del Comune di Tivoli, [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-10486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato - Tivoli\" \/>\n<meta property=\"og:description\" content=\"l pugilato italiano ha la possibilit\u00e0 di avere tre campioni europei nell\u2019arco di una sera: venerd\u00ec 5 maggio, presso il Palasport di Tivoli, con il patrocinio del Comune di Tivoli, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-03T12:27:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-04T09:57:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato\",\"datePublished\":\"2023-05-03T12:27:12+00:00\",\"dateModified\":\"2023-05-04T09:57:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/\"},\"wordCount\":471,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/\",\"name\":\"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg\",\"datePublished\":\"2023-05-03T12:27:12+00:00\",\"dateModified\":\"2023-05-04T09:57:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/03\\\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/","og_locale":"it_IT","og_type":"article","og_title":"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato - Tivoli","og_description":"l pugilato italiano ha la possibilit\u00e0 di avere tre campioni europei nell\u2019arco di una sera: venerd\u00ec 5 maggio, presso il Palasport di Tivoli, con il patrocinio del Comune di Tivoli, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-03T12:27:12+00:00","article_modified_time":"2023-05-04T09:57:49+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato","datePublished":"2023-05-03T12:27:12+00:00","dateModified":"2023-05-04T09:57:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/"},"wordCount":471,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/","name":"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg","datePublished":"2023-05-03T12:27:12+00:00","dateModified":"2023-05-04T09:57:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-Boxing-Night_Locandina-Ufficiale.jpeg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/03\/tivoli-boxing-night-tre-titoli-europei-in-ununica-serata-di-pugilato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Tivoli Boxing Night: tre titoli europei in un\u2019unica serata di pugilato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10486"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10486\/revisions"}],"predecessor-version":[{"id":10494,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10486\/revisions\/10494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10487"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}