{"id":10491,"date":"2023-05-04T09:20:37","date_gmt":"2023-05-04T07:20:37","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10491"},"modified":"2023-05-04T09:20:37","modified_gmt":"2023-05-04T07:20:37","slug":"aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/","title":{"rendered":"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno"},"content":{"rendered":"<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Si porta a conoscenza la cittadinanza che i lavori stradali di sostituzione e riparazione del guard rail, in corso sulla via Tiburtina, in un tratto stradale extraurbano, eseguiti dall&#8217;ANAS e di competenza dell&#8217;ANAS stessa, a seguito di disposizioni del Sindaco, saranno svolti in orario serale e notturno, salvo eventuali interventi diurni che non comportino l&#8217;istituzione del senso unico alternato semaforizzato.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Pertanto, da oggi giovedi 4 maggio verr\u00e0 ripristinato il normale funzionamento della ZTL1 &#8211; &#8220;Centro Storico Medioevale&#8221; (Varco 1 &#8211; Piazza Massimo, Varco 2 &#8211; Via del Colle, Varco 3 &#8211; Via dei Sosii) &#8211; precedentemente sospeso &#8211; secondo gli orari in vigore, che si ricordano essere:<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">&#8211; Accesso consentito soltanto agli autorizzati dal luned\u00ec al sabato dalle ore 07:00 alle ore 14:00 (Varco 1 &#8211; Piazza Massimo dalle 9 alle 14 nei giorni di scuola) e dalle 17 alle 2.<\/div>\n<div dir=\"auto\">&#8211; Domenica e festivi dalle ore 14 alle 2.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Il carico e scarico \u00e8 consentito dalle ore 8:30 alle 12 e dalle 15:30 alle 17.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si porta a conoscenza la cittadinanza che i lavori stradali di sostituzione e riparazione del guard rail, in corso sulla via Tiburtina, in un tratto stradale extraurbano, eseguiti dall&#8217;ANAS e [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-10491","post","type-post","status-publish","format-standard","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si porta a conoscenza la cittadinanza che i lavori stradali di sostituzione e riparazione del guard rail, in corso sulla via Tiburtina, in un tratto stradale extraurbano, eseguiti dall&#8217;ANAS e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-04T07:20:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno\",\"datePublished\":\"2023-05-04T07:20:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/\"},\"wordCount\":159,\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/\",\"name\":\"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-05-04T07:20:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/04\\\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno - Tivoli","og_description":"Si porta a conoscenza la cittadinanza che i lavori stradali di sostituzione e riparazione del guard rail, in corso sulla via Tiburtina, in un tratto stradale extraurbano, eseguiti dall&#8217;ANAS e [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-04T07:20:37+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno","datePublished":"2023-05-04T07:20:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/"},"wordCount":159,"articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/","name":"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-05-04T07:20:37+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/04\/aggiornamento-lavori-anas-via-tiburtina-km-29000-saranno-svolti-in-orario-notturno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Aggiornamento lavori ANAS via Tiburtina km 29,000: saranno svolti in orario notturno"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10491"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10491\/revisions"}],"predecessor-version":[{"id":10492,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10491\/revisions\/10492"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}