{"id":10549,"date":"2023-05-17T09:52:30","date_gmt":"2023-05-17T07:52:30","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10549"},"modified":"2023-05-17T09:52:30","modified_gmt":"2023-05-17T07:52:30","slug":"tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/","title":{"rendered":"&#8220;Tivoli illustrata da Luigi Rossini&#8221;: presentazione del volume venerd\u00ec 19 maggio al Convitto"},"content":{"rendered":"<p>Venerd\u00ec 19 maggio alle 17.30 nell&#8217;Aula Magna del Convitto Nazionale &#8220;A. di Savoia Duca d&#8217;Aosta&#8221;, si terr\u00e0 la presentazione del volume<strong>\u00a0&#8220;Tivoli illustrata da Luigi Rossini&#8221;<\/strong>, curato da Anna Maria Panattoni e Tertulliano Bonamoneta.<\/p>\n<p>Una nuova occasione per &#8220;gustare&#8221; la citt\u00e0 attraverso le incisioni di Luigi Rossini: la proposta editoriale offre la raccolta dei &#8220;ritratti&#8221; della nostra citt\u00e0 nel primo &#8216;800, in una rilettura aggiornata dell&#8217;impegno grafico del celebre architetto ravennate che, come molti, sub\u00ec le fascinazioni degli scorci e delle vestigia storiche locali.<\/p>\n<p>L&#8217;evento, patrocinato dal Comune di Tivoli, dalla Regione Lazio, dal Ministero della Cultura, dalla Soprintendenza\u00a0\u00a0Archeologia, Belle arti e Paesaggio per l&#8217;area metropolitana di Roma e la provincia di Rieti, da Citt\u00e0 Metropolitana di Roma Capitale e Convitto Nazionale Amedeo di Savoia, \u00e8 inserito nell&#8217;ambito delle manifestazioni del Natale di Tivoli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 19 maggio alle 17.30 nell&#8217;Aula Magna del Convitto Nazionale &#8220;A. di Savoia Duca d&#8217;Aosta&#8221;, si terr\u00e0 la presentazione del volume\u00a0&#8220;Tivoli illustrata da Luigi Rossini&#8221;, curato da Anna Maria Panattoni [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10550,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Tivoli illustrata da Luigi Rossini&quot;: presentazione del volume venerd\u00ec 19 maggio al Convitto - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Tivoli illustrata da Luigi Rossini&quot;: presentazione del volume venerd\u00ec 19 maggio al Convitto - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 19 maggio alle 17.30 nell&#8217;Aula Magna del Convitto Nazionale &#8220;A. di Savoia Duca d&#8217;Aosta&#8221;, si terr\u00e0 la presentazione del volume\u00a0&#8220;Tivoli illustrata da Luigi Rossini&#8221;, curato da Anna Maria Panattoni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-17T07:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-illustrata.png\" \/>\n\t<meta property=\"og:image:width\" content=\"688\" \/>\n\t<meta property=\"og:image:height\" content=\"985\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;Tivoli illustrata da Luigi Rossini&#8221;: presentazione del volume venerd\u00ec 19 maggio al Convitto\",\"datePublished\":\"2023-05-17T07:52:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/\"},\"wordCount\":144,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-illustrata.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/\",\"name\":\"\\\"Tivoli illustrata da Luigi Rossini\\\": presentazione del volume venerd\u00ec 19 maggio al Convitto - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-illustrata.png\",\"datePublished\":\"2023-05-17T07:52:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-illustrata.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/Tivoli-illustrata.png\",\"width\":688,\"height\":985},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/17\\\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Tivoli illustrata da Luigi Rossini&#8221;: presentazione del volume venerd\u00ec 19 maggio al Convitto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Tivoli illustrata da Luigi Rossini\": presentazione del volume venerd\u00ec 19 maggio al Convitto - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/","og_locale":"it_IT","og_type":"article","og_title":"\"Tivoli illustrata da Luigi Rossini\": presentazione del volume venerd\u00ec 19 maggio al Convitto - Tivoli","og_description":"Venerd\u00ec 19 maggio alle 17.30 nell&#8217;Aula Magna del Convitto Nazionale &#8220;A. di Savoia Duca d&#8217;Aosta&#8221;, si terr\u00e0 la presentazione del volume\u00a0&#8220;Tivoli illustrata da Luigi Rossini&#8221;, curato da Anna Maria Panattoni [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-17T07:52:30+00:00","og_image":[{"width":688,"height":985,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-illustrata.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;Tivoli illustrata da Luigi Rossini&#8221;: presentazione del volume venerd\u00ec 19 maggio al Convitto","datePublished":"2023-05-17T07:52:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/"},"wordCount":144,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-illustrata.png","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/","name":"\"Tivoli illustrata da Luigi Rossini\": presentazione del volume venerd\u00ec 19 maggio al Convitto - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-illustrata.png","datePublished":"2023-05-17T07:52:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-illustrata.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/Tivoli-illustrata.png","width":688,"height":985},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/17\/tivoli-illustrata-da-luigi-rossini-presentazione-del-volume-venerdi-19-maggio-al-convitto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;Tivoli illustrata da Luigi Rossini&#8221;: presentazione del volume venerd\u00ec 19 maggio al Convitto"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10549"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10549\/revisions"}],"predecessor-version":[{"id":10551,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10549\/revisions\/10551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10550"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}