{"id":10636,"date":"2023-05-26T14:53:53","date_gmt":"2023-05-26T12:53:53","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10636"},"modified":"2023-05-26T14:53:53","modified_gmt":"2023-05-26T12:53:53","slug":"presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/","title":{"rendered":"Presentazione del libro &#8220;I dannati della Saint George&#8221;: 29 maggio in Biblioteca comunale"},"content":{"rendered":"<p>Luned\u00ec 29 maggio, alle ore 17, presso la Biblioteca comunale di Tivoli, si terr\u00e0 la presentazione del libro <strong>&#8220;I dannati della Saint George&#8221;<\/strong> dell&#8217;autore Dario Pontuale.<\/p>\n<p>Era il 1901 quando, in una notte piovosa, qualcuno buss\u00f2 alla porta di Libero Gori e lo convinse ad intraprendere un viaggio di mare per affrontare le anime dannate della Saint George, in cerca di un&#8217;impossibile vendetta. Pirati, pozioni, fantasmi e maledizioni in un&#8217;avventura che ha del magico salpando per i mari oscuri. &#8220;I dannati della Saint George&#8221; \u00e8 una fiaba che ricalca i canoni ottocenteschi della letteratura d&#8217;avventura per ragazzi; ambientazioni, personaggi e lessico si rifanno ai grandi maestri del genere: Salgari, London, Stevenson, Conrad.<\/p>\n<p>Dialogher\u00e0 con l&#8217;autore Antonio Capitano.<\/p>\n<p>Dario Pontuale \u00e8 scrittore, critico letterario, curatore di numerose opere dei classici della letteratura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 29 maggio, alle ore 17, presso la Biblioteca comunale di Tivoli, si terr\u00e0 la presentazione del libro &#8220;I dannati della Saint George&#8221; dell&#8217;autore Dario Pontuale. Era il 1901 quando, [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentazione del libro &quot;I dannati della Saint George&quot;: 29 maggio in Biblioteca comunale - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentazione del libro &quot;I dannati della Saint George&quot;: 29 maggio in Biblioteca comunale - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec 29 maggio, alle ore 17, presso la Biblioteca comunale di Tivoli, si terr\u00e0 la presentazione del libro &#8220;I dannati della Saint George&#8221; dell&#8217;autore Dario Pontuale. Era il 1901 quando, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-26T12:53:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/I-Dannati.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1132\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Presentazione del libro &#8220;I dannati della Saint George&#8221;: 29 maggio in Biblioteca comunale\",\"datePublished\":\"2023-05-26T12:53:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/\"},\"wordCount\":138,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/I-Dannati.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/\",\"name\":\"Presentazione del libro \\\"I dannati della Saint George\\\": 29 maggio in Biblioteca comunale - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/I-Dannati.jpg\",\"datePublished\":\"2023-05-26T12:53:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/I-Dannati.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/05\\\/I-Dannati.jpg\",\"width\":1132,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/05\\\/26\\\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentazione del libro &#8220;I dannati della Saint George&#8221;: 29 maggio in Biblioteca comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentazione del libro \"I dannati della Saint George\": 29 maggio in Biblioteca comunale - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Presentazione del libro \"I dannati della Saint George\": 29 maggio in Biblioteca comunale - Tivoli","og_description":"Luned\u00ec 29 maggio, alle ore 17, presso la Biblioteca comunale di Tivoli, si terr\u00e0 la presentazione del libro &#8220;I dannati della Saint George&#8221; dell&#8217;autore Dario Pontuale. Era il 1901 quando, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-26T12:53:53+00:00","og_image":[{"width":1132,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/I-Dannati.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Presentazione del libro &#8220;I dannati della Saint George&#8221;: 29 maggio in Biblioteca comunale","datePublished":"2023-05-26T12:53:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/"},"wordCount":138,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/I-Dannati.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/","name":"Presentazione del libro \"I dannati della Saint George\": 29 maggio in Biblioteca comunale - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/I-Dannati.jpg","datePublished":"2023-05-26T12:53:53+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/I-Dannati.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/05\/I-Dannati.jpg","width":1132,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/05\/26\/presentazione-del-libro-i-dannati-della-saint-george-29-maggio-in-biblioteca-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Presentazione del libro &#8220;I dannati della Saint George&#8221;: 29 maggio in Biblioteca comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10636"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10636\/revisions"}],"predecessor-version":[{"id":10638,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10636\/revisions\/10638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10637"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}