{"id":10678,"date":"2023-06-07T11:44:26","date_gmt":"2023-06-07T09:44:26","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10678"},"modified":"2023-06-07T11:44:26","modified_gmt":"2023-06-07T09:44:26","slug":"tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/","title":{"rendered":"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento"},"content":{"rendered":"<p>Torna, domenica 11 giugno,\u00a0<strong>&#8220;Tivoli in passerella&#8221;<\/strong>, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, con la regia di Paolo Pizzolorusso. I protagonisti saranno\u00a0i commercianti tiburtini insieme al cast di modelle e modelli, i quali indosseranno\u00a0i capi scelti e offerti dai titolari degli esercizi commerciali della citt\u00e0. Appuntamento alle 17 alle Scuderie Estensi, dove sar\u00e0 possibile assistere alla\u00a0<strong>Gran<\/strong>\u00a0<strong>sfilata di moda&amp;trend<\/strong>, con ospiti e intrattenimento.<\/p>\n<p>L&#8217;iniziativa coinvolge non soltanto la\u00a0<strong>realt\u00e0 giovanile locale<\/strong>, ma anche molte delle\u00a0associazioni tiburtine impegnate nell\u2019ambito culturale e sociale.<\/p>\n<p>L&#8217;obiettivo dell&#8217;evento, nato nel 2014 da un&#8217;idea di Matteo Pizzolorusso, presidente dell&#8217;Associazione Culturale &#8220;Tivoli in passerella, moda, musica e commercio&#8221;, \u00e8 quello di\u00a0<strong>&#8220;dare voce&#8221; ai commercianti locali\u00a0<\/strong>e<strong>\u00a0<\/strong>valorizzare il negozio &#8220;sotto casa&#8221;, che nulla ha da invidiare alle grandi catene commerciali.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Torna, domenica 11 giugno,\u00a0&#8220;Tivoli in passerella&#8221;, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, con la regia di Paolo Pizzolorusso. [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-10678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Torna, domenica 11 giugno,\u00a0&#8220;Tivoli in passerella&#8221;, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, con la regia di Paolo Pizzolorusso. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-07T09:44:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Tivoli-in-passerella.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento\",\"datePublished\":\"2023-06-07T09:44:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/\"},\"wordCount\":150,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Tivoli-in-passerella.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/\",\"name\":\"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Tivoli-in-passerella.jpg\",\"datePublished\":\"2023-06-07T09:44:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Tivoli-in-passerella.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Tivoli-in-passerella.jpg\",\"width\":1080,\"height\":1533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/07\\\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/","og_locale":"it_IT","og_type":"article","og_title":"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento - Tivoli","og_description":"Torna, domenica 11 giugno,\u00a0&#8220;Tivoli in passerella&#8221;, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, con la regia di Paolo Pizzolorusso. [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-06-07T09:44:26+00:00","og_image":[{"width":1080,"height":1533,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Tivoli-in-passerella.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento","datePublished":"2023-06-07T09:44:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/"},"wordCount":150,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Tivoli-in-passerella.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/","name":"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Tivoli-in-passerella.jpg","datePublished":"2023-06-07T09:44:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Tivoli-in-passerella.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Tivoli-in-passerella.jpg","width":1080,"height":1533},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/07\/tivoli-in-passerella-domenica-11-giugno-gran-sfilata-con-ospiti-e-intrattenimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Tivoli in passerella: domenica 11 giugno Gran sfilata con ospiti e intrattenimento"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10678"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10678\/revisions"}],"predecessor-version":[{"id":10680,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10678\/revisions\/10680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10679"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}