{"id":10739,"date":"2023-06-19T15:38:33","date_gmt":"2023-06-19T13:38:33","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10739"},"modified":"2023-06-19T15:38:33","modified_gmt":"2023-06-19T13:38:33","slug":"tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/","title":{"rendered":"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all&#8217;ingresso della citt\u00e0"},"content":{"rendered":"<p>Oggi \u00e8 stata affissa all\u2019entrata della citt\u00e0 di Tivoli la <strong>targa di \u201cCitt\u00e0 delle donne\u201d<\/strong>, alla presenza della Polizia locale, del comandante Antonio D&#8217;Emilio, della Vicesindaca Laura Di Giuseppe, della Presidente della Commissione Pari Opportunit\u00e0 Francesca Chimenti e dell&#8217;ambasciatrice degli <span class=\"xv78j7m\">Stati Generali delle donne del Lazio<\/span> Nadia Palozza Natolli.<\/p>\n<p>Il Consiglio Comunale a novembre del 2022 ha approvato all&#8217;unanimit\u00e0 l&#8217;adozione del documento &#8220;Le citt\u00e0 delle donne &#8211; <span class=\"xv78j7m\">Stati Generali delle Donne<\/span> &#8211; Principi e obiettivi&#8221;, quale dichiarazione di intenti per la diffusione di politiche inclusive e di una cultura di parit\u00e0 di genere, libera da discriminazioni e pregiudizi.<\/p>\n<p>La targa vuole essere un simbolo visibile e tangibile dell\u2019obiettivo permanente che l\u2019Amministrazione comunale si \u00e8 posta: la tutela dei principi della non discriminazione fra i sessi, della piena affermazione del concetto della parit\u00e0 di genere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi \u00e8 stata affissa all\u2019entrata della citt\u00e0 di Tivoli la targa di \u201cCitt\u00e0 delle donne\u201d, alla presenza della Polizia locale, del comandante Antonio D&#8217;Emilio, della Vicesindaca Laura Di Giuseppe, della [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-10739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all&#039;ingresso della citt\u00e0 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all&#039;ingresso della citt\u00e0 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Oggi \u00e8 stata affissa all\u2019entrata della citt\u00e0 di Tivoli la targa di \u201cCitt\u00e0 delle donne\u201d, alla presenza della Polizia locale, del comandante Antonio D&#8217;Emilio, della Vicesindaca Laura Di Giuseppe, della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-19T13:38:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Citta-delle-donne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all&#8217;ingresso della citt\u00e0\",\"datePublished\":\"2023-06-19T13:38:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/\"},\"wordCount\":144,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Citta-delle-donne.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/\",\"name\":\"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all'ingresso della citt\u00e0 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Citta-delle-donne.jpg\",\"datePublished\":\"2023-06-19T13:38:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Citta-delle-donne.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/Citta-delle-donne.jpg\",\"width\":1600,\"height\":1201},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/19\\\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all&#8217;ingresso della citt\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all'ingresso della citt\u00e0 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/","og_locale":"it_IT","og_type":"article","og_title":"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all'ingresso della citt\u00e0 - Tivoli","og_description":"Oggi \u00e8 stata affissa all\u2019entrata della citt\u00e0 di Tivoli la targa di \u201cCitt\u00e0 delle donne\u201d, alla presenza della Polizia locale, del comandante Antonio D&#8217;Emilio, della Vicesindaca Laura Di Giuseppe, della [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-06-19T13:38:33+00:00","og_image":[{"width":1600,"height":1201,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Citta-delle-donne.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all&#8217;ingresso della citt\u00e0","datePublished":"2023-06-19T13:38:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/"},"wordCount":144,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Citta-delle-donne.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/","name":"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all'ingresso della citt\u00e0 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Citta-delle-donne.jpg","datePublished":"2023-06-19T13:38:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Citta-delle-donne.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/Citta-delle-donne.jpg","width":1600,"height":1201},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/19\/tivoli-citta-delle-donne-affissa-la-targa-allingresso-della-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Tivoli \u201cCitt\u00e0 delle donne\u201d: affissa la targa all&#8217;ingresso della citt\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10739"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10739\/revisions"}],"predecessor-version":[{"id":10741,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10739\/revisions\/10741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10740"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}