{"id":10826,"date":"2023-06-27T11:18:07","date_gmt":"2023-06-27T09:18:07","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=10826"},"modified":"2023-06-27T11:18:07","modified_gmt":"2023-06-27T09:18:07","slug":"campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/","title":{"rendered":"Campolimpido: chiusa la procedura per l&#8217;affidamento dei lavori per il nuovo campo sportivo"},"content":{"rendered":"<p>Si \u00e8 chiusa oggi la procedura per l&#8217;affidamento dei lavori per la\u00a0<strong>realizzazione di un campo sportivo polifunzionale<\/strong>\u00a0nel quartiere di Campolimpido, per un importo complessivo di 400mila euro. Il finanziamento\u00a0del\u00a0Ministero dell&#8217;Interno \u00e8 stato\u00a0ottenuto grazie ad un bando vinto dal Comune di Tivoli. Il progetto rientra nel PNRR tra gli &#8220;interventi di rigenerazione urbana&#8221;.<\/p>\n<p>Sono previste le realizzazioni di un\u00a0<strong>campo\u00a0<\/strong>polivalente, in prossimit\u00e0 della scuola \u201cDe Andr\u00e8\u201d di via Libertucci, di un\u00a0<strong>parcheggio pubblico<\/strong>\u00a0per una superficie pari a circa 380 mq e di\u00a0un\u00a0<strong>servizio igienico<\/strong>\u00a0automatizzato autopulente. Il campo, illuminato con Led e attrezzato con porte e panchine, consente la\u00a0pratica di pi\u00f9 discipline sportive e potr\u00e0 essere fruito non soltanto dagli studenti del vicino istituto scolastico, ma da parte dell&#8217;intera comunit\u00e0 di Campolimpido.<\/p>\n<p>L&#8217;area di sosta del parcheggio sar\u00e0\u00a0costituita da 24 posti auto, due dei quali riservati a persone diversamente abili. Anche il\u00a0parcheggio sar\u00e0 illuminato con lampade a Led installate su pali in acciaio.<\/p>\n<p>Per quanto riguarda invece il servizio igienico automatizzato per donne, uomini e disabili, sar\u00e0 installato in prossimit\u00e0 del parcheggio esistente oggi\u00a0adibito anche per il mercato settimanale di quartiere.<\/p>\n<p>&#8220;Questo progetto non pu\u00f2 che renderci entusiasti &#8211; afferma il consigliere del Sindaco per il quartiere di Campolimpido\u00a0<strong>Angelo Marinelli<\/strong>\u00a0&#8211; perch\u00e9 dona nuova vita, nonch\u00e9 un nuovo aspetto, ad un punto centrale e gi\u00e0 molto frequentato del nostro quartiere. Il campo sportivo diventer\u00e0 un punto di riferimento per tanti bambini e ragazzi. Il parcheggio e il servizio igienico renderanno quest&#8217;area ancora pi\u00f9 facilmente fruibile&#8221;.<\/p>\n<p>\u00c8 previsto che il 30% delle opere siano realizzate entro il 30 settembre 2024. La scadenza per la fine dei lavori \u00e8 fissata al 31 marzo 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 chiusa oggi la procedura per l&#8217;affidamento dei lavori per la\u00a0realizzazione di un campo sportivo polifunzionale\u00a0nel quartiere di Campolimpido, per un importo complessivo di 400mila euro. Il finanziamento\u00a0del\u00a0Ministero dell&#8217;Interno [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":10827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-10826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campolimpido: chiusa la procedura per l&#039;affidamento dei lavori per il nuovo campo sportivo - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campolimpido: chiusa la procedura per l&#039;affidamento dei lavori per il nuovo campo sportivo - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 chiusa oggi la procedura per l&#8217;affidamento dei lavori per la\u00a0realizzazione di un campo sportivo polifunzionale\u00a0nel quartiere di Campolimpido, per un importo complessivo di 400mila euro. Il finanziamento\u00a0del\u00a0Ministero dell&#8217;Interno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-27T09:18:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/via-libertucci.png\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"293\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Campolimpido: chiusa la procedura per l&#8217;affidamento dei lavori per il nuovo campo sportivo\",\"datePublished\":\"2023-06-27T09:18:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/\"},\"wordCount\":286,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/via-libertucci.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/\",\"name\":\"Campolimpido: chiusa la procedura per l'affidamento dei lavori per il nuovo campo sportivo - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/via-libertucci.png\",\"datePublished\":\"2023-06-27T09:18:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/via-libertucci.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/06\\\/via-libertucci.png\",\"width\":680,\"height\":293},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/06\\\/27\\\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campolimpido: chiusa la procedura per l&#8217;affidamento dei lavori per il nuovo campo sportivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campolimpido: chiusa la procedura per l'affidamento dei lavori per il nuovo campo sportivo - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/","og_locale":"it_IT","og_type":"article","og_title":"Campolimpido: chiusa la procedura per l'affidamento dei lavori per il nuovo campo sportivo - Tivoli","og_description":"Si \u00e8 chiusa oggi la procedura per l&#8217;affidamento dei lavori per la\u00a0realizzazione di un campo sportivo polifunzionale\u00a0nel quartiere di Campolimpido, per un importo complessivo di 400mila euro. Il finanziamento\u00a0del\u00a0Ministero dell&#8217;Interno [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-06-27T09:18:07+00:00","og_image":[{"width":680,"height":293,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/via-libertucci.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Campolimpido: chiusa la procedura per l&#8217;affidamento dei lavori per il nuovo campo sportivo","datePublished":"2023-06-27T09:18:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/"},"wordCount":286,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/via-libertucci.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/","name":"Campolimpido: chiusa la procedura per l'affidamento dei lavori per il nuovo campo sportivo - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/via-libertucci.png","datePublished":"2023-06-27T09:18:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/via-libertucci.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/06\/via-libertucci.png","width":680,"height":293},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/06\/27\/campolimpido-chiusa-la-procedura-per-laffidamento-dei-lavori-per-il-nuovo-campo-sportivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Campolimpido: chiusa la procedura per l&#8217;affidamento dei lavori per il nuovo campo sportivo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=10826"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10826\/revisions"}],"predecessor-version":[{"id":10828,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/10826\/revisions\/10828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/10827"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=10826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=10826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=10826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}