{"id":11047,"date":"2023-08-23T11:39:03","date_gmt":"2023-08-23T09:39:03","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11047"},"modified":"2023-08-23T11:41:34","modified_gmt":"2023-08-23T09:41:34","slug":"graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/","title":{"rendered":"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023"},"content":{"rendered":"<p>Si informa la cittadinanza che \u00e8 stata pubblicata la\u00a0<strong>graduatoria degli ammessi al soggiorno estivo per gli utenti affetti da disabilit\u00e0<\/strong>\u00a0per l\u2019anno 2023 presso il villaggio Welcome di Tortoreto Lido nel periodo dal 2 al 12 Settembre.<\/p>\n<p>Si ricorda che i disabili maggiori di 21 anni sono tenuti al versamento mediante pagoPA di una quota di compartecipazione di \u20ac 350,00, cos\u00ec come i disabili minori di anni 21 che abbiano un Isee superiore ad \u20ac 25.000,00.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_11050\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/08\/graduatoria-ammessi-2023.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/08\/graduatoria-ammessi-2023.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>GRADUATORIA AMMESSI 2023<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informa la cittadinanza che \u00e8 stata pubblicata la\u00a0graduatoria degli ammessi al soggiorno estivo per gli utenti affetti da disabilit\u00e0\u00a0per l\u2019anno 2023 presso il villaggio Welcome di Tortoreto Lido nel [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-11047","post","type-post","status-publish","format-standard","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si informa la cittadinanza che \u00e8 stata pubblicata la\u00a0graduatoria degli ammessi al soggiorno estivo per gli utenti affetti da disabilit\u00e0\u00a0per l\u2019anno 2023 presso il villaggio Welcome di Tortoreto Lido nel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T09:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-23T09:41:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/servizi-sociali-e-casa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023\",\"datePublished\":\"2023-08-23T09:39:03+00:00\",\"dateModified\":\"2023-08-23T09:41:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/\"},\"wordCount\":78,\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/\",\"name\":\"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-08-23T09:39:03+00:00\",\"dateModified\":\"2023-08-23T09:41:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/08\\\/23\\\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023 - Tivoli","og_description":"Si informa la cittadinanza che \u00e8 stata pubblicata la\u00a0graduatoria degli ammessi al soggiorno estivo per gli utenti affetti da disabilit\u00e0\u00a0per l\u2019anno 2023 presso il villaggio Welcome di Tortoreto Lido nel [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-08-23T09:39:03+00:00","article_modified_time":"2023-08-23T09:41:34+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/servizi-sociali-e-casa.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023","datePublished":"2023-08-23T09:39:03+00:00","dateModified":"2023-08-23T09:41:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/"},"wordCount":78,"articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/","name":"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-08-23T09:39:03+00:00","dateModified":"2023-08-23T09:41:34+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/08\/23\/graduatoria-ammessi-al-soggiorno-estivo-per-utenti-affetti-da-disabilita-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Graduatoria ammessi al soggiorno estivo per utenti affetti da disabilit\u00e0 2023"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11047"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11047\/revisions"}],"predecessor-version":[{"id":11049,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11047\/revisions\/11049"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}