{"id":11146,"date":"2023-09-14T12:53:37","date_gmt":"2023-09-14T10:53:37","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11146"},"modified":"2023-09-14T13:51:19","modified_gmt":"2023-09-14T11:51:19","slug":"sabato-16-settembre-xii-reunion-bikers","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/","title":{"rendered":"XII Reunion Bikers sabato 16 settembre all&#8217;Anfiteatro di Bleso"},"content":{"rendered":"<p>Sabato\u00a0<strong>16 settembre<\/strong>\u00a02023 si terr\u00e0 la\u00a0<strong>XII Reunion Bikers<\/strong>, organizzata dall\u2019associazione MPM Roma M.C. in collaborazione con l\u2019Associazione 8212.<br \/>\nL\u2019evento si terr\u00e0\u00a0<strong>dalle ore 9 alle ore 24 di sabato<\/strong>, presso\u00a0<strong>la Rocca Pia e l\u2019Anfiteatro di Bleso<\/strong>, con l\u2019intento di promuovere la citt\u00e0 di Tivoli come punto di interesse anche\u00a0 per il turismo in moto.<\/p>\n<p>Dalle ore 17 fino al termine della manifestazione,\u00a0 all\u2019interno dell\u2019Anfiteatro di Bleso si terranno dj set ed esibizioni musicali, tra cui il concerto del gruppo \u201cGreg and the Rockin\u2019 Revenge\u201d, con il celebre comico del duo \u201cLillo &amp; Greg\u201d.<\/p>\n<p>Tutti coloro che saliranno sul palco si esibiranno a scopo benefico. Saranno inoltre presenti stand gastronomici e dedicati alla vendita di articoli vari.<\/p>\n<p>Il cortile interno della Rocca Pia sar\u00e0 adibito a spazio espositivo di rievocazioni medievali e dove sar\u00e0 allestita una mostra fotografica.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sabato\u00a016 settembre\u00a02023 si terr\u00e0 la\u00a0XII Reunion Bikers, organizzata dall\u2019associazione MPM Roma M.C. in collaborazione con l\u2019Associazione 8212. L\u2019evento si terr\u00e0\u00a0dalle ore 9 alle ore 24 di sabato, presso\u00a0la Rocca Pia [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":11147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-11146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XII Reunion Bikers sabato 16 settembre all&#039;Anfiteatro di Bleso - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XII Reunion Bikers sabato 16 settembre all&#039;Anfiteatro di Bleso - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sabato\u00a016 settembre\u00a02023 si terr\u00e0 la\u00a0XII Reunion Bikers, organizzata dall\u2019associazione MPM Roma M.C. in collaborazione con l\u2019Associazione 8212. L\u2019evento si terr\u00e0\u00a0dalle ore 9 alle ore 24 di sabato, presso\u00a0la Rocca Pia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-14T10:53:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T11:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/377700907_610147687954252_9219476399046056267_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1444\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"XII Reunion Bikers sabato 16 settembre all&#8217;Anfiteatro di Bleso\",\"datePublished\":\"2023-09-14T10:53:37+00:00\",\"dateModified\":\"2023-09-14T11:51:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/\"},\"wordCount\":150,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/377700907_610147687954252_9219476399046056267_n.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/\",\"name\":\"XII Reunion Bikers sabato 16 settembre all'Anfiteatro di Bleso - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/377700907_610147687954252_9219476399046056267_n.jpg\",\"datePublished\":\"2023-09-14T10:53:37+00:00\",\"dateModified\":\"2023-09-14T11:51:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/377700907_610147687954252_9219476399046056267_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/377700907_610147687954252_9219476399046056267_n.jpg\",\"width\":1444,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/14\\\/sabato-16-settembre-xii-reunion-bikers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XII Reunion Bikers sabato 16 settembre all&#8217;Anfiteatro di Bleso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XII Reunion Bikers sabato 16 settembre all'Anfiteatro di Bleso - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/","og_locale":"it_IT","og_type":"article","og_title":"XII Reunion Bikers sabato 16 settembre all'Anfiteatro di Bleso - Tivoli","og_description":"Sabato\u00a016 settembre\u00a02023 si terr\u00e0 la\u00a0XII Reunion Bikers, organizzata dall\u2019associazione MPM Roma M.C. in collaborazione con l\u2019Associazione 8212. L\u2019evento si terr\u00e0\u00a0dalle ore 9 alle ore 24 di sabato, presso\u00a0la Rocca Pia [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-09-14T10:53:37+00:00","article_modified_time":"2023-09-14T11:51:19+00:00","og_image":[{"width":1444,"height":2048,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/377700907_610147687954252_9219476399046056267_n.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"XII Reunion Bikers sabato 16 settembre all&#8217;Anfiteatro di Bleso","datePublished":"2023-09-14T10:53:37+00:00","dateModified":"2023-09-14T11:51:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/"},"wordCount":150,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/377700907_610147687954252_9219476399046056267_n.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/","name":"XII Reunion Bikers sabato 16 settembre all'Anfiteatro di Bleso - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/377700907_610147687954252_9219476399046056267_n.jpg","datePublished":"2023-09-14T10:53:37+00:00","dateModified":"2023-09-14T11:51:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/377700907_610147687954252_9219476399046056267_n.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/377700907_610147687954252_9219476399046056267_n.jpg","width":1444,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/14\/sabato-16-settembre-xii-reunion-bikers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"XII Reunion Bikers sabato 16 settembre all&#8217;Anfiteatro di Bleso"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"1"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11146"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11146\/revisions"}],"predecessor-version":[{"id":11151,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11146\/revisions\/11151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/11147"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}