{"id":11233,"date":"2023-09-25T13:53:37","date_gmt":"2023-09-25T11:53:37","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11233"},"modified":"2023-09-25T13:53:37","modified_gmt":"2023-09-25T11:53:37","slug":"ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/","title":{"rendered":"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo"},"content":{"rendered":"<p>Dal 25 settembre al 1 ottobre, al Marco Simone Golf &amp; Country Club di Guidonia Montecelio, arriva la\u00a0<strong>Ryder Cup<\/strong>, la competizione internazionale di golf pi\u00f9 prestigiosa al mondo. A battersi saranno due squadre: una con i migliori giocatori americani ed una con i migliori giocatori europei.<\/p>\n<p>Questo importante evento sportivo, il terzo pi\u00f9 seguito al mondo dopo le Olimpiadi e la Coppa del Mondo di calcio con oltre un miliardo di telespettatori, viene organizzato ogni due anni alternativamente una volta negli Stati Uniti ed una in Europa. L\u2019edizione 2023 \u00e8 la numero 44 e, per la prima volta in quasi 100 anni di storia, \u00e8 organizzata in Italia.<\/p>\n<p>L\u2019evento \u00e8 aperto al pubblico e prevede tre giornate di allenamento (26-28\/9) e tre giornate di competizione (29\/9-1\/10) durante le quali sono previsti 50.000 spettatori al giorno ed un totale di 270.000 presenze complessive sulla settimana dell\u2019evento.<\/p>\n<p>Per l\u2019occasione, sono state previste modifiche alla viabilit\u00e0 al piano del trasporto pubblico locale, che saranno comunicate tempestivamente, insieme agli eventuali aggiornamenti,\u00a0sul\u00a0<a href=\"https:\/\/www.guidonia.org\/notizia\/ryder-cup\/\">sito della Citt\u00e0 di Guidonia Montecelio<\/a>.<\/p>\n<p>Per tutte le info sulla\u00a0Ryder Cup, clicca <a href=\"https:\/\/www.rydercup.com\/it\">qui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 25 settembre al 1 ottobre, al Marco Simone Golf &amp; Country Club di Guidonia Montecelio, arriva la\u00a0Ryder Cup, la competizione internazionale di golf pi\u00f9 prestigiosa al mondo. A battersi [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":11234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-11233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Dal 25 settembre al 1 ottobre, al Marco Simone Golf &amp; Country Club di Guidonia Montecelio, arriva la\u00a0Ryder Cup, la competizione internazionale di golf pi\u00f9 prestigiosa al mondo. A battersi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-25T11:53:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/333037161_510243277927927_9172722314912546782_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo\",\"datePublished\":\"2023-09-25T11:53:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/\"},\"wordCount\":200,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/333037161_510243277927927_9172722314912546782_n.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/\",\"name\":\"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/333037161_510243277927927_9172722314912546782_n.jpg\",\"datePublished\":\"2023-09-25T11:53:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/333037161_510243277927927_9172722314912546782_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/333037161_510243277927927_9172722314912546782_n.jpg\",\"width\":960,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/25\\\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/","og_locale":"it_IT","og_type":"article","og_title":"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo - Tivoli","og_description":"Dal 25 settembre al 1 ottobre, al Marco Simone Golf &amp; Country Club di Guidonia Montecelio, arriva la\u00a0Ryder Cup, la competizione internazionale di golf pi\u00f9 prestigiosa al mondo. A battersi [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-09-25T11:53:37+00:00","og_image":[{"width":960,"height":480,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/333037161_510243277927927_9172722314912546782_n.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo","datePublished":"2023-09-25T11:53:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/"},"wordCount":200,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/333037161_510243277927927_9172722314912546782_n.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/","name":"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/333037161_510243277927927_9172722314912546782_n.jpg","datePublished":"2023-09-25T11:53:37+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/333037161_510243277927927_9172722314912546782_n.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/333037161_510243277927927_9172722314912546782_n.jpg","width":960,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/25\/ryder-cup-2023-dal-25-settembre-al-1-ottobre-al-marco-simone-golf-country-club-la-competizione-internazionale-di-golf-piu-prestigiosa-al-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Ryder Cup 2023: dal 25 settembre al 1 ottobre al Marco Simone Golf &amp; Country Club la competizione internazionale di golf pi\u00f9 prestigiosa al mondo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11233"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11233\/revisions"}],"predecessor-version":[{"id":11235,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11233\/revisions\/11235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/11234"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}