{"id":11249,"date":"2023-09-27T13:29:32","date_gmt":"2023-09-27T11:29:32","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11249"},"modified":"2023-09-27T13:29:32","modified_gmt":"2023-09-27T11:29:32","slug":"incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/","title":{"rendered":"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0"},"content":{"rendered":"<p lang=\"\" xml:lang=\"\">Venerd\u00ec 29 settembre 2023, alle ore 16, presso il Museo della Citt\u00e0, il Comune di Tivoli organizza l&#8217;incontro pubblico dal titolo\u00a0&#8220;Settembre, andiamo, \u00e8 tempo di&#8230;&#8221; con l&#8217;intento di condividere le esperienze del Settembre tiburtino 2023, ancora in corso, e le nuove proposte relative alla manifestazione. Al panel prenderanno parte anche\u00a0Slow Food Tivoli e Valle dell&#8217;Aniene e VILLAE.<\/p>\n<p lang=\"\" xml:lang=\"\">Nel corso del pomeriggio si terr\u00e0 la premiazione del contest fotografico &#8220;\u00c8 tempo di mirare&#8221; con esposizione presso il Museo della Citt\u00e0. A seguire, aperitivo a cura di Slow Food Tivoli e Valle dell&#8217;Aniene e Unione Commercio e Turismo Tivoli.<\/p>\n<p lang=\"\" xml:lang=\"\"><strong>CONSULTA IL PROGRAMMA<\/strong><\/p>\n<p lang=\"\" xml:lang=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-11250\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-725x1024.jpg\" alt=\"\" width=\"640\" height=\"904\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-725x1024.jpg 725w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-212x300.jpg 212w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-768x1085.jpg 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web.jpg 1000w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 29 settembre 2023, alle ore 16, presso il Museo della Citt\u00e0, il Comune di Tivoli organizza l&#8217;incontro pubblico dal titolo\u00a0&#8220;Settembre, andiamo, \u00e8 tempo di&#8230;&#8221; con l&#8217;intento di condividere le [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11249","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 29 settembre 2023, alle ore 16, presso il Museo della Citt\u00e0, il Comune di Tivoli organizza l&#8217;incontro pubblico dal titolo\u00a0&#8220;Settembre, andiamo, \u00e8 tempo di&#8230;&#8221; con l&#8217;intento di condividere le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T11:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-725x1024.jpg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0\",\"datePublished\":\"2023-09-27T11:29:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/\"},\"wordCount\":112,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/Proposte-Settembre-Tiburtino-web-725x1024.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/\",\"name\":\"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/Proposte-Settembre-Tiburtino-web-725x1024.jpg\",\"datePublished\":\"2023-09-27T11:29:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/Proposte-Settembre-Tiburtino-web.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/09\\\/Proposte-Settembre-Tiburtino-web.jpg\",\"width\":1000,\"height\":1413},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/09\\\/27\\\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/","og_locale":"it_IT","og_type":"article","og_title":"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0 - Tivoli","og_description":"Venerd\u00ec 29 settembre 2023, alle ore 16, presso il Museo della Citt\u00e0, il Comune di Tivoli organizza l&#8217;incontro pubblico dal titolo\u00a0&#8220;Settembre, andiamo, \u00e8 tempo di&#8230;&#8221; con l&#8217;intento di condividere le [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-09-27T11:29:32+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-725x1024.jpg","type":"","width":"","height":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0","datePublished":"2023-09-27T11:29:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/"},"wordCount":112,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-725x1024.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/","name":"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web-725x1024.jpg","datePublished":"2023-09-27T11:29:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/09\/Proposte-Settembre-Tiburtino-web.jpg","width":1000,"height":1413},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/09\/27\/incontro-pubblico-sui-risultati-e-le-esperienze-del-settembre-tiburtino-2023-venerdi-29-settembre-al-museo-della-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Incontro pubblico sui risultati e le esperienze del Settembre tiburtino 2023: venerd\u00ec 29 settembre al Museo della Citt\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11249"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11249\/revisions"}],"predecessor-version":[{"id":11251,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11249\/revisions\/11251"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}