{"id":11413,"date":"2023-11-14T11:50:10","date_gmt":"2023-11-14T10:50:10","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11413"},"modified":"2023-11-14T11:50:10","modified_gmt":"2023-11-14T10:50:10","slug":"mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/","title":{"rendered":"&#8220;Mio padre, Little Tony&#8221;: Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre"},"content":{"rendered":"<p>La citt\u00e0 di Tivoli ospita la presentazione del libro\u00a0<strong>&#8220;Mio padre, Little Tony&#8221;<\/strong>\u00a0scritto dalla figlia del grande cantante,\u00a0<strong>Cristiana Ciacci<\/strong>, e da Teresa Giulietti. Appuntamento\u00a0<strong>venerd\u00ec 17 Novembre 2023 dalle ore 16.00<\/strong>\u00a0presso l\u2019Aula Magna del Convitto Nazionale \u201cAmedeo di Savoia Duca d\u2019Aosta\u201d in piazza Giuseppe Garbaldi: nel corso della presentazione, la Ciacci sveler\u00e0 alcuni segreti del suo rapporto con il pap\u00e0.<\/p>\n<p>\u00c8 l\u2019<strong>Accademia Ergo Cantemus coro ed Orchestre di Tivoli<\/strong>, con il patrocinio del\u00a0<strong>Comune di Tivoli<\/strong>\u00a0e \u00a0<strong>Assoarma Consiglio Provinciale<\/strong>, in collaborazione con il Conservatorio di Musica \u201cSanta Cecilia\u201d di Roma, a concludere un prodigioso iter commemorativo nel 2023, per il decennale dalla scomparsa di Little Tony .<\/p>\n<p>Nel libro, edito da Bertoni Editore con la prefazione di Mara Venier, grazie alla preziosa collaborazione di Teresa Giulietti, scrittrice e ghostwriter, la figlia dell\u2019Elvis italiano ripercorre la sua vita raccontando, in particolare, aneddoti privati della sua infanzia. Anche se cresciuta, la Cristiana adolescente e quel che sar\u00e0 poi la Cristiana giovane donna, ha sempre e solo desiderato una famiglia da vivere, radici e certezze, lei che si definisce \u201cbulimica d\u2019amore\u201d ne ha sofferto talmente tanto da cadere vittima dell\u2019anoressia.<\/p>\n<p>Diversi, dunque,\u00a0i temi che verranno trattati nel corso della presentazione. Cristiana Ciacci sar\u00e0 affiancata nei saluti di benvenuto dal presidente della Accademia Ergo Cantemus Luana Frascarelli e dalla Prof.ssa Maria Buongiorno, da Fabio Angeloni giornalista nonch\u00e8 scrittore, e dal moderatore Dott. Aleandro Fusco.<\/p>\n<p>Non mancheranno attimi musicali dedicati alla pace, con Sofia Paterni, voce bianca del Teatro dell\u2019Opera di Roma accompagnata al Pianoforte da Matteo Siscaro e la proiezione dell\u2019ultimo videoclip \u201cStringimi forte\u201d di Cristiana Ciacci che sar\u00e0 in sala insieme ad Angelo Petruccetti per salutare il pubblico, e a far da sfondo in showtime, le fotografie inedite della famiglia Ciacci.<\/p>\n<p>La presentazione vedr\u00e0 un momento istituzionale della Accademia Ergo Cantemus con il conferimento a nuove personalit\u00e0 che faranno parte del neo Comitato Artistico, alla presenza del Presidente Onorario Can.Ciro Zeno.<\/p>\n<p>La giornata si concluder\u00e0 con l\u2019intervento del M\u00b0 Prof. Roberto Giuliani, Capo delle relazioni esterne nazionali e internazionali del Conservatorio di Musica \u201cSanta Cecilia\u201d di Roma, in relazione ai progetti formativi musicali in tema di Orchestra Giovanile della Citt\u00e0 di Tivoli ed attivit\u00e0 prossime con l\u2019associazione culturale Accademia Ergo Cantemus.<\/p>\n<p>Cristiana Ciacci ed Angelo Petruccetti, saranno lieti, in fine evento, di salutare il pubblico presente al book-corner allestito in sala per l\u2019occasione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La citt\u00e0 di Tivoli ospita la presentazione del libro\u00a0&#8220;Mio padre, Little Tony&#8221;\u00a0scritto dalla figlia del grande cantante,\u00a0Cristiana Ciacci, e da Teresa Giulietti. Appuntamento\u00a0venerd\u00ec 17 Novembre 2023 dalle ore 16.00\u00a0presso l\u2019Aula [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":11414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Mio padre, Little Tony&quot;: Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Mio padre, Little Tony&quot;: Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre - Tivoli\" \/>\n<meta property=\"og:description\" content=\"La citt\u00e0 di Tivoli ospita la presentazione del libro\u00a0&#8220;Mio padre, Little Tony&#8221;\u00a0scritto dalla figlia del grande cantante,\u00a0Cristiana Ciacci, e da Teresa Giulietti. Appuntamento\u00a0venerd\u00ec 17 Novembre 2023 dalle ore 16.00\u00a0presso l\u2019Aula [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T10:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/locandina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"904\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;Mio padre, Little Tony&#8221;: Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre\",\"datePublished\":\"2023-11-14T10:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/\"},\"wordCount\":416,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/locandina.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/\",\"name\":\"\\\"Mio padre, Little Tony\\\": Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/locandina.jpg\",\"datePublished\":\"2023-11-14T10:50:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/locandina.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/locandina.jpg\",\"width\":904,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/14\\\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Mio padre, Little Tony&#8221;: Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Mio padre, Little Tony\": Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/","og_locale":"it_IT","og_type":"article","og_title":"\"Mio padre, Little Tony\": Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre - Tivoli","og_description":"La citt\u00e0 di Tivoli ospita la presentazione del libro\u00a0&#8220;Mio padre, Little Tony&#8221;\u00a0scritto dalla figlia del grande cantante,\u00a0Cristiana Ciacci, e da Teresa Giulietti. Appuntamento\u00a0venerd\u00ec 17 Novembre 2023 dalle ore 16.00\u00a0presso l\u2019Aula [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-11-14T10:50:10+00:00","og_image":[{"width":904,"height":1280,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/locandina.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;Mio padre, Little Tony&#8221;: Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre","datePublished":"2023-11-14T10:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/"},"wordCount":416,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/locandina.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/","name":"\"Mio padre, Little Tony\": Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/locandina.jpg","datePublished":"2023-11-14T10:50:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/locandina.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/locandina.jpg","width":904,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/14\/mio-padre-little-tony-cristiana-ciacci-presenta-il-libro-dedicato-al-padre-venerdi-17-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;Mio padre, Little Tony&#8221;: Cristiana Ciacci presenta il libro dedicato al padre venerd\u00ec 17 novembre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11413"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11413\/revisions"}],"predecessor-version":[{"id":11415,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11413\/revisions\/11415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/11414"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}