{"id":11424,"date":"2023-11-16T14:20:21","date_gmt":"2023-11-16T13:20:21","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11424"},"modified":"2023-11-16T14:20:21","modified_gmt":"2023-11-16T13:20:21","slug":"il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/","title":{"rendered":"&#8220;Il mondo di Babbo Natale&#8221;: la magia si accende a Tivoli dal 18 novembre al 6 gennaio"},"content":{"rendered":"<p>Tivoli si prepara a dare il benvenuto alla magia del Natale con un evento straordinario:\u00a0<strong>&#8220;Il Mondo di Babbo Natale&#8221;<\/strong>, dal 18 novembre 2023 al 6 gennaio 2024. Questa incantevole manifestazione natalizia, organizzata dalla Planner Srl, patrocinata e promossa dal Comune di Tivoli, grazie anche all&#8217;azione sinergica dell&#8217;Unione Commercio e Turismo,\u00a0porter\u00e0 in citt\u00e0 un&#8217;atmosfera fiabesca, ricca di gioia e divertimento per tutta la famiglia.<\/p>\n<p>Il cuore dell&#8217;evento sar\u00e0 il Mondo di Babbo Natale, posizionato tra le Scuderie Estensi, piazza Garibaldi e il centro storico,\u00a0un luogo incantato dove grandi e piccini potranno\u00a0<strong>incontrare Babbo Natale<\/strong>, consegnare le loro letterine direttamente all&#8217;<strong>Ufficio Postale di Babbo Natale<\/strong>, curiosare nella sua camera e nella sua cucina e scattare foto indimenticabili. Gli elfi saranno l\u00ec per assistere e rendere ogni incontro magico. I\u00a0<strong>mercatini natalizi\u00a0<\/strong>di piazza Garibaldi offriranno una vasta selezione di regali unici, prodotti artigianali e delizie culinarie per soddisfare ogni palato.<\/p>\n<p>Chi ama lo street food, sar\u00e0 viziato dalla variet\u00e0 di prelibatezze da gustare per strada. Una\u00a0<strong>pista di pattinaggio<\/strong>\u00a0all&#8217;aperto sar\u00e0 il luogo ideale per scivolare e godersi il freddo pungente. E per chi preferisce fare un giro panoramico, meglio non perdere l&#8217;opportunit\u00e0 di salire a bordo del\u00a0<strong>trenino natalizio<\/strong>\u00a0e ammirare le luci scintillanti della citt\u00e0. Previsti anche laboratori, spettacoli con personaggi Disney e nevicate finte.<\/p>\n<p>Il Sindaco di Tivoli\u00a0<strong>Giuseppe Proietti<\/strong> d\u00e0 il benvenuto cos\u00ec a questa nuova manifestazione: &#8220;Quest&#8217;anno abbiamo voluto valorizzare il significato del Natale con una formula attenta all&#8217;intrattenimento dei pi\u00f9 piccoli e delle loro famiglie e &#8211; perch\u00e9 no &#8211; anche di chi vuole tornare a sentirsi bambino. Proprio qui, nella nostra citt\u00e0, i luoghi che ci sono tanto familiari si accenderanno di magia, offrendo ai tanti tiburtini e ai tanti turisti un&#8217;occasione unica di svago. L&#8217;iniziativa non pu\u00f2 che giovare anche all&#8217;economia del territorio, alle attivit\u00e0 commerciali, ai locali e alle strutture ricettive: ci si aspetta infatti un&#8217;elevata affluenza di visitatori&#8221;.<\/p>\n<p>Oltre a convenzioni speciali con strutture ricettive, il Mondo di Babbo Natale ha previsto sconti speciali nei negozi della citt\u00e0 segnalati con il\u00a0<strong>bollino di negozio &#8220;Amico di Babbo Natale&#8221;:<\/strong>\u00a0basta presentare il biglietto all&#8217;ingresso.<\/p>\n<p>Per ulteriori informazioni sugli eventi e le attivit\u00e0 durante il periodo natalizio a Tivoli, visita il\u00a0sito web all&#8217;indirizzo\u00a0<a href=\"https:\/\/ilmondodibabbonatale.com\/\">www.ilmondodibabbonatale.com<\/a>.<br \/>\n<em><strong>COSA TROVERAI<\/strong><\/em><\/p>\n<p><strong>SCUDERIE ESTENSI:<\/strong><\/p>\n<p><strong>LA SALA DEL TRONO\u00a0<\/strong>dove Babbo Natale ricever\u00e0 le vostre visite!<\/p>\n<p><strong>CAMERA DA LETTO\u00a0<\/strong>con il lettone di Babbo Natale dal vivo!<\/p>\n<p><strong>SALOTTO DI BABBO NATALE\u00a0<\/strong>dove legge Babbo Natale tutte le vostre letterine&#8230;<\/p>\n<p><strong>LA SLITTA CON LE RENNE\u00a0<\/strong>a grandezza naturale!<\/p>\n<p><strong>CUCINA DI BABBO NATALE\u00a0<\/strong>ricostruzione della stanza preferita di Babbo Natale<\/p>\n<p><strong>VILLAGGIO DEGLI ELFI\u00a0<\/strong>un villaggio natalizio incantato a grandezza naturale<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SS ANNUNZIATA:<\/strong><\/p>\n<p><strong>LABORATORI NATALIZI<\/strong><\/p>\n<p><strong>UFFICIO POSTALE DI BABBO NATALE<\/strong><\/p>\n<p><strong>COLLEGAMENTO CON IL TRENINO DI BABBO NATALE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>CENTRO CITTA&#8217; DI TIVOLI<\/strong><\/p>\n<p><strong>PISTA SUL GHIACCIO<\/strong><\/p>\n<p><strong>MERCATINI DI NATALE<\/strong><\/p>\n<p><strong>STREET FOOD<\/strong><\/p>\n<p><strong>NEGOZI<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>COSTI E INFO SUI BIGLIETTI<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>I BIGLIETTI PER IL MONDO DI BABBO NATALE, COMPRENDONO TUTTO IL\u00a0<strong>PROGRAMMA:<\/strong><\/p>\n<p>\u2013\u00a0<strong>SCUDERIE ESTENSI\u00a0<\/strong>DIMORA DI<strong>\u00a0BABBO NATALE<\/strong>\u00a0 ( SALA DEL TRONO- VILLAGGIO DEGLI ELFI -SLITTA CON LE RENNE \u2013 CUCINA DI BABBO NATALE E SALOTTO )<\/p>\n<p>\u2013\u00a0<strong>EX SS ANNUNZIATA\u00a0<\/strong>UFFICIO POSTALE \u2013 SPAZIO LETTERINA \u2013 LABORATORI ( A PIEDI O COL TRENINO)<\/p>\n<p>\u2013\u00a0<strong>SPETTACOLI\u00a0 ORE 11.00 E ORE 15.45<\/strong>\u00a0IN PIAZZA GARIBALDI IN CASO DI PIOGGIA<strong>\u00a0NON<\/strong>\u00a0VERRANNO ESEGUITI<\/p>\n<p><strong>NON SONO COMPRESI NEL BIGLIETTO<\/strong>\u00a0:\u00a0 TRENINO<\/p>\n<p><strong>INTERO<\/strong>\u00a0\u20ac 12,00<br \/>\n( 12 ANNI &#8211; 64 ANNI)<br \/>\n<strong>RIDOTTO<\/strong>\u00a0\u20ac 10,00<br \/>\n( 2 ANNI -11 ANNI \/ OVER 65 \/ FORZE ARMATE- ACCOMPAGNATORI DISABILI)<br \/>\n<strong>Residenti Comune di Tivoli\u00a0<\/strong>\u20ac 6,00 ( con documento)<br \/>\n<strong>OMAGGIO<\/strong>\u00a0\u20ac 0,00<br \/>\n(DISABILI &#8211; MAESTRE ( in gita scolastica) 1 OGNI 25 PX GITA)<br \/>\nNB: Il biglietto \u00e8\u00a0valido solo nella data di emissione, si puo&#8217; entrare ed uscire con un timbro nell&#8217;arco dell&#8217;intera giornata<br \/>\nFAQ: cani ammessi &#8211; corsia preferenziale per donne in dolce attesa<\/p>\n<p><strong>BIGLIETTO\u00a0<a href=\"https:\/\/www.ciaotickets.com\/biglietti\/il-mondo-di-babbo-natale-campi-bisenzio\">ONLINE<\/a><\/strong>: Maggiorazione di \u20ac 1 ENTRA SENZA FARE LA FILA!<\/p>\n<p><strong>TRENINO DI BABBO NATALE<\/strong>: Un percorso di 3 km, che vi portera\u2019 in centro per poter continuare la magia natalizia andata e ritorno<\/p>\n<p><strong>ADULTI<\/strong>\u00a03,00\u20ac\u00a0<strong>\u00a0BIMBI<\/strong>\u00a02,00\u20ac<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-11429\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-1-1024x724.png\" alt=\"\" width=\"640\" height=\"453\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-1-1024x724.png 1024w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-1-300x212.png 300w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-1-768x543.png 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-1-1536x1086.png 1536w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-1.png 2000w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-11428\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-4-1024x724.png\" alt=\"\" width=\"640\" height=\"453\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-4-1024x724.png 1024w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-4-300x212.png 300w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-4-768x543.png 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-4-1536x1086.png 1536w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/mappa-4.png 2000w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11427\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/CALENDARIO-202324-1.png\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/CALENDARIO-202324-1.png 940w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/CALENDARIO-202324-1-300x251.png 300w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/CALENDARIO-202324-1-768x644.png 768w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-11426\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-retro-tivoli-2023-722x1024.jpg\" alt=\"\" width=\"640\" height=\"908\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-retro-tivoli-2023-722x1024.jpg 722w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-retro-tivoli-2023-211x300.jpg 211w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-retro-tivoli-2023-768x1090.jpg 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-retro-tivoli-2023-1083x1536.jpg 1083w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-retro-tivoli-2023-1444x2048.jpg 1444w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-retro-tivoli-2023.jpg 1748w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Tivoli si prepara a dare il benvenuto alla magia del Natale con un evento straordinario:\u00a0&#8220;Il Mondo di Babbo Natale&#8221;, dal 18 novembre 2023 al 6 gennaio 2024. Questa incantevole manifestazione [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":11425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-11424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Il mondo di Babbo Natale&quot;: la magia si accende a Tivoli dal 18 novembre al 6 gennaio - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Il mondo di Babbo Natale&quot;: la magia si accende a Tivoli dal 18 novembre al 6 gennaio - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Tivoli si prepara a dare il benvenuto alla magia del Natale con un evento straordinario:\u00a0&#8220;Il Mondo di Babbo Natale&#8221;, dal 18 novembre 2023 al 6 gennaio 2024. Questa incantevole manifestazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T13:20:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-Fronte-tivoli-gi-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"2480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;Il mondo di Babbo Natale&#8221;: la magia si accende a Tivoli dal 18 novembre al 6 gennaio\",\"datePublished\":\"2023-11-16T13:20:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/\"},\"wordCount\":653,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/volantino-Fronte-tivoli-gi-2023.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/\",\"name\":\"\\\"Il mondo di Babbo Natale\\\": la magia si accende a Tivoli dal 18 novembre al 6 gennaio - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/volantino-Fronte-tivoli-gi-2023.jpg\",\"datePublished\":\"2023-11-16T13:20:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/volantino-Fronte-tivoli-gi-2023.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2023\\\/11\\\/volantino-Fronte-tivoli-gi-2023.jpg\",\"width\":1748,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/16\\\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Il mondo di Babbo Natale&#8221;: la magia si accende a Tivoli dal 18 novembre al 6 gennaio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Il mondo di Babbo Natale\": la magia si accende a Tivoli dal 18 novembre al 6 gennaio - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/","og_locale":"it_IT","og_type":"article","og_title":"\"Il mondo di Babbo Natale\": la magia si accende a Tivoli dal 18 novembre al 6 gennaio - Tivoli","og_description":"Tivoli si prepara a dare il benvenuto alla magia del Natale con un evento straordinario:\u00a0&#8220;Il Mondo di Babbo Natale&#8221;, dal 18 novembre 2023 al 6 gennaio 2024. Questa incantevole manifestazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-11-16T13:20:21+00:00","og_image":[{"width":1748,"height":2480,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-Fronte-tivoli-gi-2023.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;Il mondo di Babbo Natale&#8221;: la magia si accende a Tivoli dal 18 novembre al 6 gennaio","datePublished":"2023-11-16T13:20:21+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/"},"wordCount":653,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-Fronte-tivoli-gi-2023.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/","name":"\"Il mondo di Babbo Natale\": la magia si accende a Tivoli dal 18 novembre al 6 gennaio - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-Fronte-tivoli-gi-2023.jpg","datePublished":"2023-11-16T13:20:21+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-Fronte-tivoli-gi-2023.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/volantino-Fronte-tivoli-gi-2023.jpg","width":1748,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/16\/il-mondo-di-babbo-natale-la-magia-si-accende-a-tivoli-dal-18-novembre-al-6-gennaio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;Il mondo di Babbo Natale&#8221;: la magia si accende a Tivoli dal 18 novembre al 6 gennaio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11424"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11424\/revisions"}],"predecessor-version":[{"id":11430,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11424\/revisions\/11430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/11425"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}