{"id":11481,"date":"2023-11-24T12:41:25","date_gmt":"2023-11-24T11:41:25","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11481"},"modified":"2023-11-24T12:41:25","modified_gmt":"2023-11-24T11:41:25","slug":"chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/","title":{"rendered":"Chiusura del plesso scolastico di Tivoli Terme &#8220;Tommaso Neri&#8221; per demolizione e ricostruzione"},"content":{"rendered":"<p>Con l&#8217;ordinanza n. 506 del 24\/11\/2023 si ordina\u00a0la sospensione delle attivita\u0300 didattiche per il Plesso Tommaso Neri \u2013 Tivoli Terme &#8211; sezioni Infanzia e Primaria a decorrere dal 27\/11\/2023 al 28\/11\/2023 compreso, per lo sgombero da persone e cose, ed allestimento degli spazi scolastici individuati, con la chiusura dell\u2019intero Plesso Tommaso Neri fino ad ultimazione dei lavori delle opere di demolizione e ricostruzione dell\u2019edificio in forza del finanziamento PNRR \u201cMissione 4 Componente 1 Investimento 3.3 &#8211; piano di messa in sicurezza e riqualificazione dell\u2019edilizia scolastica \u2013 lavori di ampliamento ed adeguamento dei plessi scolastici T.Neri E G.Rodari\u201d.<\/p>\n<p>Per maggiori informazioni consultare l&#8217;ordinanza integrale nella sezione allegati.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_11482\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/Ordinanza-n.-506-del-24112023.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/11\/Ordinanza-n.-506-del-24112023.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza n. 506 del 24\/11\/2023<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con l&#8217;ordinanza n. 506 del 24\/11\/2023 si ordina\u00a0la sospensione delle attivita\u0300 didattiche per il Plesso Tommaso Neri \u2013 Tivoli Terme &#8211; sezioni Infanzia e Primaria a decorrere dal 27\/11\/2023 al [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-11481","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiusura del plesso scolastico di Tivoli Terme &quot;Tommaso Neri&quot; per demolizione e ricostruzione - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiusura del plesso scolastico di Tivoli Terme &quot;Tommaso Neri&quot; per demolizione e ricostruzione - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Con l&#8217;ordinanza n. 506 del 24\/11\/2023 si ordina\u00a0la sospensione delle attivita\u0300 didattiche per il Plesso Tommaso Neri \u2013 Tivoli Terme &#8211; sezioni Infanzia e Primaria a decorrere dal 27\/11\/2023 al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-24T11:41:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Chiusura del plesso scolastico di Tivoli Terme &#8220;Tommaso Neri&#8221; per demolizione e ricostruzione\",\"datePublished\":\"2023-11-24T11:41:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/\"},\"wordCount\":116,\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/\",\"name\":\"Chiusura del plesso scolastico di Tivoli Terme \\\"Tommaso Neri\\\" per demolizione e ricostruzione - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-11-24T11:41:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/11\\\/24\\\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiusura del plesso scolastico di Tivoli Terme &#8220;Tommaso Neri&#8221; per demolizione e ricostruzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiusura del plesso scolastico di Tivoli Terme \"Tommaso Neri\" per demolizione e ricostruzione - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/","og_locale":"it_IT","og_type":"article","og_title":"Chiusura del plesso scolastico di Tivoli Terme \"Tommaso Neri\" per demolizione e ricostruzione - Tivoli","og_description":"Con l&#8217;ordinanza n. 506 del 24\/11\/2023 si ordina\u00a0la sospensione delle attivita\u0300 didattiche per il Plesso Tommaso Neri \u2013 Tivoli Terme &#8211; sezioni Infanzia e Primaria a decorrere dal 27\/11\/2023 al [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-11-24T11:41:25+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Chiusura del plesso scolastico di Tivoli Terme &#8220;Tommaso Neri&#8221; per demolizione e ricostruzione","datePublished":"2023-11-24T11:41:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/"},"wordCount":116,"articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/","name":"Chiusura del plesso scolastico di Tivoli Terme \"Tommaso Neri\" per demolizione e ricostruzione - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-11-24T11:41:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/11\/24\/chiusura-del-plesso-scolastico-di-tivoli-terme-tommaso-neri-per-demolizione-e-ricostruzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Chiusura del plesso scolastico di Tivoli Terme &#8220;Tommaso Neri&#8221; per demolizione e ricostruzione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11481"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11481\/revisions"}],"predecessor-version":[{"id":11483,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11481\/revisions\/11483"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}