{"id":11589,"date":"2023-12-14T17:19:03","date_gmt":"2023-12-14T16:19:03","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11589"},"modified":"2023-12-14T17:20:12","modified_gmt":"2023-12-14T16:20:12","slug":"villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/","title":{"rendered":"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli"},"content":{"rendered":"<p>Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il <strong>ripristino del manto stradale <\/strong>prima su via di Villa Adriana e poi su via Galli.<\/p>\n<p>Per tale motivo subir\u00e0 alcune modifiche operative l&#8217;intervento di ripristino integrale di via Venezia Tridentina che verr\u00e0 effettuato senza prevedere la chiusura.<\/p>\n<p>Nella giornata di domani, venerd\u00ec\u00a0 15 dicembre, verranno fornite tutte le specifiche delle modifiche alla viabilit\u00e0 e verranno comunicate le relative ordinanze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il ripristino del [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-11589","post","type-post","status-publish","format-standard","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il ripristino del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T16:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-14T16:20:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli\",\"datePublished\":\"2023-12-14T16:19:03+00:00\",\"dateModified\":\"2023-12-14T16:20:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/\"},\"wordCount\":100,\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/\",\"name\":\"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-12-14T16:19:03+00:00\",\"dateModified\":\"2023-12-14T16:20:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/14\\\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/","og_locale":"it_IT","og_type":"article","og_title":"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli - Tivoli","og_description":"Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il ripristino del [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-12-14T16:19:03+00:00","article_modified_time":"2023-12-14T16:20:12+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli","datePublished":"2023-12-14T16:19:03+00:00","dateModified":"2023-12-14T16:20:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/"},"wordCount":100,"articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/","name":"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-12-14T16:19:03+00:00","dateModified":"2023-12-14T16:20:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/14\/villa-adriana-da-lunedi-18-dicembre-ripristino-asfalto-via-di-villa-adriana-e-via-galli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Villa Adriana: da luned\u00ec 18 dicembre ripristino manto stradale via di Villa Adriana e via Galli"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11589"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11589\/revisions"}],"predecessor-version":[{"id":11591,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11589\/revisions\/11591"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}