{"id":11604,"date":"2023-12-15T19:29:13","date_gmt":"2023-12-15T18:29:13","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11604"},"modified":"2023-12-15T19:29:13","modified_gmt":"2023-12-15T18:29:13","slug":"lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/","title":{"rendered":"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana"},"content":{"rendered":"<p>Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il\u00a0<strong>ripristino del manto stradale\u00a0<\/strong>prima su via di Villa Adriana e poi su via Galli.<\/p>\n<p>La modifica temporanea dell\u2019attuale regolamentazione stradale sar\u00e0 a \u201cSTEP\u201d.<\/p>\n<p>La Vicesindaca e Assessora ai Lavori Pubblici <strong>Laura Di Giuseppe<\/strong> afferma: \u201cSappiamo che stiamo chiedendo un penultimo sforzo ai cittadini di Villa Adriana per il ripristino totale di tutta via di Villa Adriana e di via Galli, le cui condizioni, in termini di sicurezza non ci mettono nella posizione di posticipare ulteriormente l&#8217;intervento da parte di Acea. Tutte le restanti vie di Villa Adriana e di Paterno interessate dalla bonifica saranno ripristinate entro Aprile 2024, l&#8217;ultimo disagio che dovranno subire prima di poter avere le vie totalmente ripristinate e la rete idrica totalmente bonificata. Da mesi chiediamo e sollecitiamo il ripristino che fino ad ora \u00e8 stato rinviato per serie difficolt\u00e0 tecniche di passaggio dalla vecchia rete di adduzione idrica a quella nuova. Abbiamo chiesto uno sforzo in termini di gestione del cantiere tale che possa avanzare man mano cercando di minimizzare l&#8217;impatto sulla viabilit\u00e0 e sulla possibilit\u00e0 di raggiungere le attivit\u00e0 commerciali in questo periodo dell&#8217;anno&#8221;<\/p>\n<p><strong>Pamela Corbo<\/strong>, consigliera del Sindaco per il quartiere di Villa Adriana, aggiunge:\u00a0\u201cNon siamo entusiasti che i lavori di ripristino avvengano proprio nel periodo natalizio, ma sappiamo tutti di quanto bisogno ci sia di ripristinare l&#8217;asfalto nelle vie oggetto dell&#8217;intervento oramai impraticabili. Non partire oggi rischierebbe di far slittare il tutto di ulteriori settimane. Chiedo alle imprese di Acea di fare il possibile per minimizzare l&#8217;impatto del cantiere e auspico che l&#8217;intervento possa avvenire anche in meno tempo rispetto a quanto previsto. Anche io sono una cittadina prima di avere un ruolo istituzionale e come tale sono pienamente in grado di comprendere i disagi che tutti noi subiremo in questi giorni. Cercher\u00f2 in prima persona di seguire i lavori costantemente per garantire una gestione con meno impatto possibile sulla viabilit\u00e0 per permettere anche alle attivit\u00e0 commerciali di continuare il loro lavoro con meno disagi possibile&#8221;.<\/p>\n<h3><strong>1\u00b0 Step dal 18\/12\/2023 al 19\/12\/2023 nella fascia oraria 09:00\/18:00<\/strong><\/h3>\n<h3>(e comunque fino al termine dei lavori)<\/h3>\n<ul>\n<li>VIA DI VILLA ADRIANA (intersezione con via Rosolina)<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO A TUTTI I VEICOLI<\/p>\n<p>(ad eccezione de mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso)<\/p>\n<ul>\n<li>VIA DI VILLA ADRIANA (tratto compreso tra via Rosolina e via Galli)<\/li>\n<\/ul>\n<p>DIVIETO DI SOSTA CON RIMOZIONE FORZATA DEI VEICOLI INADEMPIENTI\u00a0 SU AMBO I LATI<\/p>\n<ul>\n<li>VIA DI VILLA ADRIANA (intersezione con via Rosolina per i veicoli provenienti da largo Yourcenar)<\/li>\n<\/ul>\n<p>OBBLIGO DI SVOLTA A SINISTRA IN DIREZIONE DI VIA ROSOLINA<\/p>\n<ul>\n<li>VIA DON A. PANATTONI\u00a0 &#8211; intersezione con via Villa Adriana:<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>VIA G. AMENDOLA &#8211; intersezione con via Villa Adriana:<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>VIA ROSOLINA: &#8211; ambo i lati dal civico 06 all\u2019intersezione con via di Villa Adriana \u2013<\/li>\n<\/ul>\n<p>DIVIETO DI SOSTA CON RIMOZIONE FORZATA<\/p>\n<ul>\n<li>VIA ROSOLINA: &#8211; intersezione con via di Villa Adriana \u2013<\/li>\n<\/ul>\n<p>OBBLIGO DI SVOLTA A DESTRA IN DIREZIONE DI LARGO M. YOURCENAR<\/p>\n<h3><\/h3>\n<h3><strong>2\u00b0 Step dal 20\/12\/2023 al 23\/12\/2023 nella fascia oraria 09:00\/18:00 <\/strong><\/h3>\n<h3><strong>(e comunque fino al termine dei lavori)<\/strong><\/h3>\n<ul>\n<li>VIA GALLI\u00a0 (intersezione con via di Villa Adriana)<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO A TUTTI I VEICOLI<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>VIA GALLI (tratto compreso tra via Villa Adriana e via Rosolina)<\/li>\n<\/ul>\n<p>DIVIETO DI SOSTA CON RIMOZIONE FORZATA DEI VEICOLI INADEMPIENTI\u00a0 SU AMBO I LATI<\/p>\n<ul>\n<li>VIA ALTO ADIGE\u00a0 &#8211; intersezione con via Galli<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>VICOLO GALLI\u00a0 &#8211; intersezione con via Galli<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>LARGO FRANCESCHI\u00a0 &#8211; intersezione con via Galli<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>VIA PUGLIE\u00a0 &#8211; intersezione con via Galli<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>VIA ABRUZZO\u00a0 &#8211; intersezione con via Galli<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>VIA VENEZIA TRIDENTINA\u00a0 &#8211; intersezione con via Galli<\/li>\n<\/ul>\n<p>DIVIETO DI TRANSITO<\/p>\n<p>eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<p>In caso di condizioni meteorologiche avverse che non permettano l\u2019esecuzione dei lavori, il presente dispositivo si intende prorogato per le nuove date che la ditta esecutrice dei lavori concorder\u00e0 con il Comando di Polizia Locale.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_11605\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/12\/ord-villa-adriana.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2023\/12\/ord-villa-adriana.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ORD VILLA ADRIANA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il\u00a0ripristino del manto [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-11604","post","type-post","status-publish","format-standard","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il\u00a0ripristino del manto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-15T18:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana\",\"datePublished\":\"2023-12-15T18:29:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/\"},\"wordCount\":809,\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/\",\"name\":\"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-12-15T18:29:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/12\\\/15\\\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/","og_locale":"it_IT","og_type":"article","og_title":"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana - Tivoli","og_description":"Si avvisa la cittadinanza che da luned\u00ec 18 dicembre e per i giorni successivi Villa Adriana sar\u00e0 interessata da importanti modifiche alla viabilit\u00e0 per permettere ad Acea il\u00a0ripristino del manto [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-12-15T18:29:13+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana","datePublished":"2023-12-15T18:29:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/"},"wordCount":809,"articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/","name":"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-12-15T18:29:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/12\/15\/lavori-acea-rifacimento-manto-stradale-via-galli-e-via-di-villa-adriana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Lavori ACEA: rifacimento manto stradale via Galli e via di Villa Adriana"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11604"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11604\/revisions"}],"predecessor-version":[{"id":11606,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11604\/revisions\/11606"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}