{"id":11692,"date":"2024-01-08T13:12:13","date_gmt":"2024-01-08T12:12:13","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11692"},"modified":"2024-01-08T13:12:13","modified_gmt":"2024-01-08T12:12:13","slug":"via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/","title":{"rendered":"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15)"},"content":{"rendered":"<p>Per lavori Enel- distribuzione, si ordina la chiusura temporanea di via Galli, nel tratto compreso tra via Campania e via Rosolina, il\u00a0<strong>10 gennaio nella fascia oraria 9-15<\/strong>, secondo le seguenti modalit\u00e0:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>\n<p lang=\"it-IT\" xml:lang=\"it-IT\"><strong>VIA GALLI (tratto compreso tra via Campania e via Rosolina):<\/strong><\/p>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">DIVIETO DI TRANSITO A TUTTI I VEICOLI<\/p>\n<\/li>\n<\/ul>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<ul>\n<li>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">DIVIETO DI SOSTA CON RIMOZIONE FORZATA DEI VEICOLI INADEMPIENTI SU AMBO I LATI<\/p>\n<\/li>\n<\/ul>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">\n<ul>\n<li>\n<p lang=\"it-IT\" xml:lang=\"it-IT\"><strong>VIA GALLI (intersezione con via Puglie):<\/strong><\/p>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">OBBLIGO DI SVOLTA A DESTRA IN DIREZIONE VIA LEONINA<\/p>\n<\/li>\n<\/ul>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">\n<ul>\n<li>\n<p lang=\"it-IT\" xml:lang=\"it-IT\"><strong>VIA PUGLIE &#8211; (intersezione con via Galli):<\/strong><\/p>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">OBBLIGO DI SVOLTA A SINISTRA IN DIREZIONE LARGO FRANCESCHI<\/p>\n<\/li>\n<\/ul>\n<p lang=\"it-IT\" xml:lang=\"it-IT\">eccetto i mezzi d\u2019opera della ditta esecutrice dei lavori e i mezzi di soccorso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per lavori Enel- distribuzione, si ordina la chiusura temporanea di via Galli, nel tratto compreso tra via Campania e via Rosolina, il\u00a010 gennaio nella fascia oraria 9-15, secondo le seguenti [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-11692","post","type-post","status-publish","format-standard","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15) - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15) - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Per lavori Enel- distribuzione, si ordina la chiusura temporanea di via Galli, nel tratto compreso tra via Campania e via Rosolina, il\u00a010 gennaio nella fascia oraria 9-15, secondo le seguenti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T12:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\\\/1 (fascia oraria 9-15)\",\"datePublished\":\"2024-01-08T12:12:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/\"},\"wordCount\":156,\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/\",\"name\":\"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\\\/1 (fascia oraria 9-15) - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2024-01-08T12:12:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/01\\\/08\\\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\\\/1 (fascia oraria 9-15)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15) - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/","og_locale":"it_IT","og_type":"article","og_title":"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15) - Tivoli","og_description":"Per lavori Enel- distribuzione, si ordina la chiusura temporanea di via Galli, nel tratto compreso tra via Campania e via Rosolina, il\u00a010 gennaio nella fascia oraria 9-15, secondo le seguenti [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-01-08T12:12:13+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/mobilita.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15)","datePublished":"2024-01-08T12:12:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/"},"wordCount":156,"articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/","url":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/","name":"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15) - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2024-01-08T12:12:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/01\/08\/via-galli-tratto-compreso-tra-via-campania-e-via-rosolina-chiusa-al-transito-veicolare-il-10-1-fascia-oraria-9-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Via Galli, tratto compreso tra via Campania e via Rosolina, chiusa al transito veicolare il 10\/1 (fascia oraria 9-15)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11692"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11692\/revisions"}],"predecessor-version":[{"id":11693,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11692\/revisions\/11693"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}