{"id":1176,"date":"2017-11-14T17:37:29","date_gmt":"2017-11-14T16:37:29","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1176"},"modified":"2017-11-14T17:37:29","modified_gmt":"2017-11-14T16:37:29","slug":"dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/","title":{"rendered":"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Astral ha diffuso la propria ordinanza che disciplina la circolazione in caso di neve e che introduce, dal 15 novembre 2017 al 15 aprile 2018, l\u2019obbligo di utilizzare pneumatici invernali o di avere catene a bordo del veicolo in una serie di strade regionali del Lazio.<\/p>\n<p>Per quel che riguarda il territorio di Tivoli, l\u2019obbligo riguarda anche la Tiburtina Valeria, a partire dal chilometro 34,7.<\/p>\n<p>In allegato e al seguente link \u00e8 disponibile il testo dell\u2019ordinanza <a href=\"http:\/\/www.astralspa.it\/?p=16934\">http:\/\/www.astralspa.it\/?p=16934<\/a> .<\/p>\n<p>&nbsp;<\/p>\n<p>Tivoli, 14 novembre 2017<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1177\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/11\/3753-Ordinanza-n-1-del-10-11-2017.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/11\/3753-Ordinanza-n-1-del-10-11-2017.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>3753-Ordinanza-n-1-del-10-11-2017<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Astral ha diffuso la propria ordinanza che disciplina la circolazione in caso di neve e che introduce, dal 15 novembre 2017 al 15 aprile 2018, l\u2019obbligo di utilizzare pneumatici [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE - Tivoli\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Astral ha diffuso la propria ordinanza che disciplina la circolazione in caso di neve e che introduce, dal 15 novembre 2017 al 15 aprile 2018, l\u2019obbligo di utilizzare pneumatici [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-14T16:37:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"274\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE\",\"datePublished\":\"2017-11-14T16:37:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/\"},\"wordCount\":114,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/\",\"name\":\"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"datePublished\":\"2017-11-14T16:37:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"width\":274,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/11\\\/14\\\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/","og_locale":"it_IT","og_type":"article","og_title":"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE - Tivoli","og_description":"&nbsp; Astral ha diffuso la propria ordinanza che disciplina la circolazione in caso di neve e che introduce, dal 15 novembre 2017 al 15 aprile 2018, l\u2019obbligo di utilizzare pneumatici [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-11-14T16:37:29+00:00","og_image":[{"width":274,"height":385,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE","datePublished":"2017-11-14T16:37:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/"},"wordCount":114,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/","name":"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","datePublished":"2017-11-14T16:37:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","width":274,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/11\/14\/dal-15-novembre-obbligo-di-pneumatici-invernali-o-catene-a-bordo-lelenco-di-tutte-le-strade-regionali-interessate-e-lordinanza-completa-di-astral-che-disciplina-la-circolazione-in-c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"DAL 15 NOVEMBRE OBBLIGO DI PNEUMATICI INVERNALI O CATENE A BORDO: L\u2019ELENCO DI TUTTE LE STRADE REGIONALI INTERESSATE E L\u2019ORDINANZA COMPLETA DI ASTRAL CHE DISCIPLINA LA CIRCOLAZIONE IN CASO DI NEVE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1176"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1176\/revisions"}],"predecessor-version":[{"id":1178,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1176\/revisions\/1178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/617"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}